{"id":70254,"date":"2025-02-23T10:09:00","date_gmt":"2025-02-23T10:09:00","guid":{"rendered":"https:\/\/expforex.com\/averager\/"},"modified":"2026-06-30T13:31:44","modified_gmt":"2026-06-30T13:31:44","slug":"averager","status":"publish","type":"post","link":"https:\/\/expforex.com\/es\/averager\/","title":{"rendered":"Averager. Promediando posiciones de trading. \u00a1Apertura de operaciones contra la tendencia y en la tendencia!"},"content":{"rendered":"\n<p align=\"center\">\n  <div class=\"video-container-14 video-thumbnail\" onclick=\"loadVideo('video-container-14', 'lmi5Bck0Pro', 0)\">\n    <img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/hqdefault1-7.jpg\" alt=\"Averager. Promediando posiciones de trading. \u00a1Apertura de operaciones contra la tendencia y en la tendencia! Video Thumbnail\" class=\"video-image\">\n    <div class=\"play-button\"><\/div> \n  <\/div>\n<\/p>\n\n\n\n<div class=\"wp-block-essential-blocks-advanced-tabs alignwide  root-eb-advanced-tabs-b7hkfqw\"><div class=\"eb-parent-wrapper eb-parent-eb-advanced-tabs-b7hkfqw \"><div class=\"eb-advanced-tabs-b7hkfqw eb-advanced-tabs-wrapper horizontal\" data-min-height=\"true\"><div class=\"eb-tabs-nav\"><ul class=\"tabTitles\" data-tabs-ul-id=\"eb-advanced-tabs-b7hkfqw\"><li data-title-tab-id=\"1\" data-title-custom-id=\"main\" id=\"main\" class=\"active\"><i icon=\"fas fa-home\" class=\"fas fa-home tabIcon\"><\/i><h6 class=\"tab-title-text\">Inicio<\/h6><\/li><li data-title-tab-id=\"2\" data-title-custom-id=\"Documentation\" id=\"Documentation\" class=\"inactive\"><i icon=\"fas fa-graduation-cap\" class=\"fas fa-graduation-cap tabIcon\"><\/i><h6 class=\"tab-title-text\">Documentaci\u00f3n<\/h6><\/li><li data-title-tab-id=\"3\" data-title-custom-id=\"Settings\" id=\"Settings\" class=\"inactive\"><i icon=\"fas fa-cog\" class=\"fas fa-cog tabIcon\"><\/i><h6 class=\"tab-title-text\">Configuraci\u00f3n<\/h6><\/li><li data-title-tab-id=\"4\" data-title-custom-id=\"faq\" id=\"faq\" class=\"inactive\"><i icon=\"fas fa-question\" class=\"fas fa-question tabIcon\"><\/i><h6 class=\"tab-title-text\">FAQ<\/h6><\/li><li data-title-tab-id=\"5\" data-title-custom-id=\"changelog\" id=\"changelog\" class=\"inactive\"><i icon=\"fas fa-code\" class=\"fas fa-code tabIcon\"><\/i><h6 class=\"tab-title-text\">Registro<\/h6><\/li><li data-title-tab-id=\"6\" data-title-custom-id=\"reviews\" id=\"reviews\" class=\"inactive\"><i icon=\"far fa-star\" class=\"far fa-star tabIcon\"><\/i><h6 class=\"tab-title-text\">Rese\u00f1as\u00a0<\/h6><\/li><li data-title-tab-id=\"7\" data-title-custom-id=\"comments\" id=\"comments\" class=\"inactive\"><i icon=\"far fa-comments\" class=\"far fa-comments tabIcon\"><\/i><h6 class=\"tab-title-text\">Comentarios<\/h6><\/li><li data-title-tab-id=\"8\" data-title-custom-id=\"Extra\" id=\"Extra\" class=\"inactive\"><i icon=\"fas fa-bolt\" class=\"fas fa-bolt tabIcon\"><\/i><h6 class=\"tab-title-text\">Extra<\/h6><\/li><\/ul><\/div><div class=\"eb-tabs-contents\">\n<div class=\"eb-tab-wrapper\" data-tab-id=\"1\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-acerca-de-exp-averager\">Acerca de Exp Averager<\/h2>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\"><strong>Promediar Posiciones (Averaging Positions)<\/strong><\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\"><strong>\u00a1Apertura de posiciones adicionales en la tendencia y contra la tendencia, con una funci\u00f3n general de trailing profit stop!<\/strong><\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">\u00a1El <strong>Asesor Experto (Expert Advisor) Averager<\/strong> puede abrir posiciones adicionales <strong>en la direcci\u00f3n de la tendencia y contra ella<\/strong>!<\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">\u00a1Incluye un trailing stop promedio inteligente para una serie de posiciones!<\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">Ellos <strong>incrementan y disminuyen el lote (Volume)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">Una estrategia popular para promediar posiciones no rentables al precio promedio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Asesor Experto (Expert Advisor) Averager<\/strong> es una herramienta para promediar posiciones. Permite abrir posiciones adicionales en la direcci\u00f3n de la tendencia y contra ella, e incluye un trailing stop promedio inteligente para una serie de posiciones. Con esta herramienta, los traders pueden aumentar o disminuir el tama\u00f1o del lote (volumen) para cada posici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta herramienta es utilizada popularmente para promediar posiciones no rentables al precio promedio. Es una estrategia que implica abrir nuevas posiciones en la misma direcci\u00f3n que la posici\u00f3n original pero en diferentes niveles de precios. Al hacerlo, el trader puede acercar el precio promedio de la posici\u00f3n al precio actual del mercado, lo que puede ayudar a minimizar las p\u00e9rdidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Asesor Experto (Expert Advisor) Averager tambi\u00e9n incluye un trailing stop general para ganancias, lo que puede ayudar a los traders a asegurar beneficios a medida que el mercado se mueve a su favor. Esta caracter\u00edstica es especialmente \u00fatil para traders que les gusta seguir tendencias y capturar tantas ganancias como sea posible antes de salir del mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En general, el <strong>Asesor Experto (Expert Advisor) Averager<\/strong> es una herramienta poderosa que puede ayudar a los traders a gestionar sus posiciones de manera m\u00e1s efectiva y optimizar sus estrategias de trading.<\/p>\n\n\n\n<h3 class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-heading\" id=\"h-como-funciona-la-apertura-adicional-en-la-tendencia\">\u00a1C\u00f3mo Funciona la Apertura Adicional <strong>En la Tendencia<\/strong>!<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Supongamos<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Abres una posici\u00f3n <strong>BUY<\/strong> a un precio de <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">El precio sube a <strong>1.700<\/strong>, y la ganancia actual es de <strong>+100 puntos<\/strong>;<\/li>\n\n\n\n<li class=\"\">Punto de equilibrio (Precio Promedio) = <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">Si abres una posici\u00f3n BUY a un precio de <strong>1.700<\/strong>, entonces tu posici\u00f3n se promedia, y el punto de equilibrio puede establecerse en <strong>1.650<\/strong>;<\/li>\n\n\n\n<li class=\"\">El Asesor Experto (EA) abre 3 posiciones adicionales (operaciones).<\/li>\n\n\n\n<li class=\"\">Retroceso del precio (rollback).<\/li>\n\n\n\n<li class=\"\"><strong>El Asesor Experto (EA) activa el trailing stop, y 5 posiciones ganan beneficios para incrementarlo.<\/strong><\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img decoding=\"async\" width=\"500\" height=\"188\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2-500x188.png\" alt=\"Averager Principal: \u00a1C\u00f3mo funciona la apertura adicional en la tendencia!\" class=\"wp-image-5784\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2-500x188.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2-1200x452.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2-300x113.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2-768x289.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2-150x57.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2-700x264.png 700w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-55-12-2.png 1346w\" sizes=\"(max-width:767px) 500px, 500px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-heading\" id=\"h-como-funciona-el-promediado-contra-la-tendencia\">\u00a1C\u00f3mo Funciona el Promediado <strong>Contra la Tendencia<\/strong>!<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Supongamos<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Abres una posici\u00f3n <strong>BUY<\/strong> a un precio de <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">El precio baja a <strong>1.500<\/strong>, y la p\u00e9rdida actual es de <strong>-100 puntos<\/strong>;<\/li>\n\n\n\n<li class=\"\">Punto de equilibrio (Precio Promedio) = <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">Para modificar el Stop Loss al nivel de equilibrio, la tendencia necesita subir 100 puntos;<\/li>\n\n\n\n<li class=\"\">Si abres una posici\u00f3n BUY a un precio de <strong>1.500<\/strong>, entonces tu posici\u00f3n se promedia, y el punto de equilibrio puede establecerse en <strong>1.550<\/strong>;<\/li>\n\n\n\n<li class=\"\">Para cerrar dos operaciones, el precio debe moverse hacia arriba 50 puntos, no 100 puntos;<\/li>\n\n\n\n<li class=\"\"><strong>El Asesor Experto (EA) activa el trailing stop, y dos posiciones ganan beneficios para incrementarlo.<\/strong><\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img decoding=\"async\" width=\"500\" height=\"300\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-43-46-3-500x300.png\" alt=\"Averager Principal: \u00a1C\u00f3mo funciona el promediado contra la tendencia!\" class=\"wp-image-5785\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-43-46-3-500x300.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-43-46-3-300x180.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-43-46-3-125x75.png 125w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-43-46-3-700x420.png 700w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-04_10-43-46-3.png 761w\" sizes=\"(max-width:767px) 500px, 500px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-funciona-exp-averager\">\u00bfC\u00f3mo Funciona Exp Averager?<\/h2>\n\n\n\n<div class=\"wp-block-essential-blocks-slider  root-eb-slider-4i1s6\"><div class=\"eb-parent-wrapper eb-parent-eb-slider-4i1s6 eb_animation eb___animated eb___zoomIn\"><div class=\"eb-slider-wrapper eb-slider-4i1s6\" data-blockid=\"eb-slider-4i1s6\" data-version=\"v3\" data-settings=\"eyJhcnJvd3MiOnRydWUsImFkYXB0aXZlSGVpZ2h0Ijp0cnVlLCJhdXRvcGxheSI6dHJ1ZSwiYXV0b3BsYXlTcGVlZCI6NjAyNCwiZG90cyI6dHJ1ZSwiZmFkZSI6ZmFsc2UsImluZmluaXRlIjp0cnVlLCJwYXVzZU9uSG92ZXIiOnRydWUsInNsaWRlc1RvU2hvdyI6MSwic3BlZWQiOjc0MSwidmVydGljYWwiOmZhbHNlLCJjdXJyZW50U2xpZGUiOjAsInJ0bCI6ZmFsc2UsInJlc3BvbnNpdmUiOlt7ImJyZWFrcG9pbnQiOjEwMjUsInNldHRpbmdzIjp7InNsaWRlc1RvU2hvdyI6MX19LHsiYnJlYWtwb2ludCI6NzY3LCJzZXR0aW5ncyI6eyJzbGlkZXNUb1Nob3ciOjF9fV19\" data-arrownexticon=\"fas fa-chevron-right\" data-arrowprevicon=\"fas fa-chevron-left\" data-lightbox=\"false\"><div class=\"eb-slider-init eb-slider-type-content\"><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_00_3126.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_00_3126.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/exp-averager-screen-3005.gif\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/exp-averager-screen-3005.gif\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Ejemplos de promediado Averager \u00bfC\u00f3mo funciona?  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager Contra la tendencia  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager En la tendencia  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2023-12-24_14-16-14.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2023-12-24_14-16-14.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager Promediando m\u00e1s de 30 operaciones y obteniendo ganancias basadas en el take profit total.  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_01_1204.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_01_1204.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager Apertura adicional 1  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_01_3427.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_01_3427.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager Apertura adicional 2  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_02_3403.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_02_3403.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager Promediando contra la tendencia 1  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_02_4704.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_02_4704.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager Promediando contra la tendencia 2  <\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_03_1823.png\"><div><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_Averager_2024-Time-0_03_1823.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Averager en los Asesores Expertos<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-opinan-las-personas-sobre-exp-averager\">\u00bfQu\u00e9 opinan las personas sobre Exp Averager?<\/h2>\n\n\n<div class=\"testimonials_slider single-photo\"><ul class=\"testimonials_slider_ul\"><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>DNkRockzzzzZ \r\n\r\n<hr \/>\r\n\r\ngood tool<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">DNkRockzzzzZ<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Munir Sayed Yousef Ibrahim \r\n<hr \/>\r\n\r\nIts really Nice software but if You have some heavy indicator on the same chart this Program might Lag in Speed otherwise it will work Just fine its a great tool, Thank You<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Munir Sayed Yousef Ibrahim<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>skyparc \r\n\r\n<hr \/>\r\n\r\nThank you Vlad, for Update BreakEven WithoutLOSS options in meta 5 version, now is great, also I am using VirtualTradePad another briliant and perfect usefull tool<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">skyparc<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Alex \r\n\r\n<hr \/>\r\n\r\nSurvey should be done after one month or later not two days later. Anyway I bought before Close Minus by Plus (now is free) from the same author and is an EXCELLENT piece of work so I give the author 5 stars in advance because: 1) his work has quality, 2) his ideas superb 3) This is honest work and price 4) The graphic EAPAD is nice and usefull 5) Finally I will be able to automatize the strategy of averaging against the trend that I use much more easily with pluses as trailing or break even that are not possible to do manually the same way. Very good you can choose to close the cycle or renew it. Thanks Vladislav for sharing your talent!<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289\">Alex<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>jc-hakuna-matata \r\n\r\n<hr \/>\r\n\r\nexcellent tool<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289\">jc-hakuna-matata<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5C5D6107-541D_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5C5D6107-541D_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5C5D6107-541D_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5C5D6107-541D_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5C5D6107-541D_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5C5D6107-541D_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5C5D6107-541D_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Richard Laksana\r\n\r\n<hr \/>\r\n\r\nAmazing ea. Have tons of features and very customizeable. Recommended !!<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289\">Richard Laksana<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><img decoding=\"async\" class=\"scale-with-grid\" src=\"https:\/\/expforex.com\/wp-content\/themes\/betheme\/images\/testimonials-placeholder.png\" alt=\"Atila R Akdeniz\" \/><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Atila R Akdeniz \r\n\r\n<hr \/>\r\n\r\nAs always, extremely useful Utility and excellent support from Vladislav.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Atila R Akdeniz<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/08\/avatar_na2-2.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/08\/avatar_na2-2.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>bubay123 \r\n\r\n<hr \/>\r\n\r\nvery good and profitable.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289?source=Site+Profile+Seller#!tab=reviews\">bubay123<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>adrazz \r\nAwesome EA, just what I was looking for.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">adrazz <\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>very good and profitable.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289?source=Site+Profile+Seller#!tab=reviews\">bubay123 <\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Although this utility was released a few years ago, I only recently became interested in it. I bought it because, unfortunately, I can't trust the results of demo versions, which are often very questionable. This isn't the case with this utility. It's running on a demo account and has very interesting results. It's an honest program, with great capabilities, and the developer is very attentive and honest with buyers. I've read all the reviews and comments carefully, and the explanations were always quick, thorough, and clear. It's well worth the price. I recommend purchasing it. Excellent!<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289?source=Unknown#!tab=reviews\">RBC1234 <\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Jakote Molemi\r\n\r\n<hr \/>\r\n\r\nHello Vladislav, great program and very useful. There is a small hickup on the operation; please assist: Each time I update parameters (especially setting new levels for averaging), the program takes very very long time to test and update, how can I fix this trouble?\r\n\r\nI cannot attach a screenshot here you have disabled an option to reply to you and I do not know any other channel to reach you except here.\r\n<div class=\"user\">\r\n<div class=\"frame\">\r\n<div class=\"bg\"><img decoding=\"async\" title=\"Vladislav Andruschenko\" src=\"https:\/\/c.mql5.com\/avatar\/2022\/12\/63ac7246-191a.png\" srcset=\"https:\/\/c.mql5.com\/avatar\/2022\/12\/63ac7246-191a_big.png 2x\" alt=\"Vladislav Andruschenko\" width=\"60\" height=\"60\" \/><\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"review_reply__content\"><span class=\"review_reply__author\"><i class=\"icons-ux icons-ux_reply\"><\/i>Reply from developer\u00a0<strong><a class=\"author\" href=\"https:\/\/www.mql5.com\/en\/users\/vladon\">Vladislav <\/a><\/strong><\/span><span class=\"review_reply__date_link\"><span class=\"review_reply__date_created\" title=\"2021.06.08 17:36\">2021.06.08 17:36<\/span><\/span><\/div>\r\n<div class=\"review_reply__content\">\r\n<div id=\"reviewReplyContentBlock_184013\" class=\"review_reply__description\">Hello. Thank you. I didn't understand your mistake. are you talking about the eapadpro panel? it is updated every 10 seconds so as not to slow down the schedule. this does not affect the algorithm. please attach a screenshot or log files with the error to the discussion.<\/div>\r\n<\/div><\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Jakote Molemi<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Vitali Lebianok \r\n\r\n<hr \/>\r\n\r\n\u043e\u0447\u0435\u043d\u044c \u043f\u043e\u043b\u0435\u0437\u043d\u0430\u044f \u0438 \u0445\u043e\u0440\u043e\u0448\u0430\u044f \u0443\u0442\u0438\u043b\u0438\u0442\u0430 \u043f\u043e\u0437\u0432\u043e\u043b\u044f\u044e\u0449\u0430\u044f \u0437\u0430\u0434\u0430\u0442\u044c \u0441\u0432\u043e\u044e \u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u0443\u044e \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u044e \u0438 \u0431\u0435\u0437 \u043b\u0438\u0448\u043d\u0438\u0445 \u0445\u043b\u043e\u043f\u043e\u0442 \u043f\u043e\u043b\u0443\u0447\u0430\u0442\u044c \u043f\u0440\u0438\u0431\u044b\u043b\u044c \u043d\u043e \u0432\u043d\u0438\u043c\u0430\u0442\u0435\u043b\u044c\u043d\u043e \u043e\u0442\u043d\u0435\u0441\u0438\u0442\u0435\u0441\u044c \u043f\u0440\u0438 \u043d\u0430\u0441\u0442\u0440\u043e\u0439\u043a\u0435 \u043a \u043f\u0440\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u044e \u0442\u0435\u0441\u0442\u043e\u0432 , \u0430 \u0442\u0430\u043a \u0436\u0435 \u0441\u043e\u0432\u0435\u0442\u0443\u044e \u0434\u043b\u044f \u043a\u0430\u0436\u0434\u043e\u0439 \u0432\u0430\u043b\u044e\u0442\u043d\u043e\u0439 \u043f\u0430\u0440\u044b \u0432\u044b\u0440\u0430\u0431\u0430\u0442\u044b\u0432\u0430\u0442\u044c \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u044b\u0435 \u043d\u0430\u0441\u0442\u0440\u043e\u0439\u043a\u0438 .\u0422\u0410\u041a \u0416\u0415 \u0445\u043e\u0447\u0443 \u0437\u0430\u043c\u0435\u0442\u0438\u0442\u044c \u0447\u0442\u043e \u0430\u0432\u0442\u043e\u0440 \u043e\u0447\u0435\u043d\u044c \u0431\u044b\u0441\u0442\u0440\u043e \u0438 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u043f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u0440\u0430\u0437\u043e\u0431\u0440\u0430\u0442\u044c\u0441\u044f \u0441\u043e \u0432\u0441\u0435\u043c\u0438 \u0441\u043b\u043e\u0436\u043d\u043e\u0441\u0442\u044f\u043c\u0438 \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043c\u043e\u0433\u0443\u0442 \u0432\u043e\u0437\u043d\u0438\u043a\u043d\u0443\u0442\u044c \u043f\u0440\u0438 \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043d\u0438\u0438 \u0445\u043e\u0442\u0435\u043b\u043e\u0441\u044c \u0431\u044b \u043f\u043e\u0441\u0442\u0430\u0432\u0438\u0442\u044c \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u043e 5 \u0437\u0432\u0435\u0437\u0434 \u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0443 \u043d\u043e \u0438 \u0440\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0447\u0438\u043a\u0443 )<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Vitali Lebianok<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Sammy Boy \r\n\r\n<hr \/>\r\n\r\nExcellent work Vladislav! thank you<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Sammy Boy<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FAEDA68-7F06_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FAEDA68-7F06_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FAEDA68-7F06_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FAEDA68-7F06_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FAEDA68-7F06_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FAEDA68-7F06_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FAEDA68-7F06_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Mariusz Sedlak\r\n\r\n<hr \/>\r\n\r\nVery handy<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289\">Mariusz Sedlak<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><\/ul><div class=\"slider_pager slider_pagination\"><\/div><\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-puedes-descargar-exp-averager-gratis\">\u00a1Puedes descargar Exp Averager gratis!<\/h2>\n\n\n\n<div class=\"nfd-wb-animate nfd-wb-zoom-in nfd-delay-50 wp-block-essential-blocks-call-to-action  root-eb-call-to-action-d92ap\"><div class=\"eb-parent-wrapper eb-parent-eb-call-to-action-d92ap eb_animation eb___animated eb___zoomIn\"><div class=\"eb-cia-wrapper eb-call-to-action-d92ap\" data-icon=\"fas fa-gift\"><div class=\"eb-cia-text-wrapper\"><i class=\"fas fa-gift eb-cia-icon\" icon=\"fas fa-gift\"><\/i><h4 class=\"eb-cia-title\">\u00a1Comienza GRATIS!<\/h4><h4 class=\"eb-cia-subtitle\">\u00a1Puedes descargar e instalar nuestro programa gratis!<\/h4><p class=\"eb-cia-description\">\u00a1Puedes probar todas las funciones de forma completa en tu cuenta DEMO!<br>\u00a1Tambi\u00e9n puedes probar nuestro programa gratis en una cuenta REAL usando el s\u00edmbolo USDJPY!<\/p><\/div><div class=\"eb-cia-button-wrapper\"><a href=\"https:\/\/expforex.com\/es\/?p=4156\" target=\"_blank\" rel=\"noopener\"><div class=\"eb-cia-button is-extra-large hvr-pulse\">\u00a1Quiero probarlo GRATIS!<\/div><\/a><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-puedes-comprar-la-version-completa-de-exp-averager\">\u00a1Puedes comprar la versi\u00f3n completa de Exp Averager!<\/h2>\n\n\n\n<div class=\"wp-block-essential-blocks-pro-multicolumn-pricing-table  root-eb-multicolumn-pricing-table-je6a3\"><div class=\"eb-parent-wrapper eb-parent-eb-multicolumn-pricing-table-je6a3 \"><div class=\"eb-mcpt-wrap eb-multicolumn-pricing-table-je6a3 preset-1\" data-id=\"eb-multicolumn-pricing-table-je6a3\" data-collapse=\"false\" data-row-number=\"5\" data-icon-one=\"fas fa-angle-down\" data-icon-two=\"fas fa-angle-up\" data-text-one=\"See More\" data-text-two=\"See Less\" data-icon-postion=\"right\"><div class=\"eb-mcpt-content\"><div class=\"eb-mcpt-row\">\n<div class=\"eb-mcpt-column eb-mcpt-column-features\"><div class=\"eb-mcpt-feature-list eb-mcpt-feature-titles\">\n<div class=\"eb-mcpt-cell eb-mcpt-header\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_Averager-45.png\" alt=\"\" class=\"wp-image-4361\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_Averager-45.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_Averager-45-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_Averager-45-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-ko468\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-ko468 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-ko468 button-1\" data-id=\"eb-advance-heading-ko468\"><p class=\"eb-ah-title\">MetaTrader<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-6tcsx\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-6tcsx \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-6tcsx button-1\" data-id=\"eb-advance-heading-6tcsx\"><p class=\"eb-ah-title\">Tiempo de uso<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\">Cuentas de trading<\/p>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\">Computadoras \/ Activaciones<\/p>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-0qw38\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-0qw38 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-0qw38 button-1\" data-id=\"eb-advance-heading-0qw38\"><p class=\"eb-ah-title\">Funciones<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-au8ni\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-au8ni \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-au8ni button-1\" data-id=\"eb-advance-heading-au8ni\"><p class=\"eb-ah-title\">Soporte<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"eb-mcpt-column\"><div class=\"eb-mcpt-feature-list\">\n<div class=\"eb-mcpt-cell eb-mcpt-header\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-o5htx\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-o5htx \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-o5htx preset-3\" data-id=\"eb-advance-heading-o5htx\"><p class=\"eb-ah-title\"><strong>VERSI\u00d3N COMPLETA MT4<\/strong><\/p><p class=\"eb-ah-subtitle\"><br>Para MetaTrader 4<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-6mbg4\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-6mbg4 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-6mbg4 preset-3\" data-id=\"eb-advance-heading-6mbg4\"><p class=\"eb-ah-title\"><strong>50 $<\/strong><\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"root-eb-button-oq0x3 wp-block-essential-blocks-button  root-eb-button-a085i\"><div class=\"eb-parent-wrapper eb-parent-eb-button-a085i \"><div class=\"eb-button-wrapper eb-button-alignment eb-button-a085i\"><div class=\"eb-button\"><div class=\"eb-button-inner-wrapper \"><a class=\"eb-button-anchor hvr-icon-pulse \" href=\"https:\/\/www.mql5.com\/es\/accounting\/buy\/market\/1289?period=0\" target=\"_blank\" rel=\"noopener\"><i icon=\"fas fa-cart-plus\" class=\"fas fa-cart-plus eb-button-icon eb-button-icon-left hvr-icon\"><\/i>COMPRAR PARA MT4<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-xhqwz\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-xhqwz \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-xhqwz button-1\" data-id=\"eb-advance-heading-xhqwz\"><p class=\"eb-ah-title\">MT <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">4<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-95f2p\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-95f2p \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-95f2p button-1\" data-id=\"eb-advance-heading-95f2p\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">De por vida<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-6mw3h\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-6mw3h \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-6mw3h button-1\" data-id=\"eb-advance-heading-6mw3h\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Ilimitado<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-zksna\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-zksna \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-zksna button-1\" data-id=\"eb-advance-heading-zksna\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">10<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-n81sy\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-n81sy \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-n81sy button-1\" data-id=\"eb-advance-heading-n81sy\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Completo<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-fig35\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-fig35 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-fig35 button-1\" data-id=\"eb-advance-heading-fig35\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">24\/7<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"eb-mcpt-column\"><div class=\"eb-mcpt-feature-list\">\n<div class=\"eb-mcpt-cell eb-mcpt-header\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-60e3h\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-60e3h \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-60e3h preset-3\" data-id=\"eb-advance-heading-60e3h\"><p class=\"eb-ah-title\"><strong>VERSI\u00d3N COMPLETA MT5<\/strong><\/p><p class=\"eb-ah-subtitle\"><br>Para MetaTrader 5<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-rystd\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-rystd \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-rystd preset-3\" data-id=\"eb-advance-heading-rystd\"><p class=\"eb-ah-title\"><strong>50 $<\/strong><\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"root-eb-button-ovhfg wp-block-essential-blocks-button  root-eb-button-tf0lu\"><div class=\"eb-parent-wrapper eb-parent-eb-button-tf0lu \"><div class=\"eb-button-wrapper eb-button-alignment eb-button-tf0lu\"><div class=\"eb-button\"><div class=\"eb-button-inner-wrapper \"><a class=\"eb-button-anchor hvr-icon-pulse \" href=\"https:\/\/www.mql5.com\/es\/accounting\/buy\/market\/1112?period=0\" target=\"_blank\" rel=\"noopener\"><i icon=\"fas fa-cart-plus\" class=\"fas fa-cart-plus eb-button-icon eb-button-icon-left hvr-icon\"><\/i>COMPRAR PARA MT5<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-yalq1\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-yalq1 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-yalq1 button-1\" data-id=\"eb-advance-heading-yalq1\"><p class=\"eb-ah-title\">MT <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">5<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-bghuu\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-bghuu \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-bghuu button-1\" data-id=\"eb-advance-heading-bghuu\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">De por vida<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-xigye\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-xigye \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-xigye button-1\" data-id=\"eb-advance-heading-xigye\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Ilimitado<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-hlgvp\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-hlgvp \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-hlgvp button-1\" data-id=\"eb-advance-heading-hlgvp\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">10<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-t0w37\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-t0w37 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-t0w37 button-1\" data-id=\"eb-advance-heading-t0w37\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Completo<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-cdoou\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-cdoou \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-cdoou button-1\" data-id=\"eb-advance-heading-cdoou\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">24\/7<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"eb-mcpt-column\"><div class=\"eb-mcpt-feature-list\">\n<div class=\"eb-mcpt-cell eb-mcpt-header\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-sg8g8\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-sg8g8 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-sg8g8 preset-3\" data-id=\"eb-advance-heading-sg8g8\"><p class=\"eb-ah-title\"><strong>ALQUILER por 3 meses<\/strong><\/p><p class=\"eb-ah-subtitle\"><br>Para MetaTrader 4<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-1ugx3\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-1ugx3 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-1ugx3 preset-3\" data-id=\"eb-advance-heading-1ugx3\"><p class=\"eb-ah-title\"><strong>30 $<\/strong><\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"root-eb-button-b7w7z wp-block-essential-blocks-button  root-eb-button-atejp\"><div class=\"eb-parent-wrapper eb-parent-eb-button-atejp \"><div class=\"eb-button-wrapper eb-button-alignment eb-button-atejp\"><div class=\"eb-button\"><div class=\"eb-button-inner-wrapper \"><a class=\"eb-button-anchor hvr-icon-pulse \" href=\"https:\/\/www.mql5.com\/es\/accounting\/buy\/market\/1289?period=3\" target=\"_blank\" rel=\"noopener\"><i icon=\"far fa-calendar-check\" class=\"far fa-calendar-check eb-button-icon eb-button-icon-left hvr-icon\"><\/i>ALQUILER PARA MT4<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-gp7gu\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-gp7gu \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-gp7gu button-1\" data-id=\"eb-advance-heading-gp7gu\"><p class=\"eb-ah-title\">MT <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">4<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-768d2\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-768d2 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-768d2 button-1\" data-id=\"eb-advance-heading-768d2\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">3 meses<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-23zpj\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-23zpj \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-23zpj button-1\" data-id=\"eb-advance-heading-23zpj\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Ilimitado<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-t45f3\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-t45f3 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-t45f3 button-1\" data-id=\"eb-advance-heading-t45f3\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">10<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-qyq2s\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-qyq2s \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-qyq2s button-1\" data-id=\"eb-advance-heading-qyq2s\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Completo<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-ge2ch\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-ge2ch \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-ge2ch button-1\" data-id=\"eb-advance-heading-ge2ch\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">24\/7<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"eb-mcpt-column\"><div class=\"eb-mcpt-feature-list\">\n<div class=\"eb-mcpt-cell eb-mcpt-header\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-3ny6f\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-3ny6f \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-3ny6f preset-3\" data-id=\"eb-advance-heading-3ny6f\"><p class=\"eb-ah-title\">ALQUILER por 3 meses<\/p><p class=\"eb-ah-subtitle\"><br>Para MetaTrader 5<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-4m8z2\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-4m8z2 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-4m8z2 preset-3\" data-id=\"eb-advance-heading-4m8z2\"><p class=\"eb-ah-title\"><strong>30 $<\/strong><\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"root-eb-button-mivfw wp-block-essential-blocks-button  root-eb-button-v0ot2\"><div class=\"eb-parent-wrapper eb-parent-eb-button-v0ot2 \"><div class=\"eb-button-wrapper eb-button-alignment eb-button-v0ot2\"><div class=\"eb-button\"><div class=\"eb-button-inner-wrapper \"><a class=\"eb-button-anchor hvr-icon-pulse \" href=\"https:\/\/www.mql5.com\/es\/accounting\/buy\/market\/1112?period=3\" target=\"_blank\" rel=\"noopener\"><i icon=\"far fa-calendar-check\" class=\"far fa-calendar-check eb-button-icon eb-button-icon-left hvr-icon\"><\/i>ALQUILER PARA MT5<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-aic3y\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-aic3y \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-aic3y button-1\" data-id=\"eb-advance-heading-aic3y\"><p class=\"eb-ah-title\">MT <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">5<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-rfdjq\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-rfdjq \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-rfdjq button-1\" data-id=\"eb-advance-heading-rfdjq\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">3 meses<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-k46ny\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-k46ny \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-k46ny button-1\" data-id=\"eb-advance-heading-k46ny\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Ilimitado<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-pki7i\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-pki7i \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-pki7i button-1\" data-id=\"eb-advance-heading-pki7i\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">10<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-1utpx\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-1utpx \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-1utpx button-1\" data-id=\"eb-advance-heading-1utpx\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Completo<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-o2yu3\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-o2yu3 \"><div class=\"eb-advance-heading-wrapper eb-advance-heading-o2yu3 button-1\" data-id=\"eb-advance-heading-o2yu3\"><p class=\"eb-ah-title\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">24\/7<\/mark><\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"eb-mcpt-cell\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Antes de realizar una compra, te recomendamos encarecidamente que revises nuestras <strong><a href=\"https:\/\/expforex.com\/es\/metatrader-market-how-to-buy-an-advisor-on-mql5-com-how-to-rent-how-to-update-how-to-install\/\" target=\"_blank\" rel=\"noreferrer noopener\">instrucciones<\/a><\/strong> y la <strong><a href=\"https:\/\/expforex.com\/es\/faq\/#questions-about-purchasing-trading-advisors-and-licenses\" target=\"_blank\" rel=\"noreferrer noopener\">secci\u00f3n de Preguntas Frecuentes (FAQ)<\/a><\/strong> para asegurar una experiencia fluida.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-links\">Links<\/h2>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"2\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\"><div class=\"root-eb-toc-n8usydf wp-block-essential-blocks-table-of-contents\"><div class=\"eb-parent-wrapper eb-parent-eb-toc-n8usydf \"><div class=\"eb-toc-container eb-toc-n8usydf  eb-toc-is-not-sticky eb-toc-collapsible eb-toc-initially-collapsed eb-toc-scrollToTop style-1 list-style-none\" data-scroll-top=\"false\" data-scroll-top-icon=\"fas fa-angle-up\" data-collapsible=\"true\" data-sticky-hide-mobile=\"false\" data-sticky=\"false\" data-scroll-target=\"scroll_to_toc\" data-copy-link=\"true\" data-editor-type=\"\" data-hide-desktop=\"false\" data-hide-tab=\"false\" data-hide-mobile=\"false\" data-itemcollapsed=\"false\" data-highlight-scroll=\"false\"><div class=\"eb-toc-header\"><h2 class=\"eb-toc-title\">\u00cdndice de contenidos (haga clic para mostrar)<\/h2><\/div><div class=\"eb-toc-wrapper hide-content\" data-headers=\"[{&quot;level&quot;:2,&quot;content&quot;:&quot;Acerca de Exp Averager&quot;,&quot;text&quot;:&quot;Acerca de Exp Averager&quot;,&quot;link&quot;:&quot;acerca-de-exp-averager&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-1&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-2&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-3&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-4&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-5&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;text&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;link&quot;:&quot;eb-table-content-6&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-7&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;link&quot;:&quot;eb-table-content-8&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Links&quot;,&quot;text&quot;:&quot;Links&quot;,&quot;link&quot;:&quot;links&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Descripci\\u00f3n&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n&quot;,&quot;link&quot;:&quot;eb-table-content-10&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-11&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-12&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-gif&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-imagen&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;text&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;link&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;link&quot;:&quot;eb-table-content-16&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;text&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;link&quot;:&quot;eb-table-content-17&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;text&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;link&quot;:&quot;eb-table-content-18&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;text&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;link&quot;:&quot;eb-table-content-19&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;text&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;link&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;text&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;link&quot;:&quot;eb-table-content-21&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;text&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;link&quot;:&quot;eb-table-content-22&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;text&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;link&quot;:&quot;eb-table-content-23&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;link&quot;:&quot;eb-table-content-24&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;link&quot;:&quot;eb-table-content-25&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;text&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;link&quot;:&quot;eb-table-content-26&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;text&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;link&quot;:&quot;variables-externas-y-configuraciones&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Generales&quot;,&quot;text&quot;:&quot;Configuraciones Generales&quot;,&quot;link&quot;:&quot;configuraciones-generales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Promediado&quot;,&quot;text&quot;:&quot;Configuraciones de Promediado&quot;,&quot;link&quot;:&quot;configuraciones-de-promediado&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Adicionales&quot;,&quot;text&quot;:&quot;Configuraciones Adicionales&quot;,&quot;link&quot;:&quot;configuraciones-adicionales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Filtro&quot;,&quot;text&quot;:&quot;Configuraciones de Filtro&quot;,&quot;link&quot;:&quot;configuraciones-de-filtro&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;text&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;link&quot;:&quot;configuraciones-de-trailing-stop&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;text&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;link&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Registro Exp Averager&quot;,&quot;text&quot;:&quot;Registro Exp Averager&quot;,&quot;link&quot;:&quot;registro-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;text&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;link&quot;:&quot;eb-table-content-35&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;text&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;link&quot;:&quot;comentarios-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Extra&quot;,&quot;text&quot;:&quot;Extra&quot;,&quot;link&quot;:&quot;extra&quot;}]\" data-visible=\"[true,true,true,true,true,false]\" data-delete-headers=\"[{&quot;label&quot;:&quot;Acerca de Exp Averager&quot;,&quot;value&quot;:&quot;acerca-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-la-apertura-adicional-en-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-el-promediado-contra-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfqu\\u00e9-opinan-las-personas-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-exp-averager-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;value&quot;:&quot;\\u00a1comienza-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-e-instalar-nuestro-programa-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-comprar-la-versi\\u00f3n-completa-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Links&quot;,&quot;value&quot;:&quot;links&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Descripci\\u00f3n&quot;,&quot;value&quot;:&quot;descripci\\u00f3n&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-apertura-adicional-con-la-tendencia&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-promediaci\\u00f3n-contra-la-tendencia&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-gif&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-imagen&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;value&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;value&quot;:&quot;descripci\\u00f3n-breve-del-principio-de-funcionamiento-y-par\\u00e1metros&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;value&quot;:&quot;c\\u00f3mo-instalar-exp-promediador&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;value&quot;:&quot;la-informaci\\u00f3n-mostrada-en-el-panel-de-eapadpro&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;value&quot;:&quot;recomendaciones-para-calcular-la-distancia-de-promediaci\\u00f3n-distance-y-el-stoploss&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;value&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;value&quot;:&quot;par\\u00e1metro-averageuse&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;value&quot;:&quot;par\\u00e1metro-takeprofitall&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distance&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distancemartin&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-lotsmartin&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;value&quot;:&quot;par\\u00e1metro-maxordersopen&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;value&quot;:&quot;variables-externas-y-configuraciones&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones Generales&quot;,&quot;value&quot;:&quot;configuraciones-generales&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones de Promediado&quot;,&quot;value&quot;:&quot;configuraciones-de-promediado&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones Adicionales&quot;,&quot;value&quot;:&quot;configuraciones-adicionales&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones de Filtro&quot;,&quot;value&quot;:&quot;configuraciones-de-filtro&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;value&quot;:&quot;configuraciones-de-trailing-stop&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;value&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Registro Exp Averager&quot;,&quot;value&quot;:&quot;registro-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;value&quot;:&quot;rese\\u00f1as-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;value&quot;:&quot;comentarios-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Extra&quot;,&quot;value&quot;:&quot;extra&quot;,&quot;isDelete&quot;:true}]\" data-smooth=\"true\" data-top-offset=\"500\"><div class=\"eb-toc__list-wrap\"><ul class=\"eb-toc__list\"><li><a href=\"#eb-table-content-10\">Descripci\u00f3n<\/a><li><a href=\"#eb-table-content-11\">\u00bfC\u00f3mo Funciona la Apertura Adicional con la Tendencia?<\/a><li><a href=\"#eb-table-content-12\">\u00bfC\u00f3mo Funciona la Promediaci\u00f3n Contra la Tendencia?<\/a><ul class=\"eb-toc__list\"><li><a href=\"#promediador-ejemplo-en-gif\">Promediador: Ejemplo en GIF<\/a><li><a href=\"#promediador-ejemplo-en-imagen\">Promediador: Ejemplo en Imagen<\/a><li><a href=\"#ejemplo-de-trabajo-usando-takeprofit\">Ejemplo de Trabajo Usando TakeProfit<\/a><li><a href=\"#eb-table-content-16\">Descripci\u00f3n Breve del Principio de Funcionamiento y Par\u00e1metros<\/a><\/li><\/ul><li><a href=\"#eb-table-content-17\">C\u00f3mo Instalar Exp-Promediador<\/a><li><a href=\"#eb-table-content-18\">La Informaci\u00f3n Mostrada en el Panel de EAPADPRO<\/a><li><a href=\"#eb-table-content-19\">Recomendaciones para Calcular la Distancia de Promediaci\u00f3n (Distance) y el StopLoss<\/a><li><a href=\"#recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador\">Recomendaciones para Probar y Optimizar las Opciones del Promediador<\/a><ul class=\"eb-toc__list\"><li><a href=\"#eb-table-content-21\">Par\u00e1metro AverageUSE<\/a><li><a href=\"#eb-table-content-22\">Par\u00e1metro TakeProfitALL<\/a><li><a href=\"#eb-table-content-23\">Par\u00e1metro Distance<\/a><li><a href=\"#eb-table-content-24\">Par\u00e1metro DistanceMartin<\/a><li><a href=\"#eb-table-content-25\">Par\u00e1metro LotsMartin<\/a><li><a href=\"#eb-table-content-26\">Par\u00e1metro MaxOrdersOpen<\/a><\/li><\/ul><\/ul><\/div><\/div><\/div><\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"root-eb-toc-f2xgj wp-block-essential-blocks-table-of-contents\"><div class=\"eb-parent-wrapper eb-parent-eb-toc-f2xgj \"><div class=\"eb-toc-container eb-toc-f2xgj eb-toc-sticky-right eb-toc-is-sticky eb-toc-collapsible eb-toc-initially-collapsed eb-toc-scrollToTop style-1 \" data-scroll-top=\"false\" data-scroll-top-icon=\"fas fa-angle-up\" data-collapsible=\"true\" data-sticky-hide-mobile=\"true\" data-sticky=\"true\" data-scroll-target=\"scroll_to_toc\" data-copy-link=\"true\" data-editor-type=\"\" data-hide-desktop=\"false\" data-hide-tab=\"false\" data-hide-mobile=\"false\" data-itemcollapsed=\"true\" data-highlight-scroll=\"false\"><div class=\"eb-toc-header\"><span class=\"eb-toc-close eb-toc-sticky-right\"><\/span><h2 class=\"eb-toc-title\">List<\/h2><\/div><div class=\"eb-toc-wrapper \" data-headers=\"[{&quot;level&quot;:2,&quot;content&quot;:&quot;Acerca de Exp Averager&quot;,&quot;text&quot;:&quot;Acerca de Exp Averager&quot;,&quot;link&quot;:&quot;acerca-de-exp-averager&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-1&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-2&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-3&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-4&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-5&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;text&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;link&quot;:&quot;eb-table-content-6&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-7&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;link&quot;:&quot;eb-table-content-8&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Links&quot;,&quot;text&quot;:&quot;Links&quot;,&quot;link&quot;:&quot;links&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Descripci\\u00f3n&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n&quot;,&quot;link&quot;:&quot;eb-table-content-10&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-11&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-12&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-gif&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-imagen&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;text&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;link&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;link&quot;:&quot;eb-table-content-16&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;text&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;link&quot;:&quot;eb-table-content-17&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;text&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;link&quot;:&quot;eb-table-content-18&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;text&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;link&quot;:&quot;eb-table-content-19&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;text&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;link&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;text&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;link&quot;:&quot;eb-table-content-21&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;text&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;link&quot;:&quot;eb-table-content-22&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;text&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;link&quot;:&quot;eb-table-content-23&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;link&quot;:&quot;eb-table-content-24&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;link&quot;:&quot;eb-table-content-25&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;text&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;link&quot;:&quot;eb-table-content-26&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;text&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;link&quot;:&quot;variables-externas-y-configuraciones&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Generales&quot;,&quot;text&quot;:&quot;Configuraciones Generales&quot;,&quot;link&quot;:&quot;configuraciones-generales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Promediado&quot;,&quot;text&quot;:&quot;Configuraciones de Promediado&quot;,&quot;link&quot;:&quot;configuraciones-de-promediado&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Adicionales&quot;,&quot;text&quot;:&quot;Configuraciones Adicionales&quot;,&quot;link&quot;:&quot;configuraciones-adicionales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Filtro&quot;,&quot;text&quot;:&quot;Configuraciones de Filtro&quot;,&quot;link&quot;:&quot;configuraciones-de-filtro&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;text&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;link&quot;:&quot;configuraciones-de-trailing-stop&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;text&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;link&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Registro Exp Averager&quot;,&quot;text&quot;:&quot;Registro Exp Averager&quot;,&quot;link&quot;:&quot;registro-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;text&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;link&quot;:&quot;eb-table-content-35&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;text&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;link&quot;:&quot;comentarios-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Extra&quot;,&quot;text&quot;:&quot;Extra&quot;,&quot;link&quot;:&quot;extra&quot;}]\" data-visible=\"[true,true,true,true,false,false]\" data-delete-headers=\"[{&quot;label&quot;:&quot;Acerca de Exp Averager&quot;,&quot;value&quot;:&quot;acerca-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-la-apertura-adicional-en-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-el-promediado-contra-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfqu\\u00e9-opinan-las-personas-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-exp-averager-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;value&quot;:&quot;\\u00a1comienza-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-e-instalar-nuestro-programa-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-comprar-la-versi\\u00f3n-completa-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Links&quot;,&quot;value&quot;:&quot;links&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Descripci\\u00f3n&quot;,&quot;value&quot;:&quot;descripci\\u00f3n&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-apertura-adicional-con-la-tendencia&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-promediaci\\u00f3n-contra-la-tendencia&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-gif&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-imagen&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;value&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;value&quot;:&quot;descripci\\u00f3n-breve-del-principio-de-funcionamiento-y-par\\u00e1metros&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;value&quot;:&quot;c\\u00f3mo-instalar-exp-promediador&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;value&quot;:&quot;la-informaci\\u00f3n-mostrada-en-el-panel-de-eapadpro&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;value&quot;:&quot;recomendaciones-para-calcular-la-distancia-de-promediaci\\u00f3n-distance-y-el-stoploss&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;value&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;value&quot;:&quot;par\\u00e1metro-averageuse&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;value&quot;:&quot;par\\u00e1metro-takeprofitall&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distance&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distancemartin&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-lotsmartin&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;value&quot;:&quot;par\\u00e1metro-maxordersopen&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;value&quot;:&quot;variables-externas-y-configuraciones&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones Generales&quot;,&quot;value&quot;:&quot;configuraciones-generales&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones de Promediado&quot;,&quot;value&quot;:&quot;configuraciones-de-promediado&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones Adicionales&quot;,&quot;value&quot;:&quot;configuraciones-adicionales&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones de Filtro&quot;,&quot;value&quot;:&quot;configuraciones-de-filtro&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;value&quot;:&quot;configuraciones-de-trailing-stop&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;value&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Registro Exp Averager&quot;,&quot;value&quot;:&quot;registro-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;value&quot;:&quot;rese\\u00f1as-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;value&quot;:&quot;comentarios-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Extra&quot;,&quot;value&quot;:&quot;extra&quot;,&quot;isDelete&quot;:true}]\" data-smooth=\"true\" data-top-offset=\"150\"><div class=\"eb-toc__list-wrap\"><ul class=\"eb-toc__list\"><li><a href=\"#eb-table-content-10\">Descripci\u00f3n<\/a><li><a href=\"#eb-table-content-11\">\u00bfC\u00f3mo Funciona la Apertura Adicional con la Tendencia?<\/a><li><a href=\"#eb-table-content-12\">\u00bfC\u00f3mo Funciona la Promediaci\u00f3n Contra la Tendencia?<\/a><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\">\n                    <path d=\"M6.75 9.75L9 7.5L11.25 9.75\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <path d=\"M9 15.75C9.88642 15.75 10.7642 15.5754 11.5831 15.2362C12.4021 14.897 13.1462 14.3998 13.773 13.773C14.3998 13.1462 14.897 12.4021 15.2362 11.5831C15.5754 10.7642 15.75 9.88642 15.75 9C15.75 8.11358 15.5754 7.23583 15.2362 6.41689C14.897 5.59794 14.3998 4.85383 13.773 4.22703C13.1462 3.60023 12.4021 3.10303 11.5831 2.76381C10.7642 2.42459 9.88642 2.25 9 2.25C7.20979 2.25 5.4929 2.96116 4.22703 4.22703C2.96116 5.4929 2.25 7.20979 2.25 9C2.25 10.7902 2.96116 12.5071 4.22703 13.773C5.4929 15.0388 7.20979 15.75 9 15.75Z\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <\/svg><ul class=\"eb-toc__list\"><li><a href=\"#promediador-ejemplo-en-gif\">Promediador: Ejemplo en GIF<\/a><li><a href=\"#promediador-ejemplo-en-imagen\">Promediador: Ejemplo en Imagen<\/a><li><a href=\"#ejemplo-de-trabajo-usando-takeprofit\">Ejemplo de Trabajo Usando TakeProfit<\/a><li><a href=\"#eb-table-content-16\">Descripci\u00f3n Breve del Principio de Funcionamiento y Par\u00e1metros<\/a><\/li><\/ul><li><a href=\"#eb-table-content-17\">C\u00f3mo Instalar Exp-Promediador<\/a><li><a href=\"#eb-table-content-18\">La Informaci\u00f3n Mostrada en el Panel de EAPADPRO<\/a><li><a href=\"#eb-table-content-19\">Recomendaciones para Calcular la Distancia de Promediaci\u00f3n (Distance) y el StopLoss<\/a><li><a href=\"#recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador\">Recomendaciones para Probar y Optimizar las Opciones del Promediador<\/a><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\">\n                    <path d=\"M6.75 9.75L9 7.5L11.25 9.75\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <path d=\"M9 15.75C9.88642 15.75 10.7642 15.5754 11.5831 15.2362C12.4021 14.897 13.1462 14.3998 13.773 13.773C14.3998 13.1462 14.897 12.4021 15.2362 11.5831C15.5754 10.7642 15.75 9.88642 15.75 9C15.75 8.11358 15.5754 7.23583 15.2362 6.41689C14.897 5.59794 14.3998 4.85383 13.773 4.22703C13.1462 3.60023 12.4021 3.10303 11.5831 2.76381C10.7642 2.42459 9.88642 2.25 9 2.25C7.20979 2.25 5.4929 2.96116 4.22703 4.22703C2.96116 5.4929 2.25 7.20979 2.25 9C2.25 10.7902 2.96116 12.5071 4.22703 13.773C5.4929 15.0388 7.20979 15.75 9 15.75Z\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <\/svg><ul class=\"eb-toc__list\"><li><a href=\"#eb-table-content-21\">Par\u00e1metro AverageUSE<\/a><li><a href=\"#eb-table-content-22\">Par\u00e1metro TakeProfitALL<\/a><li><a href=\"#eb-table-content-23\">Par\u00e1metro Distance<\/a><li><a href=\"#eb-table-content-24\">Par\u00e1metro DistanceMartin<\/a><li><a href=\"#eb-table-content-25\">Par\u00e1metro LotsMartin<\/a><li><a href=\"#eb-table-content-26\">Par\u00e1metro MaxOrdersOpen<\/a><\/li><\/ul><\/ul><\/div><\/div><button class=\"eb-toc-button  eb-toc-button-right\"><div>List<\/div><\/button><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-heading\" id=\"h-descripcion\">Descripci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">La <strong>estrategia de promediaci\u00f3n (averaging strategy)<\/strong> es un enfoque bien conocido en el comercio de Forex. Cuando abres una posici\u00f3n, la direcci\u00f3n futura de la moneda es incierta, incluso si est\u00e1s utilizando indicadores o an\u00e1lisis t\u00e9cnico. A veces el precio se mueve a tu favor, aumentando las ganancias, pero tambi\u00e9n hay situaciones en las que el precio se mueve en contra de tu posici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese punto, tienes varias opciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Esperar a que el precio regrese al punto de <strong>equilibrio (break-even)<\/strong>.<\/li>\n\n\n\n<li class=\"\">Cerrar la posici\u00f3n con <strong>p\u00e9rdidas m\u00ednimas<\/strong>.<\/li>\n\n\n\n<li class=\"\">Aplicar la <strong>estrategia de promediaci\u00f3n (averaging strategy)<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\"><strong>Prome<\/strong> implica abrir posiciones adicionales <strong>contra la tendencia<\/strong> a medida que el precio se aleja de tu posici\u00f3n inicial, con el objetivo de reducir el precio de entrada general.<\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">Por otro lado, <strong>apertura adicional (additional opening)<\/strong> se refiere a abrir m\u00e1s posiciones <strong>con la tendencia<\/strong>, aprovechando los movimientos favorables del mercado para maximizar las ganancias potenciales.<\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\"><br><strong>Prome<\/strong> es la apertura de posiciones <strong><span style=\"text-decoration: underline;\">contra la tendencia<\/span><\/strong>.<br><strong>Apertura adicional (additional opening)<\/strong> es la apertura de posiciones <strong><span style=\"text-decoration: underline;\">con la tendencia<\/span><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\">Esto tambi\u00e9n es muy \u00fatil.<br>Nuestro <strong>Asesor Experto (Expert Advisor, EA)<\/strong> te ayudar\u00e1 con esto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<blockquote class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La estrategia de promediaci\u00f3n de posiciones implica abrir una posici\u00f3n adicional contra tu posici\u00f3n principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, <strong>promediamos el punto de equilibrio (Average Price) de dos posiciones<\/strong> (Deals).<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\"><br><\/p>\n\n\n\n<h2 class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-heading\" id=\"h-como-funciona-la-apertura-adicional-con-la-tendencia\">\u00bfC\u00f3mo Funciona la Apertura Adicional con la Tendencia?<\/h2>\n\n\n\n<p align=\"center\">\n  <div class=\"video-container-16 video-thumbnail\" onclick=\"loadVideo('video-container-16', 'lmi5Bck0Pro', 37)\">\n    <img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/hqdefault1-7.jpg\" alt=\"\u00bfC\u00f3mo Funciona la Apertura Adicional con la Tendencia? Miniatura de Video\" class=\"video-image\">\n    <div class=\"play-button\"><\/div>\n  <\/div>\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Supongamos<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Abres una posici\u00f3n <strong>BUY<\/strong> a un precio de <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">El precio sube a <strong>1.700<\/strong>, y la ganancia actual es de <strong>+100 puntos<\/strong>;<\/li>\n\n\n\n<li class=\"\">Punto de equilibrio (Average Price) = <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">Si abrimos otra posici\u00f3n <strong>BUY<\/strong> al precio de <strong>1.700<\/strong>, entonces nuestra posici\u00f3n se promedia, y el punto de equilibrio puede establecerse en <strong>1.650<\/strong>;<\/li>\n\n\n\n<li class=\"\">El <strong>Asesor Experto (EA)<\/strong> abre 3 posiciones adicionales (deals).<\/li>\n\n\n\n<li class=\"\">El precio <strong>se revierte<\/strong>.<\/li>\n\n\n\n<li class=\"\"><strong>El Asesor Experto (EA) activa el Trailing Stop, y 5 posiciones ganan ganancias para aumentarlo.<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"582\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-1200x582.png\" alt=\"Promediador: \u00bfC\u00f3mo Funciona la Apertura Adicional con la Tendencia?\" class=\"wp-image-5782\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-1200x582.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-500x243.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-300x146.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-768x372.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-1536x745.png 1536w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-150x73.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12-700x340.png 700w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-55-12.png 1668w\" sizes=\"(max-width:767px) 700px, (max-width:1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Con la Tendencia<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-funciona-la-promediacion-contra-la-tendencia\">\u00bfC\u00f3mo Funciona la Promediaci\u00f3n Contra la Tendencia?<\/h2>\n\n\n\n<p align=\"center\">\n  <div class=\"video-container-17 video-thumbnail\" onclick=\"loadVideo('video-container-17', 'lmi5Bck0Pro', 97)\">\n    <img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/hqdefault1-7.jpg\" alt=\"\u00bfC\u00f3mo Funciona la Promediaci\u00f3n Contra la Tendencia? Miniatura de Video\" class=\"video-image\">\n    <div class=\"play-button\"><\/div>\n  <\/div>\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Supongamos<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Abres una posici\u00f3n <strong>BUY<\/strong> a un precio de <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">El precio baja a <strong>1.500<\/strong>, y la p\u00e9rdida actual es de <strong>-100 puntos<\/strong>;<\/li>\n\n\n\n<li class=\"\">Punto de equilibrio (Average Price) = <strong>1.600<\/strong>;<\/li>\n\n\n\n<li class=\"\">Para modificar el Stop Loss al nivel de equilibrio, necesitamos subir 100 puntos en tendencia al alza;<\/li>\n\n\n\n<li class=\"\">Si abrimos otra posici\u00f3n <strong>BUY<\/strong> al precio de <strong>1.500<\/strong>, entonces nuestra posici\u00f3n se promedia, y el punto de equilibrio puede establecerse en <strong>1.550<\/strong>;<\/li>\n\n\n\n<li class=\"\">Para cerrar dos operaciones, el precio debe moverse 50 puntos hacia arriba, no 100 puntos.<\/li>\n\n\n\n<li class=\"\"><strong>El Asesor Experto (EA) activa el Trailing Stop, y dos posiciones ganan ganancias para aumentarlo.<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>desventaja<\/strong> de este m\u00e9todo, por supuesto, es que abres un lote adicional, lo que carga el dep\u00f3sito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>ventajas<\/strong> de este m\u00e9todo son incuestionables: obtienes la oportunidad de cerrar antes del nivel que estableciste, pero con una ganancia y no con una p\u00e9rdida.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1571\" height=\"923\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2.png\" alt=\"Promediador: \u00bfC\u00f3mo Funciona la Promediaci\u00f3n Contra la Tendencia?\" class=\"wp-image-5783\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2.png 1571w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2-500x294.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2-1200x705.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2-300x176.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2-768x451.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2-1536x902.png 1536w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2-128x75.png 128w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-04_10-43-46-2-700x411.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1571px) 100vw, 1571px\" \/><figcaption class=\"wp-element-caption\">Contra la Tendencia<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-promediador-ejemplo-en-gif\">Promediador: Ejemplo en GIF<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/741565741.gif\" alt=\"Promediador: Ejemplo en GIF\" class=\"wp-image-70142\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-promediador-ejemplo-en-imagen\">Promediador: Ejemplo en Imagen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Abrimos una operaci\u00f3n <strong>BUY<\/strong>, y nuestro <strong>EA Promediador<\/strong> abre la siguiente posici\u00f3n <strong>BUY<\/strong>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1319\" height=\"699\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1.png\" alt=\"Promediador: Ejemplo en Imagen: Abrimos una Operaci\u00f3n BUY, y Nuestro EA Promediador Abre la Siguiente BUY\" class=\"wp-image-70130\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1.png 1319w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1-500x265.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1-1200x636.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1-300x159.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1-768x407.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1-142x75.png 142w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-1-700x371.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1319px) 100vw, 1319px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><br>El <strong>Asesor Experto (EA)<\/strong> luego <strong>activa<\/strong> la funci\u00f3n de <strong>Trailing Stop promedio<\/strong> y establece el Stop-Loss total de las operaciones a un precio promedio.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1317\" height=\"829\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2.png\" alt=\"Promediador: El Asesor Experto (EA) Activa la Funci\u00f3n de Trailing Stop Promedio y Establece el Stop-Loss Total a un Precio Promedio.\" class=\"wp-image-70154\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2.png 1317w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2-500x315.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2-1200x755.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2-300x189.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2-768x483.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2-119x75.png 119w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-2-700x441.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1317px) 100vw, 1317px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><br>Como resultado, todas las posiciones en la direcci\u00f3n <strong>BUY<\/strong> se cierran a un precio con una <strong>ganancia total<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"555\" height=\"557\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-3.png\" alt=\"Promediador: Todas las Posiciones BUY Se Cierran a un Precio con Ganancia Total.\" class=\"wp-image-70166\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-3.png 555w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-3-498x500.png 498w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-3-300x300.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-3-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-3-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-Example-3-200x200.png 200w\" sizes=\"(max-width:767px) 555px, 555px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ejemplo de c\u00f3mo un asesor <a href=\"https:\/\/www.expforex.com\/es\/?p=10\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>TickSniper<\/strong><\/a> funciona con la estrategia de promediaci\u00f3n:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/933704511.jpg\" alt=\"Promediador: Ejemplo de C\u00f3mo un Asesor TickSniper Funciona con la Estrategia de Promediaci\u00f3n\" class=\"wp-image-6188\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/933704511.jpg 640w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/933704511-500x375.jpg 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/933704511-300x225.jpg 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/933704511-100x75.jpg 100w\" sizes=\"(max-width:767px) 640px, 640px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ejemplo-de-trabajo-usando-takeprofit\">Ejemplo de Trabajo Usando TakeProfit<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Distancia = 100 puntos, TakeProfit = 250 puntos, LotsMartin = 2<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">1 2013.01.02 09:00 <strong>BUY 1 0.10 1.32732<\/strong> 0.00000 0.00000 0.00 10000.00\n2 2013.01.02 09:00 MODIFY 1 0.10 1.32732 0.00000 1.32982 0.00 10000.00\n3 2013.01.02 11:27 <strong>BUY 2 0.20 1.32632<\/strong> 0.00000 0.00000 0.00 10000.00 \n4 2013.01.02 11:27 MODIFY 1 0.10 1.32732 0.00000 1.32915 0.00 10000.00\n5 2013.01.02 11:27 MODIFY 2 0.20 1.32632 0.00000 1.32915 0.00 10000.00\n6 2013.01.02 12:20 <strong>BUY 3 0.40 1.32532<\/strong> 0.00000 0.00000 0.00 10000.00\n7 2013.01.02 12:20 MODIFY 1 0.10 1.32732 0.00000 1.32839 0.00 10000.00\n8 2013.01.02 12:20 MODIFY 2 0.20 1.32632 0.00000 1.32839 0.00 10000.00\n9 2013.01.02 12:20 MODIFY 3 0.40 1.32532 0.00000 1.32839 0.00 10000.00\n10 2013.01.02 12:27 <strong>BUY 4 0.80 1.32429<\/strong> 0.00000 0.00000 0.00 10000.00\n11 2013.01.02 12:27 <strong>MODIFY 1 0.10 1.32732<\/strong> 0.00000 1.32754 0.00 10000.00\n12 2013.01.02 12:27 <strong>MODIFY 2 0.20 1.32632<\/strong> 0.00000 1.32754 0.00 10000.00\n13 2013.01.02 12:27 <strong>MODIFY 3 0.40 1.32532<\/strong> 0.00000 1.32754 0.00 10000.00\n14 2013.01.02 12:27 <strong>MODIFY 4 0.80 1.32429<\/strong> 0.00000 1.32754 0.00 10000.00\n15 2013.01.02 14:28 <strong>T\/P 1 0.10 1.32754<\/strong> 0.00000 1.32754 2.20 <strong>10002.20<\/strong>\n16 2013.01.02 14:28 T\/P 2 0.20 1.32754 0.00000 1.32754 24.40 <strong>10026.60<\/strong>\n17 2013.01.02 14:28 T\/P 3 0.40 1.32754 0.00000 1.32754 88.80 <strong>10115.40<\/strong>\n18 2013.01.02 14:28 T\/P 4 0.80 1.32754 0.00000 1.32754 260.00 <strong>10375.40<\/strong>\n<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este ejemplo muestra la apertura de la primera posici\u00f3n principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medida que el precio se mueve en p\u00e9rdida, nuestro asesor abre posiciones <strong>BUY<\/strong> adicionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de eso, el precio vuelve a la tendencia <strong>BUY<\/strong>, y todas las posiciones se cierran por el Take Profit com\u00fan (Promedio).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-descripcion-breve-del-principio-de-funcionamiento-y-parametros\">Descripci\u00f3n Breve del Principio de Funcionamiento y Par\u00e1metros<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro <strong>Exp-Promediador (Exp-Averager)<\/strong> aparece as\u00ed en el gr\u00e1fico:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1310\" height=\"770\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36.png\" alt=\"Promediador: Descripci\u00f3n Breve del Principio de Funcionamiento y Par\u00e1metros\" class=\"wp-image-70178\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36.png 1310w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36-500x294.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36-1200x705.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36-300x176.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36-768x451.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36-128x75.png 128w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-14_09-23-36-700x411.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1310px) 100vw, 1310px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Exp-Promediador (Exp-Averager)<\/strong> est\u00e1 dise\u00f1ado para promediar operaciones que han experimentado una cierta ca\u00edda y no han seguido la tendencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Nuestro asesor, basado en un n\u00famero predeterminado de puntos <strong>Distancia<\/strong>, abre una posici\u00f3n en la misma direcci\u00f3n con <strong>Lot = Lote de la Operaci\u00f3n Anterior * LotsMartin<\/strong> y modifica el Take Profit (TP) general en todas las operaciones al precio de la &#8220;<strong>l\u00ednea de punto cero para todas las posiciones en una direcci\u00f3n<\/strong>&#8221; + <strong>TakeProfit<\/strong> puntos.<br><br>Tambi\u00e9n es posible modificar (Trailing Stop <strong>TrailingStopUSE = true<\/strong>) el Stop Loss de todas las posiciones en la direcci\u00f3n cuando el precio atraviesa la &#8220;<strong>l\u00ednea de punto cero de todas las posiciones en la misma direcci\u00f3n<\/strong>&#8221; a una distancia de <strong>TrailingStop<\/strong> puntos.<br><br>En la configuraci\u00f3n del Asesor Experto, tambi\u00e9n hay una opci\u00f3n para el n\u00famero m\u00e1ximo de posiciones abiertas para promediar: <strong>MaxOrdersOpen<\/strong>.<br><br>El asesor operar\u00e1 en el gr\u00e1fico del par de divisas donde est\u00e9 instalado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para habilitar el modo de promediaci\u00f3n en el par de divisas EURUSD, necesitas abrir el gr\u00e1fico de EURUSD e instalar el experto.<\/strong><br><br>Tambi\u00e9n puedes limitar la promediaci\u00f3n mediante el Asesor Experto utilizando el par\u00e1metro <strong>OrderToAverage<\/strong> y la opci\u00f3n <strong>MagicToAverage<\/strong> para el Magic de la Posici\u00f3n.<br><br>Este Asesor Experto puede ser probado usando el probador de estrategias en el terminal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para hacer esto, al iniciar, se abrir\u00e1 una posici\u00f3n <strong>BUY<\/strong> con un tama\u00f1o de lote de 0.1 para verificaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a1Puedes usar nuestro <a href=\"https:\/\/www.expforex.com\/es\/?p=35\" target=\"_blank\" rel=\"noreferrer noopener\">EAPADPRO<\/a> para trabajar con Exp-Promediador (Exp-Averager) en el Probador de Estrategias!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-1200x801.png\" alt=\"Promediador: \u00a1Puedes Usar Nuestro EAPADPRO para Trabajar con Exp-Promediador en el Probador de Estrategias!\" class=\"wp-image-5751\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-1200x801.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-500x334.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-300x200.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-768x513.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-1536x1026.png 1536w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-112x75.png 112w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22-700x467.png 700w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-22.png 1791w\" sizes=\"(max-width:767px) 700px, (max-width:1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-instalar-exp-promediador\">C\u00f3mo Instalar Exp-Promediador<\/h2>\n\n\n\n<p align=\"center\">\n  <div class=\"video-container-18 video-thumbnail\" onclick=\"loadVideo('video-container-18', 'lmi5Bck0Pro', 247)\">\n    <img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/hqdefault1-7.jpg\" alt=\"C\u00f3mo Instalar Exp-Promediador Miniatura de Video\" class=\"video-image\">\n    <div class=\"play-button\"><\/div>\n  <\/div>\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-informacion-mostrada-en-el-panel-de-eapadpro\">La Informaci\u00f3n Mostrada en el Panel de EAPADPRO<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"706\" height=\"233\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-03_19-40-37.png\" alt=\"Promediador: La Informaci\u00f3n Mostrada en el Panel de EAPADPRO\" class=\"wp-image-5748\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-03_19-40-37.png 706w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-03_19-40-37-500x165.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-03_19-40-37-300x99.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-03_19-40-37-150x50.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/2024-01-03_19-40-37-700x231.png 700w\" sizes=\"(max-width:767px) 700px, 706px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;BUY Average \/ Lot&#8221;<\/strong> &#8211; La cantidad de puntos (pips) antes de promediar para posiciones <strong>BUY<\/strong>. \u00a1Se muestra con un signo menos! + \u00daltimo lote de operaci\u00f3n (volumen);<br>\n<strong>&#8220;SELL Average \/ Lot&#8221;<\/strong> &#8211; La cantidad de puntos antes de promediar para operaciones <strong>SELL<\/strong>. \u00a1Se muestra con un signo menos! + \u00daltimo lote de operaci\u00f3n (volumen);<br>\n<strong>&#8220;BUY Add \/ Lot&#8221;<\/strong> &#8211; La cantidad de puntos antes de promediar para posiciones <strong>BUY<\/strong>. \u00a1Se muestra con un signo m\u00e1s! + \u00daltimo lote de operaci\u00f3n (volumen);<br>\n<strong>&#8220;SELL Add \/ Lot&#8221;<\/strong> &#8211; La cantidad de puntos antes de promediar para operaciones <strong>SELL<\/strong>. \u00a1Se muestra con un signo m\u00e1s! + \u00daltimo lote de operaci\u00f3n (volumen);<br>\n<strong>&#8220;Min Price Buy&#8221;<\/strong> &#8211; Precio m\u00ednimo para operaciones <strong>BUY<\/strong>;<br>\n<strong>&#8220;Max Price Sell&#8221;<\/strong> &#8211; Precio m\u00e1ximo para operaciones <strong>SELL<\/strong>;<br>\n<strong>&#8220;Min Lot Buy&#8221;<\/strong> &#8211; Tama\u00f1o de lote de la posici\u00f3n <strong>BUY<\/strong> m\u00ednima;<br>\n<strong>&#8220;Max Lot Sell&#8221;<\/strong> &#8211; Tama\u00f1o de lote de la posici\u00f3n <strong>SELL<\/strong> m\u00e1xima;<br>\n<strong>&#8220;Max Price Buy&#8221;<\/strong> &#8211; Precio m\u00e1ximo de las operaciones <strong>BUY<\/strong>;<br>\n<strong>&#8220;Min Price Sell&#8221;<\/strong> &#8211; Precio m\u00ednimo de las operaciones <strong>SELL<\/strong>;<br>\n<strong>&#8220;Max Lot Buy&#8221;<\/strong> &#8211; Tama\u00f1o de lote de la posici\u00f3n <strong>BUY<\/strong> m\u00e1xima;<br>\n<strong>&#8220;Min Lot Sell&#8221;<\/strong> &#8211; Tama\u00f1o de lote de la posici\u00f3n <strong>SELL<\/strong> m\u00ednima;<br>\n<strong>&#8220;Average Price Buy&#8221;<\/strong> &#8211; Precio promedio, el punto de equilibrio para todas las posiciones <strong>BUY<\/strong>;<br>\n<strong>&#8220;Average Price Sell&#8221;<\/strong> &#8211; Precio promedio, el punto de equilibrio para todas las posiciones <strong>SELL<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando <strong>ShowInfoAverager = true<\/strong> est\u00e1 activado, ver\u00e1s la siguiente informaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\"><strong>Promedio<\/strong> &#8211; Muestra la l\u00ednea promedio (cero) de las posiciones en la misma direcci\u00f3n. \u00a1Al pasar el cursor sobre la etiqueta, se mostrar\u00e1 informaci\u00f3n adicional sobre el c\u00e1lculo de la l\u00ednea promedio!<\/li>\n\n\n\n<li class=\"\"><strong>Pr\u00f3ximo Promedio<\/strong> &#8211; Muestra la pr\u00f3xima posici\u00f3n de promediaci\u00f3n que se abrir\u00e1 en esta direcci\u00f3n. \u00a1Al pasar el cursor sobre la etiqueta, se mostrar\u00e1 informaci\u00f3n adicional sobre la distancia!<\/li>\n\n\n\n<li class=\"\"><strong>Pr\u00f3xima Adici\u00f3n<\/strong> &#8211; Muestra la pr\u00f3xima posici\u00f3n para apertura adicional que se abrir\u00e1 en esta direcci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"612\" height=\"466\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-labels.png\" alt=\"Promediador: Informaci\u00f3n Mostrada en el Panel de EAPADPRO\" class=\"wp-image-70190\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-labels.png 612w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-labels-500x381.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-labels-300x228.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/Averager-labels-98x75.png 98w\" sizes=\"(max-width:767px) 612px, 612px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-recomendaciones-para-calcular-la-distancia-de-promediacion-distance-y-el-stoploss\">Recomendaciones para Calcular la Distancia de Promediaci\u00f3n (<strong>Distance<\/strong>) y el StopLoss<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los par\u00e1metros dependen del par de divisas y de tu dep\u00f3sito.<br>Calcula la distancia de promediaci\u00f3n (<strong>Distance<\/strong>) de manera que, al abrir la pr\u00f3xima posici\u00f3n de promediaci\u00f3n (deal), tu cuenta contenga fondos suficientes.<br><strong>Por ejemplo:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\"><strong>Uso una distancia de promediaci\u00f3n igual a 75 SPREAD del par de divisas.<\/strong><\/li>\n\n\n\n<li class=\"\">Si tu SPREAD para el par de divisas es de 10 puntos, entonces la distancia de promediaci\u00f3n (<strong>Distance<\/strong>) = 750 puntos.<\/li>\n\n\n\n<li class=\"\">Si tu posici\u00f3n gana una distancia de 750 puntos, entonces mi asesor abrir\u00e1 una posici\u00f3n adicional, y el punto de equilibrio se desplazar\u00e1 a 750 \/ 2 = 375 puntos desde el precio de apertura de la segunda posici\u00f3n.<\/li>\n\n\n\n<li class=\"\">Esto significa que las dos posiciones necesitan moverse una distancia de 350 puntos en ganancia (ganancia total de dos posiciones) para cerrar en 0 puntos. <strong>La primera posici\u00f3n tendr\u00e1 una p\u00e9rdida de 350 puntos, y la segunda posici\u00f3n tendr\u00e1 una ganancia de 350 puntos.<\/strong><\/li>\n\n\n\n<li class=\"\">Si las posiciones contin\u00faan incurriendo en p\u00e9rdidas, entonces la pr\u00f3xima posici\u00f3n de promediaci\u00f3n se abrir\u00e1 despu\u00e9s de 750 puntos.<\/li>\n\n\n\n<li class=\"\">Esto significa que el punto de equilibrio se desplazar\u00e1 al nivel de 2250 \/ 3 = 750 puntos.<\/li>\n\n\n\n<li class=\"\">Para que tres posiciones cierren en un punto de equilibrio promedio de estos 3 deals, necesitan ganar 750 puntos en ganancia (ganancia total).<\/li>\n<\/ol>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfPor Qu\u00e9 Uso 75 SPREAD?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Esta es una distancia de promediaci\u00f3n (<strong>Distance<\/strong>) suficiente para promediar. Esta cifra puede aplicarse a cualquier par de divisas.<br>Seg\u00fan nuestras pruebas, una distancia de promediaci\u00f3n (<strong>Distance<\/strong>) es suficiente con un dep\u00f3sito de $1,000 que se ha mantenido durante mucho tiempo.<\/u><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Otra forma de determinar la distancia de promediaci\u00f3n (<strong>Distance<\/strong>) es calcular el movimiento promedio del par de divisas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por ejemplo, durante 1 semana.<\/strong><br>Si el par de divisas se mueve una distancia promedio de 1,000 puntos durante 1 semana, entonces la probabilidad de que el precio se mueva 1,000 puntos es del 100%.<br>As\u00ed, puedes establecer la distancia de promediaci\u00f3n (<strong>Distance<\/strong>) en 1,000 puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante elegir un valor en el que tu dep\u00f3sito no se vaya a una p\u00e9rdida total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Por ejemplo:<\/strong><br>Cuando abres una posici\u00f3n con un tama\u00f1o de lote de 0.01 en el par de divisas EURUSD (apalancamiento 1:100, EURUSD = 1.1961), necesitas tener un margen libre de $11.961.<br>El costo de 1 punto = $0.10.<br>Si la <strong>Distance<\/strong> = 100 puntos y el Asesor Experto abre 5 posiciones de promediaci\u00f3n, entonces:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precio actual = 1.1800<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">La primera posici\u00f3n <strong>BUY<\/strong> (precio de apertura = 1.18500, lote = 0.01) tendr\u00e1 una p\u00e9rdida de $50.<\/li>\n\n\n\n<li class=\"\">La segunda posici\u00f3n <strong>BUY<\/strong> (precio de apertura = 1.18400, lote = 0.01) tendr\u00e1 una p\u00e9rdida de $40.<\/li>\n\n\n\n<li class=\"\">La tercera posici\u00f3n <strong>BUY<\/strong> (precio de apertura = 1.18300, lote = 0.01) tendr\u00e1 una p\u00e9rdida de $30.<\/li>\n\n\n\n<li class=\"\">La cuarta posici\u00f3n <strong>BUY<\/strong> (precio de apertura = 1.18200, lote = 0.01) tendr\u00e1 una p\u00e9rdida de $20.<\/li>\n\n\n\n<li class=\"\">La quinta posici\u00f3n <strong>BUY<\/strong> (precio de apertura = 1.18100, lote = 0.01) tendr\u00e1 una p\u00e9rdida de $10.<\/li>\n\n\n\n<li class=\"\">La sexta posici\u00f3n <strong>BUY<\/strong> (precio de apertura = 1.18000, lote = 0.01) alcanzar\u00e1 el punto de equilibrio con una p\u00e9rdida de $0.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Total: $150 + 11.96 * 6 = $221.76.<\/strong><br>Esto significa que para mantener las 6 posiciones (si la distancia de promediaci\u00f3n es 100 puntos), la cuenta debe tener $221.76.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Calcula la distancia de promediaci\u00f3n (<strong>Distance<\/strong>) de manera independiente. Todo depende de tu dep\u00f3sito y de tus l\u00edmites de p\u00e9rdida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Tambi\u00e9n recomiendo establecer un StopLoss de 5 distancias de promediaci\u00f3n y no usar m\u00e1s de 5 posiciones de promediaci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por ejemplo:<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si la distancia de promediaci\u00f3n (<strong>Distance<\/strong>) = 100 puntos, mientras que el StopLoss (<strong>StopLoss<\/strong>) = 500 puntos, y el n\u00famero m\u00e1ximo de \u00f3rdenes de promediaci\u00f3n (<strong>MaxOrdersOpen<\/strong>) = 5.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas las configuraciones de nuestra herramienta son familiares. Debes calcular la distancia correcta para promediar t\u00fa mismo, junto con el tama\u00f1o del lote y el StopLoss.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador\">Recomendaciones para Probar y Optimizar las Opciones del Promediador<\/h2>\n\n\n\n<p align=\"center\">\n  <div class=\"video-container-19 video-thumbnail\" onclick=\"loadVideo('video-container-19', 'lmi5Bck0Pro', 294)\">\n    <img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/hqdefault1-7.jpg\" alt=\"Recomendaciones para Probar y Optimizar las Opciones del Promediador Miniatura de Video\" class=\"video-image\">\n    <div class=\"play-button\"><\/div>\n  <\/div>\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bloque de trabajo con apertura de posiciones contra la tendencia. Promediaci\u00f3n de posiciones.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<pre class=\"wp-block-preformatted\">input string oo2 = \"========= Opciones del Promediador =========\";\ninput bool AverageUSE = true;\ninput bool OnlyModify = false;\ninput int TakeProfitALL = 200;\ninput int Distance = 500;\ninput double DistanceMartin = 1;\ninput double LotsMartin = 1;\ninput int MaxOrdersOpen = 5;<\/pre>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Par\u00e1metros <strong>OnlyModify<\/strong> \u2013 \u00a1No recomiendo cambiar! No tiene sentido optimizar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-parametro-averageuse\">Par\u00e1metro <strong>AverageUSE<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Habilita las funciones de promediaci\u00f3n. \u00a1Solo con <strong>AverageUSE = true<\/strong> se pueden optimizar otros par\u00e1metros!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Optimizaci\u00f3n de valores:<\/u> Verdadero &#8211; FALSO<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Las posiciones de promediaci\u00f3n pueden cargar tu dep\u00f3sito con posiciones adicionales.<\/li>\n\n\n\n<li class=\"\">La estrategia de promediaci\u00f3n requiere un saldo que sea al menos 3 veces mayor que el dep\u00f3sito est\u00e1ndar (sin promediaci\u00f3n).<\/li>\n\n\n\n<li class=\"\">Las posiciones de promediaci\u00f3n son intentos de convertir una posici\u00f3n con p\u00e9rdidas en una ganancia.<\/li>\n\n\n\n<li class=\"\">Si usas el dep\u00f3sito recomendado, puedes aumentar el n\u00famero de operaciones rentables al 70-90%.<\/li>\n\n\n\n<li class=\"\">Al usar la promediaci\u00f3n, el asesor intentar\u00e1 convertir una se\u00f1al falsa en ganancia. Otras se\u00f1ales ser\u00e1n ignoradas hasta que la serie de promediaci\u00f3n se cierre.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-parametro-takeprofitall\">Par\u00e1metro <strong>TakeProfitALL<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8211; Modifica el take-profit de todas las posiciones en 1 nivel.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Optimizaci\u00f3n de valores:<\/u> 10-50-1000 (inicio = 10, paso = 50, fin = 1000)<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Sirve como protecci\u00f3n adicional para las posiciones si lo has deshabilitado.<\/li>\n\n\n\n<li class=\"\">Tiene sentido si no usas <strong>AdditionalOpening = false<\/strong>.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-parametro-distance\">Par\u00e1metro <strong>Distance<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8211; Determina la distancia a la cual se abren posiciones adicionales contra la tendencia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Optimizaci\u00f3n de valores:<\/u> Se recomienda establecer los par\u00e1metros individualmente para cada par.<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Por ejemplo, si este es el par de divisas EURUSD y operas en el marco de tiempo M30 con un movimiento de precio promedio de 50 barras = 7500 puntos, entonces configura este par\u00e1metro para optimizaci\u00f3n: inicio 0, paso 25, fin 500.<\/li>\n\n\n\n<li class=\"\">Por ejemplo, si este es el par de divisas XUGUSD y operas en el marco de tiempo M1 con un movimiento de precio promedio de 50 barras = 100 puntos, entonces configura este par\u00e1metro para optimizaci\u00f3n de la siguiente manera: inicio 0, paso 5, fin 100.<\/li>\n\n\n\n<li class=\"\">Otra forma de optimizar este par\u00e1metro es usar el spread promedio para el par de divisas seleccionado. Este m\u00e9todo se utiliza en nuestro asesor <strong><a href=\"https:\/\/www.expforex.com\/es\/?p=10\" target=\"_blank\" rel=\"noreferrer noopener\">TickSniper<\/a><\/strong>.<\/li>\n\n\n\n<li class=\"\">Por ejemplo, si el spread promedio para un par de divisas es de 3 puntos, entonces la distancia de promediaci\u00f3n = 50 * 3 = 150 puntos. En este caso, la optimizaci\u00f3n se puede configurar de la siguiente manera: 100-25-250.<\/li>\n\n\n\n<li class=\"\">Cuanto mayores sean los valores de distancia, m\u00e1s tiempo tarda el asesor en convertir la serie de posiciones en ganancia total.<\/li>\n\n\n\n<li class=\"\">Cuanto menor sea la distancia de promediaci\u00f3n, mayor ser\u00e1 la carga en tu saldo. Se abrir\u00e1n m\u00e1s posiciones. \u00a1Puedes obtener ganancias m\u00e1s r\u00e1pido, pero al mismo tiempo, habr\u00e1 una carga significativa en tu cuenta de trading!<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-parametro-distancemartin\">Par\u00e1metro <strong>DistanceMartin<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Aumenta la <strong>Distance<\/strong> en cada posici\u00f3n adicional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Optimizaci\u00f3n de valores:<\/u> Solo en casos extremos, 1-0.1-2<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Este par\u00e1metro debe optimizarse solo si necesitas aumentar la distancia para cada nueva posici\u00f3n en la serie.<\/li>\n\n\n\n<li class=\"\">Si <strong>Distance<\/strong> es demasiado peque\u00f1a, entonces <strong>DistanceMartin<\/strong> te permite aumentar el paso de la cuadr\u00edcula de promediaci\u00f3n.<\/li>\n\n\n\n<li class=\"\">Si <strong>DistanceMartin<\/strong> es menor que 1, entonces el paso de la cuadr\u00edcula de promediaci\u00f3n y <strong>Distance<\/strong> disminuir\u00e1n cuando se abra cada posici\u00f3n adicional de promediaci\u00f3n.<\/li>\n\n\n\n<li class=\"\">Si <strong>DistanceMartin<\/strong> es mayor que 1, entonces el paso de la cuadr\u00edcula de promediaci\u00f3n y <strong>Distance<\/strong> aumentar\u00e1n cuando se abra cada posici\u00f3n adicional de promediaci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-parametro-lotsmartin\">Par\u00e1metro <strong>LotsMartin<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Aumenta el tama\u00f1o del lote para cada posici\u00f3n adicional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Optimizaci\u00f3n de valores:<\/u> Solo en casos extremos, 1-0.1-2<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Permite reducir el tiempo para que una serie de posiciones se convierta en ganancia.<\/li>\n\n\n\n<li class=\"\">Puede cargar tu cuenta de trading y tu saldo.<\/li>\n\n\n\n<li class=\"\">\u00a1Se recomienda usar solo con un saldo suficiente!<\/li>\n\n\n\n<li class=\"\">Si <strong>LotsMartin<\/strong> es menor que 1, entonces el pr\u00f3ximo lote de promediaci\u00f3n disminuir\u00e1 cuando abras cada posici\u00f3n adicional de promediaci\u00f3n.<\/li>\n\n\n\n<li class=\"\">Si <strong>LotsMartin<\/strong> es mayor que 1, entonces el pr\u00f3ximo lote de promediaci\u00f3n aumentar\u00e1 cuando abras cada posici\u00f3n adicional de promediaci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-parametro-maxordersopen\">Par\u00e1metro <strong>MaxOrdersOpen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Limita el n\u00famero de posiciones adicionales de promediaci\u00f3n contra la tendencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Optimizaci\u00f3n de valores:<\/u> Solo en casos extremos, 0 &#8211; 1 &#8211; 10<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"\">Permite limitar la carga en el dep\u00f3sito restringiendo el n\u00famero de nuevas posiciones adicionales.<\/li>\n\n\n\n<li class=\"\">Uso el valor de 5. Pero puedes optimizar este valor para obtener mejores resultados.<\/li>\n<\/ol>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"3\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\"><div class=\"root-eb-toc-x6pwr7g wp-block-essential-blocks-table-of-contents\"><div class=\"eb-parent-wrapper eb-parent-eb-toc-x6pwr7g \"><div class=\"eb-toc-container eb-toc-x6pwr7g  eb-toc-is-not-sticky eb-toc-collapsible eb-toc-initially-collapsed eb-toc-scrollToTop style-1 list-style-none\" data-scroll-top=\"false\" data-scroll-top-icon=\"fas fa-angle-up\" data-collapsible=\"true\" data-sticky-hide-mobile=\"false\" data-sticky=\"false\" data-scroll-target=\"scroll_to_toc\" data-copy-link=\"true\" data-editor-type=\"\" data-hide-desktop=\"false\" data-hide-tab=\"false\" data-hide-mobile=\"false\" data-itemcollapsed=\"false\" data-highlight-scroll=\"false\"><div class=\"eb-toc-header\"><h2 class=\"eb-toc-title\">\u00cdndice de contenidos (haga clic para mostrar)<\/h2><\/div><div class=\"eb-toc-wrapper hide-content\" data-headers=\"[{&quot;level&quot;:2,&quot;content&quot;:&quot;Acerca de Exp Averager&quot;,&quot;text&quot;:&quot;Acerca de Exp Averager&quot;,&quot;link&quot;:&quot;acerca-de-exp-averager&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-1&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-2&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-3&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-4&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-5&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;text&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;link&quot;:&quot;eb-table-content-6&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-7&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;link&quot;:&quot;eb-table-content-8&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Links&quot;,&quot;text&quot;:&quot;Links&quot;,&quot;link&quot;:&quot;links&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Descripci\\u00f3n&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n&quot;,&quot;link&quot;:&quot;eb-table-content-10&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-11&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-12&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-gif&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-imagen&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;text&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;link&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;link&quot;:&quot;eb-table-content-16&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;text&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;link&quot;:&quot;eb-table-content-17&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;text&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;link&quot;:&quot;eb-table-content-18&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;text&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;link&quot;:&quot;eb-table-content-19&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;text&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;link&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;text&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;link&quot;:&quot;eb-table-content-21&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;text&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;link&quot;:&quot;eb-table-content-22&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;text&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;link&quot;:&quot;eb-table-content-23&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;link&quot;:&quot;eb-table-content-24&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;link&quot;:&quot;eb-table-content-25&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;text&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;link&quot;:&quot;eb-table-content-26&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;text&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;link&quot;:&quot;variables-externas-y-configuraciones&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Generales&quot;,&quot;text&quot;:&quot;Configuraciones Generales&quot;,&quot;link&quot;:&quot;configuraciones-generales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Promediado&quot;,&quot;text&quot;:&quot;Configuraciones de Promediado&quot;,&quot;link&quot;:&quot;configuraciones-de-promediado&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Adicionales&quot;,&quot;text&quot;:&quot;Configuraciones Adicionales&quot;,&quot;link&quot;:&quot;configuraciones-adicionales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Filtro&quot;,&quot;text&quot;:&quot;Configuraciones de Filtro&quot;,&quot;link&quot;:&quot;configuraciones-de-filtro&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;text&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;link&quot;:&quot;configuraciones-de-trailing-stop&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;text&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;link&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Registro Exp Averager&quot;,&quot;text&quot;:&quot;Registro Exp Averager&quot;,&quot;link&quot;:&quot;registro-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;text&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;link&quot;:&quot;eb-table-content-35&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;text&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;link&quot;:&quot;comentarios-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Extra&quot;,&quot;text&quot;:&quot;Extra&quot;,&quot;link&quot;:&quot;extra&quot;}]\" data-visible=\"[true,true,true,true,true,false]\" data-delete-headers=\"[{&quot;label&quot;:&quot;Acerca de Exp Averager&quot;,&quot;value&quot;:&quot;acerca-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-la-apertura-adicional-en-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-el-promediado-contra-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfqu\\u00e9-opinan-las-personas-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-exp-averager-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;value&quot;:&quot;\\u00a1comienza-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-e-instalar-nuestro-programa-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-comprar-la-versi\\u00f3n-completa-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Links&quot;,&quot;value&quot;:&quot;links&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Descripci\\u00f3n&quot;,&quot;value&quot;:&quot;descripci\\u00f3n&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-apertura-adicional-con-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-promediaci\\u00f3n-contra-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-gif&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-imagen&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;value&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;value&quot;:&quot;descripci\\u00f3n-breve-del-principio-de-funcionamiento-y-par\\u00e1metros&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;value&quot;:&quot;c\\u00f3mo-instalar-exp-promediador&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;value&quot;:&quot;la-informaci\\u00f3n-mostrada-en-el-panel-de-eapadpro&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;value&quot;:&quot;recomendaciones-para-calcular-la-distancia-de-promediaci\\u00f3n-distance-y-el-stoploss&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;value&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;value&quot;:&quot;par\\u00e1metro-averageuse&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;value&quot;:&quot;par\\u00e1metro-takeprofitall&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distance&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distancemartin&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-lotsmartin&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;value&quot;:&quot;par\\u00e1metro-maxordersopen&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;value&quot;:&quot;variables-externas-y-configuraciones&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones Generales&quot;,&quot;value&quot;:&quot;configuraciones-generales&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones de Promediado&quot;,&quot;value&quot;:&quot;configuraciones-de-promediado&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones Adicionales&quot;,&quot;value&quot;:&quot;configuraciones-adicionales&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones de Filtro&quot;,&quot;value&quot;:&quot;configuraciones-de-filtro&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;value&quot;:&quot;configuraciones-de-trailing-stop&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;value&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Registro Exp Averager&quot;,&quot;value&quot;:&quot;registro-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;value&quot;:&quot;rese\\u00f1as-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;value&quot;:&quot;comentarios-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Extra&quot;,&quot;value&quot;:&quot;extra&quot;,&quot;isDelete&quot;:true}]\" data-smooth=\"true\" data-top-offset=\"500\"><div class=\"eb-toc__list-wrap\"><ul class=\"eb-toc__list\"><li><a href=\"#variables-externas-y-configuraciones\">Variables Externas y Configuraciones<\/a><li><a href=\"#configuraciones-generales\">Configuraciones Generales<\/a><li><a href=\"#configuraciones-de-promediado\">Configuraciones de Promediado<\/a><li><a href=\"#configuraciones-adicionales\">Configuraciones Adicionales<\/a><li><a href=\"#configuraciones-de-filtro\">Configuraciones de Filtro<\/a><li><a href=\"#configuraciones-de-trailing-stop\">Configuraciones de Trailing Stop<\/a><\/ul><\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"root-eb-toc-sika1 wp-block-essential-blocks-table-of-contents\"><div class=\"eb-parent-wrapper eb-parent-eb-toc-sika1 \"><div class=\"eb-toc-container eb-toc-sika1 eb-toc-sticky-right eb-toc-is-sticky eb-toc-collapsible eb-toc-initially-collapsed eb-toc-scrollToTop style-1 \" data-scroll-top=\"false\" data-scroll-top-icon=\"fas fa-angle-up\" data-collapsible=\"true\" data-sticky-hide-mobile=\"true\" data-sticky=\"true\" data-scroll-target=\"scroll_to_toc\" data-copy-link=\"true\" data-editor-type=\"\" data-hide-desktop=\"false\" data-hide-tab=\"false\" data-hide-mobile=\"false\" data-itemcollapsed=\"true\" data-highlight-scroll=\"false\"><div class=\"eb-toc-header\"><span class=\"eb-toc-close eb-toc-sticky-right\"><\/span><h2 class=\"eb-toc-title\">List<\/h2><\/div><div class=\"eb-toc-wrapper \" data-headers=\"[{&quot;level&quot;:2,&quot;content&quot;:&quot;Acerca de Exp Averager&quot;,&quot;text&quot;:&quot;Acerca de Exp Averager&quot;,&quot;link&quot;:&quot;acerca-de-exp-averager&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-1&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;text&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;link&quot;:&quot;eb-table-content-2&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-3&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;text&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;link&quot;:&quot;eb-table-content-4&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-5&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;text&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;link&quot;:&quot;eb-table-content-6&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;link&quot;:&quot;eb-table-content-7&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;text&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;link&quot;:&quot;eb-table-content-8&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Links&quot;,&quot;text&quot;:&quot;Links&quot;,&quot;link&quot;:&quot;links&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Descripci\\u00f3n&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n&quot;,&quot;link&quot;:&quot;eb-table-content-10&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-11&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;text&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;link&quot;:&quot;eb-table-content-12&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-gif&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;text&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;link&quot;:&quot;promediador-ejemplo-en-imagen&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;text&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;link&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;text&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;link&quot;:&quot;eb-table-content-16&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;text&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;link&quot;:&quot;eb-table-content-17&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;text&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;link&quot;:&quot;eb-table-content-18&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;text&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;link&quot;:&quot;eb-table-content-19&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;text&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;link&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;text&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;link&quot;:&quot;eb-table-content-21&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;text&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;link&quot;:&quot;eb-table-content-22&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;text&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;link&quot;:&quot;eb-table-content-23&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;link&quot;:&quot;eb-table-content-24&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;text&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;link&quot;:&quot;eb-table-content-25&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;text&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;link&quot;:&quot;eb-table-content-26&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;text&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;link&quot;:&quot;variables-externas-y-configuraciones&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Generales&quot;,&quot;text&quot;:&quot;Configuraciones Generales&quot;,&quot;link&quot;:&quot;configuraciones-generales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Promediado&quot;,&quot;text&quot;:&quot;Configuraciones de Promediado&quot;,&quot;link&quot;:&quot;configuraciones-de-promediado&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones Adicionales&quot;,&quot;text&quot;:&quot;Configuraciones Adicionales&quot;,&quot;link&quot;:&quot;configuraciones-adicionales&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Filtro&quot;,&quot;text&quot;:&quot;Configuraciones de Filtro&quot;,&quot;link&quot;:&quot;configuraciones-de-filtro&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;text&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;link&quot;:&quot;configuraciones-de-trailing-stop&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;text&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;link&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Registro Exp Averager&quot;,&quot;text&quot;:&quot;Registro Exp Averager&quot;,&quot;link&quot;:&quot;registro-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;text&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;link&quot;:&quot;eb-table-content-35&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;text&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;link&quot;:&quot;comentarios-sobre-exp-averager&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Extra&quot;,&quot;text&quot;:&quot;Extra&quot;,&quot;link&quot;:&quot;extra&quot;}]\" data-visible=\"[true,true,true,true,false,false]\" data-delete-headers=\"[{&quot;label&quot;:&quot;Acerca de Exp Averager&quot;,&quot;value&quot;:&quot;acerca-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona la Apertura Adicional En la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-la-apertura-adicional-en-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1C\\u00f3mo Funciona el Promediado Contra la Tendencia!&quot;,&quot;value&quot;:&quot;\\u00a1c\\u00f3mo-funciona-el-promediado-contra-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfQu\\u00e9 opinan las personas sobre Exp Averager?&quot;,&quot;value&quot;:&quot;\\u00bfqu\\u00e9-opinan-las-personas-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar Exp Averager gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-exp-averager-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Comienza GRATIS!&quot;,&quot;value&quot;:&quot;\\u00a1comienza-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes descargar e instalar nuestro programa gratis!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-descargar-e-instalar-nuestro-programa-gratis&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00a1Puedes comprar la versi\\u00f3n completa de Exp Averager!&quot;,&quot;value&quot;:&quot;\\u00a1puedes-comprar-la-versi\\u00f3n-completa-de-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Links&quot;,&quot;value&quot;:&quot;links&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Descripci\\u00f3n&quot;,&quot;value&quot;:&quot;descripci\\u00f3n&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Apertura Adicional con la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-apertura-adicional-con-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;\\u00bfC\\u00f3mo Funciona la Promediaci\\u00f3n Contra la Tendencia?&quot;,&quot;value&quot;:&quot;\\u00bfc\\u00f3mo-funciona-la-promediaci\\u00f3n-contra-la-tendencia&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Promediador: Ejemplo en GIF&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-gif&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Promediador: Ejemplo en Imagen&quot;,&quot;value&quot;:&quot;promediador-ejemplo-en-imagen&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Ejemplo de Trabajo Usando TakeProfit&quot;,&quot;value&quot;:&quot;ejemplo-de-trabajo-usando-takeprofit&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Descripci\\u00f3n Breve del Principio de Funcionamiento y Par\\u00e1metros&quot;,&quot;value&quot;:&quot;descripci\\u00f3n-breve-del-principio-de-funcionamiento-y-par\\u00e1metros&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;C\\u00f3mo Instalar Exp-Promediador&quot;,&quot;value&quot;:&quot;c\\u00f3mo-instalar-exp-promediador&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;La Informaci\\u00f3n Mostrada en el Panel de EAPADPRO&quot;,&quot;value&quot;:&quot;la-informaci\\u00f3n-mostrada-en-el-panel-de-eapadpro&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Recomendaciones para Calcular la Distancia de Promediaci\\u00f3n (Distance) y el StopLoss&quot;,&quot;value&quot;:&quot;recomendaciones-para-calcular-la-distancia-de-promediaci\\u00f3n-distance-y-el-stoploss&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Recomendaciones para Probar y Optimizar las Opciones del Promediador&quot;,&quot;value&quot;:&quot;recomendaciones-para-probar-y-optimizar-las-opciones-del-promediador&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro AverageUSE&quot;,&quot;value&quot;:&quot;par\\u00e1metro-averageuse&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro TakeProfitALL&quot;,&quot;value&quot;:&quot;par\\u00e1metro-takeprofitall&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro Distance&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distance&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro DistanceMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-distancemartin&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro LotsMartin&quot;,&quot;value&quot;:&quot;par\\u00e1metro-lotsmartin&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Par\\u00e1metro MaxOrdersOpen&quot;,&quot;value&quot;:&quot;par\\u00e1metro-maxordersopen&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Variables Externas y Configuraciones&quot;,&quot;value&quot;:&quot;variables-externas-y-configuraciones&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones Generales&quot;,&quot;value&quot;:&quot;configuraciones-generales&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones de Promediado&quot;,&quot;value&quot;:&quot;configuraciones-de-promediado&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones Adicionales&quot;,&quot;value&quot;:&quot;configuraciones-adicionales&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones de Filtro&quot;,&quot;value&quot;:&quot;configuraciones-de-filtro&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Configuraciones de Trailing Stop&quot;,&quot;value&quot;:&quot;configuraciones-de-trailing-stop&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Preguntas y respuestas frecuentes sobre Exp Averager&quot;,&quot;value&quot;:&quot;preguntas-y-respuestas-frecuentes-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Registro Exp Averager&quot;,&quot;value&quot;:&quot;registro-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Rese\\u00f1as sobre Exp Averager&quot;,&quot;value&quot;:&quot;rese\\u00f1as-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Comentarios sobre Exp Averager&quot;,&quot;value&quot;:&quot;comentarios-sobre-exp-averager&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Extra&quot;,&quot;value&quot;:&quot;extra&quot;,&quot;isDelete&quot;:true}]\" data-smooth=\"true\" data-top-offset=\"150\"><div class=\"eb-toc__list-wrap\"><ul class=\"eb-toc__list\"><li><a href=\"#variables-externas-y-configuraciones\">Variables Externas y Configuraciones<\/a><li><a href=\"#configuraciones-generales\">Configuraciones Generales<\/a><li><a href=\"#configuraciones-de-promediado\">Configuraciones de Promediado<\/a><li><a href=\"#configuraciones-adicionales\">Configuraciones Adicionales<\/a><li><a href=\"#configuraciones-de-filtro\">Configuraciones de Filtro<\/a><li><a href=\"#configuraciones-de-trailing-stop\">Configuraciones de Trailing Stop<\/a><\/ul><\/div><\/div><button class=\"eb-toc-button  eb-toc-button-right\"><div>List<\/div><\/button><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-variables-externas-y-configuraciones\">Variables Externas y Configuraciones<\/h2>\n\n\n\n<figure class=\"is-style-stripes wp-block-table\"><table><thead><tr><th>Nombre<\/th><th>Descripci\u00f3n<\/th><\/tr><\/thead><tbody><tr><td colspan=\"2\">\n          <h2>Configuraciones Generales<\/h2>\n        <\/td><\/tr><tr><td><strong>SetMinStops<\/strong><\/td><td>\n          <p><strong>Normaliza autom\u00e1ticamente todos los par\u00e1metros del Asesor Experto (Expert Advisor) a los niveles m\u00ednimos de stop aceptables.<\/strong><\/p>\n          <p>Con <strong>stops virtuales<\/strong>, este par\u00e1metro no se aplica.<\/p>\n          <p>Con <strong>AutoSetMinLevel<\/strong>, los niveles de stop se establecer\u00e1n en los niveles m\u00e1s bajos permitidos por el servidor;<\/p>\n          <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Si el nivel de Stop Loss o Take Profit est\u00e1 por debajo del nivel m\u00ednimo de stop del servidor, entonces el nivel de Stop Loss\/Take Profit = Nivel de Stop M\u00ednimo (Spread * 2 o nivel fijo en el servidor) + Spread.<\/mark>\n          <p>Al usar <strong>ManualSet<\/strong>, el usuario recibir\u00e1 un mensaje de que los niveles de stop del EA est\u00e1n por debajo del m\u00ednimo, y el EA recibir\u00e1 un error del servidor.<\/p>\n          <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Si el nivel de stop del servidor es flotante, entonces el nivel de stop m\u00ednimo se calcula autom\u00e1ticamente como = Spread * 2.<\/mark>\n        <\/td><\/tr><tr><td><strong>Magic<\/strong><\/td><td>El <strong>n\u00famero m\u00e1gico (magic number)<\/strong> de las posiciones abiertas por nuestro Asesor Experto (EA).<\/td><\/tr><tr><td><strong>TakeProfitALL<\/strong><\/td><td>\n          <p><strong>Take Profit total para todas las posiciones.<\/strong><\/p>\n          <p>El Take Profit se establecer\u00e1 a una distancia de <strong>TakeProfitALL<\/strong> puntos desde el precio de apertura promedio de las posiciones.<\/p>\n          <p>Si estableces <strong>TakeProfitALL<\/strong> = 5 puntos, esto significa que el Take Profit se establecer\u00e1 a una distancia de 5 puntos desde la l\u00ednea media.<\/p>\n        <\/td><\/tr><tr><td><strong>StopLossALL<\/strong><\/td><td>\n          <p><strong>Stop Loss total para todas las posiciones.<\/strong><\/p>\n          <p>El Stop Loss se establecer\u00e1 a una distancia de <strong>StopLossALL<\/strong> puntos desde el precio de apertura promedio de las posiciones.<\/p>\n          <p>Si estableces <strong>StopLossALL<\/strong> = 5 puntos, esto significa que el Stop Loss se establecer\u00e1 a una distancia de 5 puntos desde la l\u00ednea media.<\/p>\n        <\/td><\/tr><tr><td><strong>MaxOrdersOpen<\/strong><\/td><td>El n\u00famero m\u00e1ximo de posiciones para este par de divisas en una direcci\u00f3n (separadamente para BUY y SELL).<\/td><\/tr><tr><td><strong>AllTradeTrail<\/strong><\/td><td>\n          <strong>Modificar la posici\u00f3n original (la posici\u00f3n principal desde la cual se abre el promediado).<\/strong><br><br>\n          <strong>Trailing Stop \/ TakeProfitALL \/ StopLossALL<\/strong> se aplicar\u00e1n a todas las posiciones (operaciones) y a la posici\u00f3n que deseas promediar.<br>\n          Si tu posici\u00f3n no tiene un Trailing Stop \/ TakeProfitALL \/ StopLossALL, nuestro asesor tambi\u00e9n establecer\u00e1 Trailing Stop \/ TakeProfitALL \/ StopLossALL en tu posici\u00f3n.<br>\n          Este par\u00e1metro tambi\u00e9n est\u00e1 involucrado en la modificaci\u00f3n de Take Profit \/ Stop Loss.<br>\n          Si esta opci\u00f3n est\u00e1 habilitada, entonces todas las posiciones (operaciones) en la cuenta ser\u00e1n reconocidas por nuestro asesor como tus operaciones.<br>\n          Todos los SL y TP de todas las operaciones se establecer\u00e1n de acuerdo con las configuraciones de nuestro programa.\n        <\/td><\/tr><tr><td><strong>Include_Commission_Swap<\/strong><\/td><td>\n          <strong>Considerar el c\u00e1lculo del autor de la Comisi\u00f3n y el swap cuando las funciones est\u00e1n habilitadas: BreakEven (stop loss en el Punto de equilibrio (Pips)), Trailing Stop, Promediado.<\/strong><br><br>\n          El c\u00e1lculo del autor de la Comisi\u00f3n se basa en la f\u00f3rmula para calcular el valor de 1 Punto (Pips) de las posiciones abiertas para este s\u00edmbolo y el n\u00famero m\u00e1gico; un swap negativo y la Comisi\u00f3n est\u00e1n incluidos en el c\u00e1lculo.<br>\n          La funci\u00f3n devuelve el costo de un swap negativo y la Comisi\u00f3n en Puntos (Pips) y lo tiene en cuenta al trabajar con las funciones BreakEven (stop loss en el Punto de equilibrio (Pips)) y Trailing Stop.<br><br>\n          <strong>Atenci\u00f3n<\/strong>: Si tienes un spread flotante con tu broker, el asentamiento de la Comisi\u00f3n se ejecuta y se establece en el momento de las funciones BreakEven (stop loss en el Punto de equilibrio (Pips)) y Trailing Stop, pero el spread puede aumentar, resultando en puntos (pips) de p\u00e9rdida adicionales.<br><br>\n          \u00a1Esto no es un error de c\u00e1lculo! Adem\u00e1s, ten en cuenta que cuando ocurre un swap, el asesor recalcula la l\u00ednea BreakEven (stop loss en el Punto de equilibrio (Pips)) y establece nuevos stops si el servidor lo permite (restricci\u00f3n al nivel m\u00ednimo de stop para el StopLevel de tu broker). Si el servidor no permite establecer un BreakEven y devuelve un error de nivel m\u00ednimo de stop, el EA no podr\u00e1 modificar la posici\u00f3n, y podr\u00edas incurrir en puntos (pips) de p\u00e9rdida adicionales.<br><br>\n          <strong>Para evitar p\u00e9rdidas<\/strong> al usar Comisi\u00f3n y recibir un swap negativo, recomendamos aumentar la distancia entre BreakEven (stop loss en el Punto de equilibrio (Pips)) o Trailing Stop. El nivel de BreakEven (<strong>LevelWLoss<\/strong>) puede calcularse de forma independiente, considerando la Comisi\u00f3n.<br><br>\n          Por ejemplo, si la Comisi\u00f3n por abrir y cerrar una posici\u00f3n = 2 d\u00f3lares (EURUSD) por 1 lote.<br>\n          Para cubrir la p\u00e9rdida de Comisi\u00f3n, establece <strong>LevelWLoss = 2 (Puntos (Pips)) + 1 (punto de control) = 3 Puntos (Pips)<\/strong>.<br>\n          As\u00ed, el asesor establecer\u00e1 el BreakEven (Stop Loss en el Punto de equilibrio (Pips)) en +3 Puntos (Pips), lo que cubrir\u00e1 la p\u00e9rdida de Comisi\u00f3n.\n        <\/td><\/tr><tr><td><strong>ShowInfoAverager<\/strong><\/td><td>\n          <strong>Informaci\u00f3n adicional en el gr\u00e1fico donde est\u00e1 instalado nuestro asesor.<\/strong><br><br>\n          Cuando <strong>ShowInfoAverager<\/strong> est\u00e1 habilitado (true), ver\u00e1s la siguiente informaci\u00f3n:<br><br>\n          <strong>Promedio<\/strong> = Muestra la l\u00ednea Promedio (cero) de las posiciones en la misma direcci\u00f3n.<br>\n          Al pasar el cursor sobre la etiqueta, proporciona informaci\u00f3n adicional sobre el c\u00e1lculo de la l\u00ednea promedio.<br><br>\n          <strong>Siguiente Promedio<\/strong> = Muestra la pr\u00f3xima posici\u00f3n de promediado que se abrir\u00e1 en esta direcci\u00f3n.<br>\n          Al pasar el cursor sobre la etiqueta, proporciona informaci\u00f3n adicional sobre la distancia.<br><br>\n          <strong>Siguiente Adicional<\/strong> = Muestra la pr\u00f3xima posici\u00f3n para apertura adicional que se abrir\u00e1 en esta direcci\u00f3n.<p><img decoding=\"async\" src=\"https:\/\/www.expforex.com\/_pu\/2\/17759429.jpg\" style=\"\" alt=\"Informaci\u00f3n adicional en el gr\u00e1fico donde est\u00e1 instalado nuestro asesor.\"><\/p>\n        <\/td><\/tr><tr><td colspan=\"2\">\n          <h2>Configuraciones de Promediado<\/h2>\n          <br>\n        <\/td><\/tr><tr><td><strong>Distance<\/strong><\/td><td>\n          <strong>La distancia para abrir posiciones en la cuadr\u00edcula de promediado.<\/strong><br><br>\n          Despu\u00e9s de cu\u00e1ntos puntos contra la tendencia abrir la pr\u00f3xima posici\u00f3n de promediado (Deal) desde la \u00faltima posici\u00f3n abierta de un tipo para promediado.<br><br>\n          Por ejemplo, puedes establecer 100 Puntos (Pips).<br>\n          Luego, cada nueva posici\u00f3n de promediado se abrir\u00e1 despu\u00e9s de 100 Puntos (Pips) de p\u00e9rdida desde la \u00faltima posici\u00f3n abierta.<br><br>\n          Puedes establecer <strong>50<\/strong> Puntos (Pips).<br>\n          Luego, cada nueva posici\u00f3n adicional (Deal) se abrir\u00e1 despu\u00e9s de 100 + 50 puntos de p\u00e9rdida desde la \u00faltima posici\u00f3n abierta. <strong>(100,150,200,250,300)<\/strong>\n        <\/td><\/tr><tr><td><strong>DistanceMartin<\/strong><\/td><td>\n          <strong>El multiplicador para la distancia desde el promedio para cada operaci\u00f3n.<\/strong><br><br>\n          Puedes establecerlo en <strong>1.5<\/strong>.<br>\n          Luego, cada nueva posici\u00f3n de promediado se abrir\u00e1 despu\u00e9s de 100 + 50 (100 * 1.5) Puntos (Pips) de p\u00e9rdida desde la \u00faltima posici\u00f3n abierta <strong>(100,150,225,337,506)<\/strong>.\n        <\/td><\/tr><tr><td><strong>DistanceAdditionalPoint<\/strong><\/td><td>\n          <strong>Puntos (Pips) adicionales para calcular la distancia.<\/strong><br>\n          Si <strong>DistanceAdditionalPoint<\/strong> = 5, entonces se a\u00f1aden 5 puntos (Pips) a cada distancia subsecuente.<br>\n          Si el n\u00famero anterior de operaciones = 3, entonces puntos (Pips) adicionales para la distancia = 5 * 3 = 15 puntos adicionales (Pips).\n        <\/td><\/tr><tr><td><strong>DistanceMax<\/strong><\/td><td>\n          <strong>El n\u00famero m\u00e1ximo de puntos (Pips) para la distancia.<\/strong><br>\n          Si, al calcular la distancia, el valor obtenido excede <strong>DistanceMax<\/strong>, entonces el Asesor Experto (EA) usar\u00e1 <strong>DistanceMax<\/strong> en Puntos (Pips).\n        <\/td><\/tr><tr><td><strong>DistanceDifferent<\/strong><\/td><td>\n          <strong>Distancias para nuevas posiciones de promediado (contra la tendencia),<\/strong><br>\n          separadas por comas.<br>\n          Puedes especificar valores de distancia en el formato: <strong>xx, yy, zz, aa<\/strong><br>\n          <strong>D\u00f3nde:<\/strong><br>\n          xx &#8211; Distancia en puntos para abrir la primera posici\u00f3n de promediado;<br>\n          yy &#8211; Distancia en puntos para abrir la segunda posici\u00f3n de promediado;<br>\n          zz &#8211; Distancia en puntos para abrir la tercera posici\u00f3n de promediado;<br>\n          aa &#8211; Distancia en puntos para abrir la cuarta y posteriores posiciones de promediado;<br><br>\n          <strong>El \u00faltimo n\u00famero en la l\u00ednea = distancia para todas las posiciones subsecuentes.<\/strong><br>\n          <strong>Puedes establecer cualquier n\u00famero de distancias.<\/strong>\n        <\/td><\/tr><tr><td><strong>StopLoss<\/strong><\/td><td>\n          <strong>Stop Loss para la posici\u00f3n de promediado a abrir,<\/strong><br>\n          <strong>Nota<\/strong>: Cada posici\u00f3n de promediado se abrir\u00e1 inicialmente con su propio Stop Loss.<br>\n          El Stop Loss se establecer\u00e1 a una distancia de <strong>StopLoss<\/strong> puntos desde el precio de apertura de la posici\u00f3n de promediado.\n        <\/td><\/tr><tr><td><strong>TakeProfit<\/strong><\/td><td>\n          <strong>Take Profit para la posici\u00f3n de promediado a abrir,<\/strong><br>\n          <strong>Nota<\/strong>: Cada posici\u00f3n de promediado se abrir\u00e1 inicialmente con su propio Take Profit.<br>\n          El Take Profit se establecer\u00e1 a una distancia de <strong>TakeProfit<\/strong> puntos desde el precio de apertura de la posici\u00f3n de promediado.\n        <\/td><\/tr><tr><td><strong>LotsMartin<\/strong><\/td><td>\n          <strong>Coeficiente: Incrementar el lote (Volume) para posiciones en la cuadr\u00edcula.<\/strong><br>\n          <strong>El coeficiente para incrementar los lotes de cada posici\u00f3n de promediado subsecuente.<\/strong><br>\n          Por <strong>ejemplo<\/strong>:<br>\n          Lote Inicial (Volume) de la posici\u00f3n principal = 0.1<br>\n          <strong>LotsMartin = 2, entonces<\/strong><br>\n          El pr\u00f3ximo lote (Volume) de la posici\u00f3n de promediado abierta ser\u00e1 0.2, 0.4, 0.8, y as\u00ed sucesivamente.<br><br>\n          Si <strong>Martin = 1<\/strong>, entonces el martingala no se activa (lotes fijos (Volumes)).<br>\n          Si <strong>Martin = 0<\/strong>, entonces el Asesor Experto (EA) no puede abrir la pr\u00f3xima posici\u00f3n.<br>\n          Si <strong>Martin = 2<\/strong>, entonces el primer lote = 0.1, el segundo lote = 0.2, y as\u00ed sucesivamente: 0.4 \u2013 0.8 \u2013 1.6 \u2013 3.2 \u2013 6.4\u2026<br>\n          Si <strong>Martin = 0.5<\/strong>, entonces el primer lote = 1, el segundo lote = 0.5, y as\u00ed sucesivamente: 0.25 \u2013 0.125.<br><br>\n          <strong>Atenci\u00f3n<\/strong>: La l\u00ednea media se calcular\u00e1 usando la f\u00f3rmula basada en los lotes.<br>\n          Esto permite acercar el nivel de BreakEven (l\u00ednea media) al precio actual.<br><br>\n          Sin embargo, el martingala puede ser peligroso para tu cuenta.<br>\n          Por favor, calcula este par\u00e1metro de manera que tu dep\u00f3sito pueda soportar tal carga.\n        <\/td><\/tr><tr><td><strong>LotAdditional<\/strong><\/td><td>\n          <strong>Lote (Volume) adicional para la pr\u00f3xima posici\u00f3n de promediado.<\/strong><br>\n          Por <strong>ejemplo<\/strong>:<br>\n          Lote inicial (Volume) de la posici\u00f3n principal = 0.1;<br>\n          <strong>LotAdditional = 0.05, entonces<\/strong><br>\n          El pr\u00f3ximo lote de la posici\u00f3n de promediado abierta ser\u00e1 0.15, 0.2, 0.25, y as\u00ed sucesivamente.\n        <\/td><\/tr><tr><td><strong>LotDifferent<\/strong><\/td><td>\n          <strong>Lotes, separados por comas para operaciones de promediado;<\/strong><br>\n          Puedes especificar los valores de lote deseados en el formato: <strong>xx.xx, yy.yy, zz.zz, aa.aa<\/strong><br>\n          donde:<br>\n          xx.xx &#8211; Lote para abrir la primera posici\u00f3n de promediado;<br>\n          yy.yy &#8211; Lote para abrir la segunda posici\u00f3n de promediado;<br>\n          zz.zz &#8211; Lote para abrir la tercera posici\u00f3n de promediado;<br>\n          aa.aa &#8211; Lote para abrir la cuarta y posteriores posiciones de promediado;<br><br>\n          <strong>El \u00faltimo n\u00famero en la l\u00ednea = Lote (Volume) de todas las posiciones subsecuentes.<\/strong><br>\n          <strong>Puedes especificar cualquier n\u00famero de lotes.<\/strong>\n        <\/td><\/tr><tr><td><strong>LotMax<\/strong><\/td><td>\n          <strong>El lote (Volume) m\u00e1ximo que se establecer\u00e1 cuando se abra una posici\u00f3n de promediado.<\/strong><br>\n          0 &#8211; deshabilitado\n        <\/td><\/tr><tr><td><strong>CloseAveragingAfterCloseMainDeals<\/strong><\/td><td>\n          <strong>El EA puede cerrar posiciones de promediado (abiertas contra la tendencia) cuando se cierren las posiciones principales.<\/strong><br>\n          La funci\u00f3n cerrar\u00e1 posiciones de promediado solo cuando todas las posiciones principales (para el s\u00edmbolo y n\u00famero m\u00e1gico actuales) est\u00e9n cerradas!<br><br>\n          <strong>Atenci\u00f3n<\/strong>: La nueva funci\u00f3n funciona por separado para las direcciones BUY y SELL!\n        <\/td><\/tr><tr><td colspan=\"2\">\n          <h2>Configuraciones Adicionales<\/h2>\n        <\/td><\/tr><tr><td><strong>ADDITIONALDistance<\/strong><\/td><td>\n          <strong>La distancia para abrir posiciones en la cuadr\u00edcula adicional.<\/strong><br>\n          Despu\u00e9s de cu\u00e1ntos puntos en la tendencia abrir la pr\u00f3xima posici\u00f3n adicional (Deal).<br><br>\n          Puedes establecer <strong>50<\/strong> puntos (Pips).<br>\n          Luego, cada nueva posici\u00f3n adicional (Deal) se abrir\u00e1 despu\u00e9s de 100 + 50 puntos de p\u00e9rdida desde la \u00faltima posici\u00f3n abierta. <strong>(100,150,200,250,300)<\/strong>\n        <\/td><\/tr><tr><td><strong>ADDITIONALDistanceMartin<\/strong><\/td><td>\n          <strong>El multiplicador para la distancia desde las posiciones adicionales para cada operaci\u00f3n.<\/strong><br><br>\n          Puedes establecer 50 puntos (Pips).<br>\n          Luego, cada nueva posici\u00f3n adicional (Deal) se abrir\u00e1 despu\u00e9s de 100 + 50 puntos de p\u00e9rdida desde la \u00faltima posici\u00f3n abierta. <strong>(100,150,200,250,300)<\/strong>\n        <\/td><\/tr><tr><td><strong>ADDITIONALDistanceAdditionalPoint<\/strong><\/td><td>\n          <strong>Puntos (Pips) adicionales para calcular la distancia.<\/strong><br>\n          Si <strong>ADDITIONALDistanceAdditionalPoint<\/strong> = 5, entonces se a\u00f1aden 5 puntos (Pips) a cada distancia subsecuente.<br>\n          Si el n\u00famero anterior de operaciones = 3, entonces puntos (Pips) adicionales para la distancia = 5 * 3 = 15 puntos adicionales (Pips).\n        <\/td><\/tr><tr><td><strong>ADDITIONALDistanceMax<\/strong><\/td><td>\n          <strong>El n\u00famero m\u00e1ximo de puntos (Pips) para la distancia.<\/strong><br>\n          Si, al calcular la distancia, el valor obtenido excede <strong>ADDITIONALDistanceMax<\/strong>, entonces el Asesor Experto (EA) usar\u00e1 <strong>ADDITIONALDistanceMax<\/strong> en Puntos (Pips).\n        <\/td><\/tr><tr><td><strong>ADDITIONALDistanceDifferent<\/strong><\/td><td>\n          <strong>Distancias para nuevas posiciones adicionales (en la tendencia),<\/strong><br>\n          separadas por comas.<br>\n          Puedes especificar valores de distancia en el formato: <strong>xx, yy, zz, aa<\/strong><br>\n          <strong>D\u00f3nde:<\/strong><br>\n          xx &#8211; Distancia en puntos para abrir la primera posici\u00f3n <strong>adicional<\/strong>;<br>\n          yy &#8211; Distancia en puntos para abrir la segunda posici\u00f3n <strong>adicional<\/strong>;<br>\n          zz &#8211; Distancia en puntos para abrir la tercera posici\u00f3n <strong>adicional<\/strong>;<br>\n          aa &#8211; Distancia en puntos para abrir la cuarta y posteriores posiciones <strong>adicionales<\/strong>;<br><br>\n          <strong>El \u00faltimo n\u00famero en la l\u00ednea = distancia para todas las posiciones subsecuentes.<\/strong><br>\n          <strong>Puedes establecer cualquier n\u00famero de distancias.<\/strong>\n        <\/td><\/tr><tr><td><strong>ADDITIONALStopLoss<\/strong><\/td><td>\n          <strong>Stop Loss para la posici\u00f3n adicional a abrir,<\/strong><br>\n          <strong>Nota<\/strong>: Cada posici\u00f3n adicional se abrir\u00e1 inicialmente con su propio Stop Loss.<br>\n          El Stop Loss se establecer\u00e1 a una distancia de <strong>ADDITIONALStopLoss<\/strong> puntos desde el precio de apertura de la posici\u00f3n de promediado.\n        <\/td><\/tr><tr><td><strong>ADDITIONALTakeProfit<\/strong><\/td><td>\n          <strong>Take Profit para la posici\u00f3n adicional a abrir,<\/strong><br>\n          <strong>Nota<\/strong>: Cada posici\u00f3n adicional se abrir\u00e1 inicialmente con su propio Take Profit.<br>\n          El Take Profit se establecer\u00e1 a una distancia de <strong>ADDITIONALTakeProfit<\/strong> puntos desde el precio de apertura de la posici\u00f3n de promediado.\n        <\/td><\/tr><tr><td><strong>ADDITIONALLotsMartin<\/strong><\/td><td>\n          <strong>Coeficiente: Incrementar el lote (Volume) para posiciones en la cuadr\u00edcula.<\/strong><br>\n          <strong>El coeficiente para incrementar los lotes de cada posici\u00f3n adicional subsecuente.<\/strong><br>\n          Por <strong>ejemplo<\/strong>:<br>\n          Lote Inicial (Volume) de la posici\u00f3n principal = 0.1<br>\n          <strong>LotsMartin = 2, entonces<\/strong><br>\n          El pr\u00f3ximo lote (Volume) de la posici\u00f3n adicional abierta ser\u00e1 0.2, 0.4, 0.8, y as\u00ed sucesivamente.<br><br>\n          <strong>Atenci\u00f3n<\/strong>: La l\u00ednea media se calcular\u00e1 usando la f\u00f3rmula basada en los lotes.<br>\n          Esto permite acercar el nivel de BreakEven (l\u00ednea media) al precio actual.<br><br>\n          Sin embargo, el martingala puede ser peligroso para tu cuenta.<br>\n          Por favor, calcula este par\u00e1metro de manera que tu dep\u00f3sito pueda soportar tal carga.\n        <\/td><\/tr><tr><td><strong>ADDITIONALLotAdditional<\/strong><\/td><td>\n          <strong>Lote (Volume) adicional para la pr\u00f3xima posici\u00f3n adicional.<\/strong><br>\n          Por <strong>ejemplo<\/strong>:<br>\n          Lote inicial (Volume) de la posici\u00f3n principal = 0.1;<br>\n          <strong>LotAdditional = 0.05, entonces<\/strong><br>\n          El pr\u00f3ximo lote de la posici\u00f3n adicional abierta ser\u00e1 0.15, 0.2, 0.25, y as\u00ed sucesivamente.\n        <\/td><\/tr><tr><td><strong>ADDITIONALLotDifferent<\/strong><\/td><td>\n          <strong>Lotes, separados por comas para operaciones adicionales;<\/strong><br>\n          Puedes especificar los valores de lote deseados en el formato: <strong>xx.xx, yy.yy, zz.zz, aa.aa<\/strong><br>\n          donde:<br>\n          xx.xx &#8211; Lote para abrir la primera posici\u00f3n adicional;<br>\n          yy.yy &#8211; Lote para abrir la segunda posici\u00f3n adicional;<br>\n          zz.zz &#8211; Lote para abrir la tercera posici\u00f3n adicional;<br>\n          aa.aa &#8211; Lote para abrir la cuarta y posteriores posiciones adicionales;<br><br>\n          <strong>El \u00faltimo n\u00famero en la l\u00ednea = Lote (Volume) de todas las posiciones subsecuentes.<\/strong><br>\n          <strong>Puedes especificar cualquier n\u00famero de lotes.<\/strong>\n        <\/td><\/tr><tr><td><strong>ADDITIONALLotMax<\/strong><\/td><td>\n          <strong>El lote (Volume) m\u00e1ximo que se establecer\u00e1 cuando se abra una posici\u00f3n adicional.<\/strong><br>\n          0 &#8211; deshabilitado\n        <\/td><\/tr><tr><td><strong>CloseAdditionalAfterCloseMainDeals<\/strong><\/td><td>\n          <strong>Cerrar posiciones adicionales abiertas (abiertas con la tendencia) cuando se cierren las posiciones principales.<\/strong><br><br>\n          La funci\u00f3n cerrar\u00e1 posiciones de apertura adicional solo cuando todas las posiciones principales (para el s\u00edmbolo y n\u00famero m\u00e1gico actuales) est\u00e9n cerradas!<br><br>\n          <strong>Atenci\u00f3n<\/strong>: La nueva funci\u00f3n funciona por separado para las direcciones BUY y SELL!\n        <\/td><\/tr><tr><td colspan=\"2\">\n          <h2>Configuraciones de Filtro<\/h2>\n        <\/td><\/tr><tr><td><strong>OrderToAverage<\/strong><\/td><td>\n          <strong>El tipo de posiciones que nuestro Asesor Experto (EA) monitorea.<\/strong><br>\n          El tipo de orden para el Asesor Experto (Expert Advisor),<br>\n          <strong>All = -1, = Todas las Posiciones<\/strong>;<br>\n          <strong>BUY = 0, = Solo BUY<\/strong>;<br>\n          <strong>SELL = 1, = Solo SELL<\/strong>.\n        <\/td><\/tr><tr><td><strong>MagikToAverage<\/strong><\/td><td>\n          <strong>El n\u00famero m\u00e1gico (magic number) de las posiciones que nuestro Asesor Experto (EA) monitorea.<\/strong><br>\n          <strong>\u00a1Soporta m\u00faltiples n\u00fameros m\u00e1gicos!<\/strong><br><br>\n          MagicNumber: N\u00famero m\u00e1gico de posiciones (operaciones) para seguimiento.<br>\n          MagicNumber: Los n\u00fameros m\u00e1gicos pueden especificarse y separarse por comas:<br>\n          <strong>0<\/strong> &#8211; \u00f3rdenes abiertas manualmente;<br>\n          <strong>123,345,147<\/strong> &#8211; todas las posiciones con n\u00fameros MagicNumber 123,345,147;<br>\n          <strong>-1<\/strong> &#8211; todos los MagicNumbers, sin excepci\u00f3n.\n        <\/td><\/tr><tr><td colspan=\"2\">&nbsp;<\/td><\/tr><tr><td><strong>MarketWatch<\/strong><\/td><td>\n          <strong>Para posiciones abiertas con Stop Loss \/ Take Profit en una cuenta con ejecuci\u00f3n MARKET.<\/strong><br>\n          Primero, el EA puede abrir una posici\u00f3n (Deal), y despu\u00e9s de abrirla exitosamente, modifica los niveles de Stop Loss y Take Profit para esta posici\u00f3n (deal).\n        <\/td><\/tr><tr><td><strong>SleepForOpenbetweenLastClose<\/strong><\/td><td><strong>El n\u00famero de segundos de retraso en el promediado despu\u00e9s de la \u00faltima posici\u00f3n cerrada.<\/strong><\/td><\/tr><tr><td><strong>OpenOnly1ofBar<\/strong><\/td><td><strong>Abrir solo una posici\u00f3n de promediado por barra actual (Depende del TF).<\/strong><\/td><\/tr><tr><td colspan=\"2\">\n          <h2>Configuraciones de Trailing Stop<\/h2>\n        <\/td><\/tr><tr><td><strong>TrailingStopUSE<\/strong><\/td><td>\n          <strong>Funci\u00f3n est\u00e1ndar de trailing stop.<\/strong><br><br>\n          <strong>Nota<\/strong>: Si las posiciones de promediado o adicionales est\u00e1n habilitadas (true):<br>\n          Si abres 2 o m\u00e1s posiciones, el Asesor Experto (EA) activa la funci\u00f3n de trailing stop desde la l\u00ednea promedio, no desde el precio de apertura de la posici\u00f3n.<br>\n          El precio promedio se muestra en el gr\u00e1fico.<img decoding=\"async\" src=\"https:\/\/www.expforex.com\/_pu\/1\/03316376.jpg\" style=\"\" alt=\"La funci\u00f3n de trailing stop est\u00e1ndar.\"><br><br>\n          <a href=\"https:\/\/expforex.com\/es\/functional-features-of-experts-from-www-expforex-com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Caracter\u00edsticas funcionales de los expertos de www.expforex.com<\/a>\n        <\/td><\/tr><tr><td><strong>TrailingStop<\/strong><\/td><td>\n          <strong>Distancia en puntos desde el precio actual al Stop Loss.<\/strong><br>\n          Si la ganancia actual es de 200 Puntos (Pips), y TrailingStop = 100, entonces el Stop Loss se establecer\u00e1 en +100 puntos.<br><br>\n          As\u00ed, el precio tiene la posibilidad de un retroceso de un m\u00e1ximo de 100 Puntos (Pips).<br>\n          De lo contrario, el Stop Loss funcionar\u00e1, y la posici\u00f3n se cerrar\u00e1 en +100 Puntos (Pips).\n        <\/td><\/tr><tr><td><strong>TrailingStep<\/strong><\/td><td>Paso del Stop Loss cuando la funci\u00f3n de trailing stop est\u00e1 habilitada.<\/td><\/tr><tr><td colspan=\"2\">&nbsp;<\/td><\/tr><tr><td><strong>MovingInWLUSE<\/strong><\/td><td>\n          <strong>Habilitar la funci\u00f3n break-even.<\/strong><br><br>\n          La funci\u00f3n modifica el Stop Loss por <strong>LevelWLoss<\/strong> puntos cuando la posici\u00f3n alcanza <strong>LevelProfit<\/strong> puntos de ganancia.<br>\n          <a href=\"https:\/\/expforex.com\/es\/functional-features-of-experts-from-www-expforex-com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Caracter\u00edsticas funcionales de los expertos de www.expforex.com<\/a><br><br><br>\n          Ejemplo:<br>\n          <strong>LevelWLoss = 50, LevelProfit = 200<\/strong><br>\n          Tan pronto como la posici\u00f3n acumule 200 puntos de ganancia, el Stop Loss de la posici\u00f3n se modificar\u00e1 al precio de apertura de la posici\u00f3n (+ spread) + 50 puntos.<br><br>\n          Ejemplo:<br>\n          <strong>LevelWLoss = 0, LevelProfit = 100<\/strong><br>\n          Tan pronto como la posici\u00f3n acumule 100 puntos de ganancia, el Stop Loss de la posici\u00f3n se modificar\u00e1 al precio de apertura de la posici\u00f3n (+ spread).<br><br>\n          <strong>Atenci\u00f3n<\/strong>: Si la funci\u00f3n de promediado o adicional est\u00e1 habilitada (true):<br>\n          Cuando abres 2 o m\u00e1s posiciones, el asesor activa la funci\u00f3n break-even desde la l\u00ednea promedio, no desde el precio de apertura de las posiciones.\n        <\/td><\/tr><tr><td><strong>LevelWLoss<\/strong><\/td><td>\n          El nivel de ganancia (<strong>LevelWLoss<\/strong>) en puntos al cual el Stop Loss se establece cuando esta funci\u00f3n est\u00e1 habilitada.<br><br>\n          1 = 1 punto de ganancia;<br>\n          0 = Modo de ganancia m\u00ednima autom\u00e1tica.<br>\n          Si es 0, entonces el n\u00famero de puntos de ganancia para el break-even (Stop Loss en el Punto de equilibrio) = Spread del par de divisas actual.\n        <\/td><\/tr><tr><td><strong>LevelProfit<\/strong><\/td><td>\n          El n\u00famero de puntos de ganancia (<strong>LevelProfit<\/strong>) que ha acumulado la posici\u00f3n para establecer un <strong>Stop Loss<\/strong> en los <strong>LevelWLoss<\/strong> puntos de ganancia (Pips).<br>\n          <strong>LevelProfit debe ser mayor que LevelWLoss.<\/strong>\n        <\/td><\/tr><tr><td>&nbsp;<\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"4\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-preguntas-y-respuestas-frecuentes-sobre-exp-averager\">Preguntas y respuestas frecuentes sobre Exp Averager<\/h2>\n\n\n\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-86564\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-86564 eb_animation eb___animated eb___fadeIn\"><div class=\"eb-infobox-86564 eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><img decoding=\"async\" class=\"eb-infobox-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/Expforex-FAQ.png\" alt=\"\"\/><\/div><\/div><div class=\"contents-wrapper\"><h6 class=\"title\">Preguntas Frecuentes Generales<\/h6><p class=\"description\">Respuestas a las preguntas m\u00e1s populares<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor hvr-pulse infobox-btn  hvr-pulse\" href=\"https:\/\/expforex.com\/es\/?p=293\" target=\"_blank\" rel=\"noopener\">Click Me!<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 valores tienen los par\u00e1metros en puntos o pips?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1En puntos! El valor se toma de la variable <strong>Point()<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Si tienes un broker de 5 o 3 d\u00edgitos, entonces 1 punto = 0.00001 o 0.001<\/li>\n\n\n\n<li class=\"\">Si tienes un broker de 4 o 2 d\u00edgitos, entonces 1 punto = 0.0001 o 0.01<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ingresas el valor requerido (en el campo) de acuerdo con tu broker particular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay mucho debate sobre qu\u00e9 es un punto y qu\u00e9 es un pip.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo uso valores universales (<strong>Point = Pips<\/strong>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estos valores son iguales a los valores de tu broker.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Cuando establezco TakeProfitAll = 100, veo que las l\u00edneas de TP se modifican instant\u00e1neamente. \u00bfPodr\u00edas explicar por qu\u00e9? Mientras que deben ser est\u00e1ticas desde la l\u00ednea media.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a1Has especificado un nivel de Take Profit \/ Stop Loss \/ Trailing Stop que est\u00e1 por debajo de lo permitido en el servidor de tu broker!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo tanto, el asesor Averager calcula el nivel m\u00ednimo de orden de stop (<strong>StopLevel<\/strong>) y modifica el Take Profit \/ Stop Loss \/ Trailing Stop de acuerdo con las reglas de tu broker (Especificaciones del Contrato).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tu cuenta tiene un spread flotante, entonces los niveles m\u00ednimos de Stop Loss y Take Profit cambian con cada cambio de precio (Tick).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debes establecer un Take Profit que sea mayor que el nivel m\u00ednimo de orden de stop permitido (<strong>StopLevel<\/strong>) en tu servidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O deshabilita la funci\u00f3n autom\u00e1tica de detecci\u00f3n de <strong>StopLevel<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Normaliza autom\u00e1ticamente todos los par\u00e1metros del Asesor Experto (Expert Advisor) a los niveles m\u00ednimos de stop aceptables.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con <strong>stops<\/strong> virtuales &#8211; este par\u00e1metro no se aplica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con <strong>AutoSetMinLevel<\/strong>, los niveles de stop se establecer\u00e1n en los niveles m\u00e1s bajos permitidos por el servidor;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>Si el nivel de Stop Loss o Take Profit est\u00e1 por debajo del nivel m\u00ednimo de stop del servidor, entonces el nivel de Stop Loss\/Take Profit = Nivel de Stop M\u00ednimo (Spread * 2 o nivel fijo en el servidor) + Spread.<\/mark><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al usar <strong>ManualSet<\/strong>, el usuario recibir\u00e1 un mensaje de que los niveles de stop del EA est\u00e1n por debajo del m\u00ednimo, y el EA recibir\u00e1 un error del servidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark>Si el nivel de stop del servidor es flotante, entonces el nivel de stop m\u00ednimo se calcula autom\u00e1ticamente como = Spread * 2.<\/mark><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo se calculan el precio promedio y el Stop Loss \/ Take Profit total? \u00bfPor qu\u00e9 el EA establece el Take Profit en 36 pips en lugar de 25 pips?<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Precio Promedio<\/strong> = (1.08191 + 1.08141) \/ 2 = <strong>1.08166<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TakeProfit<\/strong> Precio promedio = 1.08166 &#8211; 36 = <strong>1.08130<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(porque 25 &lt; MinStop si es flotante) MinStop = 3 * Spread = 36<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>StopLoss<\/strong> Precio promedio = 1.08166 + 200 = <strong>1.08366<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1080\" height=\"804\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/2024-03-27_18-41-35-1.png\" alt=\"Averager: \u00a1Has especificado un nivel de Take Profit \/ Stop Loss \/ Trailing Stop que es menor de lo permitido en el servidor de tu broker!\" class=\"wp-image-8202\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/2024-03-27_18-41-35-1.png 1080w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/2024-03-27_18-41-35-1-500x372.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/2024-03-27_18-41-35-1-300x223.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/2024-03-27_18-41-35-1-768x572.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/2024-03-27_18-41-35-1-101x75.png 101w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/2024-03-27_18-41-35-1-700x521.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 es la Estrategia de Promedio (Averaging Strategy) en el trading de Forex?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>Estrategia de Promedio (Averaging Strategy)<\/strong> implica abrir posiciones adicionales en contra de la tendencia a medida que el precio se aleja de tu posici\u00f3n inicial, con el objetivo de reducir el precio de entrada general y alcanzar el <strong>punto de equilibrio (break-even point)<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo funciona la Apertura Adicional (Additional Opening) con la tendencia?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Apertura Adicional (Additional Opening)<\/strong> se refiere a abrir m\u00e1s posiciones en la direcci\u00f3n de la tendencia, aprovechando los movimientos favorables del mercado para maximizar las ganancias potenciales. Por ejemplo, abrir una segunda posici\u00f3n de COMPRA (BUY) a un precio m\u00e1s alto para ajustar el <strong>punto de equilibrio (break-even point)<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1les son las diferencias clave entre la Estrategia de Promedio (Averaging) y la Apertura Adicional (Additional Opening)?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrategia de Promedio (Averaging)<\/strong> implica abrir posiciones en contra de la tendencia para reducir el precio de entrada promedio, mientras que <strong>Apertura Adicional (Additional Opening)<\/strong> implica a\u00f1adir posiciones en la direcci\u00f3n de la tendencia para capitalizar los movimientos favorables.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo ayuda el Asesor Experto (EA) en la Estrategia de Promedio (averaging)?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Asesor Experto (EA)<\/strong> automatiza el proceso de promedio abriendo posiciones adicionales basadas en par\u00e1metros predefinidos, gestionando el <strong>Trailing Stop<\/strong>, y ajustando los niveles de <strong>Take Profit<\/strong> para optimizar el rendimiento del trading.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1l es el prop\u00f3sito del Trailing Stop en la estrategia de promedio?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La funci\u00f3n de <strong>Trailing Stop<\/strong> mueve el nivel de <strong>Stop Loss<\/strong> en la direcci\u00f3n de la ganancia a medida que el mercado se mueve favorablemente, ayudando a asegurar las ganancias y minimizar las p\u00e9rdidas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo debo determinar la Distancia de Promedio (Averaging Distance)?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>Distancia de Promedio (Averaging Distance)<\/strong> debe calcularse basada en el movimiento promedio del par de divisas y el saldo de tu cuenta. Esto asegura que tu cuenta pueda soportar las posiciones adicionales sin arriesgar una p\u00e9rdida total.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1les son los riesgos asociados con la Estrategia Martingala (Martingale Strategy) en el promedio?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>Estrategia Martingala (Martingale Strategy)<\/strong> aumenta el tama\u00f1o del lote con cada posici\u00f3n adicional, lo que puede llevar a p\u00e9rdidas significativas si el mercado contin\u00faa movi\u00e9ndose en contra de tu posici\u00f3n inicial. Es crucial calcular los par\u00e1metros cuidadosamente para gestionar el riesgo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo instalo y configuro el Exp-Averager?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Para instalar el <strong>Exp-Averager<\/strong>, abre el gr\u00e1fico del par de divisas deseado, instala el Asesor Experto, y configura los par\u00e1metros como <strong>Distancia (Distance)<\/strong>, <strong>TakeProfit<\/strong>, y <strong>StopLoss<\/strong> de acuerdo con tu estrategia de trading.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 par\u00e1metros se pueden optimizar en el Exp-Averager?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Par\u00e1metros como <strong>TakeProfitALL<\/strong>, <strong>Distancia (Distance)<\/strong>, <strong>DistanceMartin<\/strong>, <strong>LotsMartin<\/strong>, y <strong>MaxOrdersOpen<\/strong> pueden optimizarse para mejorar el rendimiento de la estrategia de promedio.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo funciona el N\u00famero M\u00e1gico (Magic Number) en la configuraci\u00f3n del EA?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>N\u00famero M\u00e1gico (Magic Number)<\/strong> identifica de manera \u00fanica las posiciones abiertas por el EA, permiti\u00e9ndole gestionar y rastrear solo esas operaciones sin interferir con posiciones abiertas manualmente.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfPuedo probar el Exp-Averager antes de usarlo en vivo?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, puedes usar el <strong>Tester de Estrategia (Strategy Tester)<\/strong> en tu terminal de trading para realizar backtesting del <strong>Exp-Averager<\/strong> y optimizar sus configuraciones antes de desplegarlo en una cuenta en vivo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 debo considerar al configurar los niveles de StopLoss y TakeProfit?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Configura los niveles de <strong>StopLoss<\/strong> y <strong>TakeProfit<\/strong> basados en la <strong>Distancia de Promedio (Averaging Distance)<\/strong> y tu estrategia de gesti\u00f3n de riesgos para asegurar que el EA pueda gestionar efectivamente las operaciones y proteger tu cuenta de p\u00e9rdidas excesivas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo maneja el EA la Comisi\u00f3n y el Swap?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El EA considera los costos de <strong>Comisi\u00f3n<\/strong> y <strong>Swap<\/strong> al calcular el <strong>Punto de Equilibrio (BreakEven)<\/strong> y el <strong>Trailing Stop<\/strong>, asegurando que estos costos sean tenidos en cuenta para evitar p\u00e9rdidas innecesarias.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1l es el rol de MaxOrdersOpen en la configuraci\u00f3n del EA?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MaxOrdersOpen<\/strong> limita el n\u00famero de posiciones adicionales de promedio que el EA puede abrir, ayudando a controlar la carga en tu dep\u00f3sito y gestionar el riesgo efectivamente.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo puedo personalizar los tama\u00f1os de los lotes para las posiciones de promedio?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes personalizar los tama\u00f1os de los lotes usando par\u00e1metros como <strong>LotsMartin<\/strong>, <strong>LotAdditional<\/strong>, y <strong>LotDifferent<\/strong>, permiti\u00e9ndote definir c\u00f3mo el tama\u00f1o del lote aumenta o disminuye con cada posici\u00f3n adicional.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 informaci\u00f3n se muestra en el Panel EAPADPRO?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Panel EAPADPRO<\/strong> muestra informaci\u00f3n clave como <strong>Promedio de COMPRA \/ Lote (BUY Average \/ Lot)<\/strong>, <strong>Promedio de VENTA \/ Lote (SELL Average \/ Lot)<\/strong>, <strong>Precio M\u00ednimo\/M\u00e1ximo (Min\/Max Price)<\/strong> para operaciones de COMPRA y VENTA, y el <strong>Precio Promedio (Average Price)<\/strong> para ambas direcciones.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo gestiona el EA el Stop Loss al usar promedio?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El EA modifica el <strong>Stop Loss<\/strong> al <strong>punto de equilibrio (break-even point)<\/strong> una vez que el precio se mueve una cierta distancia a favor de la operaci\u00f3n, ayudando a asegurar las ganancias y minimizar las p\u00e9rdidas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfPara qu\u00e9 se utiliza el par\u00e1metro OrderToAverage?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El par\u00e1metro <strong>OrderToAverage<\/strong> especifica el tipo de posiciones que el EA monitorea para el promedio, como todas las posiciones, solo \u00f3rdenes de COMPRA (BUY), o solo \u00f3rdenes de VENTA (SELL).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfPuede el EA manejar m\u00faltiples N\u00fameros M\u00e1gicos (Magic Numbers)?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, el EA soporta m\u00faltiples <strong>N\u00fameros M\u00e1gicos (Magic Numbers)<\/strong>, permiti\u00e9ndole gestionar posiciones a trav\u00e9s de diferentes estrategias o sistemas de trading simult\u00e1neamente.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1l es la configuraci\u00f3n recomendada de StopLoss al usar promedio?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Se recomienda establecer un <strong>StopLoss<\/strong> de 5 distancias de promedio y limitar el n\u00famero de posiciones de promedio a un m\u00e1ximo de 5 para equilibrar el riesgo y el potencial de ganancia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo asegura el EA que no exceda el Nivel M\u00ednimo de Stop del br\u00f3ker?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El EA puede normalizar autom\u00e1ticamente todos los par\u00e1metros para cumplir con el <strong>Nivel M\u00ednimo de Stop (Minimum Stop Level)<\/strong> del br\u00f3ker utilizando las configuraciones <strong>SetMinStops<\/strong> o <strong>AutoSetMinLevel<\/strong>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"5\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-registro-exp-averager\">Registro Exp Averager<\/h2>\n\n\n\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"6\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-resenas-sobre-exp-averager\">Rese\u00f1as sobre Exp Averager<\/h2>\n\n\n\n<div class=\"wp-block-columns has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background has-medium-font-size is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<div class=\"wp-block-essential-blocks-icon  root-eb-icon-0uyx4\"><div class=\"eb-parent-wrapper eb-parent-eb-icon-0uyx4 \"><div class=\"eb-icon-wrapper eb-icon-0uyx4 eb-icon-view-default\" data-id=\"eb-icon-0uyx4\"><div class=\"eb-icon-container\"><i icon=\"fas fa-star\" class=\"fas fa-star \"><\/i><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-large-font-size is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p align=\"center\">\u00a1Gracias por tus comentarios!<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><div class=\"testimonials_list \"><div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/excr-mql5-avatar-7301-e31c661b1b-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/excr-mql5-avatar-7301-e31c661b1b-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/excr-mql5-avatar-7301-e31c661b1b.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/excr-mql5-avatar-7301-e31c661b1b.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/excr-mql5-avatar-7301-e31c661b1b.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/excr-mql5-avatar-7301-e31c661b1b-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/excr-mql5-avatar-7301-e31c661b1b-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112?source=Site+Profile+Seller\">220072256<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote><p>Great program, and the author&#039;s support is fantastic!!!<\/p>\n<hr>\n<p><strong>Reply from ExpForex:<\/strong><br \/>Thank you<\/p>\n<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112?source=Site+Profile+Seller#!tab=reviews\">Wepa11<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Best ever I seen<hr \/><div style=\"text-align: center; margin: 10px 0;\"><img decoding=\"async\" title=\"Vladislav Expforex\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/LOGONEW-2024-2.png\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/LOGONEW-2024-2.png\" alt=\"Vladislav Expforex\" width=\"60\" height=\"60\"><\/div><strong>Reply from ExpForex:<\/strong><br>Thank you. \ud83d\ude0a<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289?source=Unknown#!tab=reviews\">RBC1234 <\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Although this utility was released a few years ago, I only recently became interested in it. I bought it because, unfortunately, I can't trust the results of demo versions, which are often very questionable. This isn't the case with this utility. It's running on a demo account and has very interesting results. It's an honest program, with great capabilities, and the developer is very attentive and honest with buyers. I've read all the reviews and comments carefully, and the explanations were always quick, thorough, and clear. It's well worth the price. I recommend purchasing it. Excellent!<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289?source=Site+Profile+Seller#\">RBC1234<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Although this utility was released a few years ago, I only recently became interested in it. I bought it because, unfortunately, I can't trust the results of demo versions, which are often very questionable. This isn't the case with this utility. It's running on a demo account and has very interesting results. It's an honest program, with great capabilities, and the developer is very attentive and honest with buyers. I've read all the reviews and comments carefully, and the explanations were always quick, thorough, and clear. It's well worth the price. I recommend purchasing it. Excellent!<hr \/><div style=\"text-align: center; margin: 10px 0;\"><img decoding=\"async\" title=\"Vladislav Expforex\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/LOGONEW-2024-2.png\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/LOGONEW-2024-2.png\" alt=\"Vladislav Expforex\" width=\"60\" height=\"60\"><\/div><strong>Reply from ExpForex:<\/strong><br>Thank you \ud83d\ude42<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289?source=Site+Profile+Seller#!tab=reviews\">bubay123 <\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>very good and profitable.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">adrazz <\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>adrazz \r\nAwesome EA, just what I was looking for.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/08\/avatar_na2-2.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/08\/avatar_na2-2.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289?source=Site+Profile+Seller#!tab=reviews\">bubay123<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>bubay123 \r\n\r\n<hr \/>\r\n\r\nvery good and profitable.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item no-img\"><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Atila R Akdeniz<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Atila R Akdeniz \r\n\r\n<hr \/>\r\n\r\nAs always, extremely useful Utility and excellent support from Vladislav.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">DNkRockzzzzZ<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>DNkRockzzzzZ \r\n\r\n<hr \/>\r\n\r\ngood tool<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6273E629-7236_big-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Munir Sayed Yousef Ibrahim<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Munir Sayed Yousef Ibrahim \r\n<hr \/>\r\n\r\nIts really Nice software but if You have some heavy indicator on the same chart this Program might Lag in Speed otherwise it will work Just fine its a great tool, Thank You<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289\">Alex<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Alex \r\n\r\n<hr \/>\r\n\r\nSurvey should be done after one month or later not two days later. Anyway I bought before Close Minus by Plus (now is free) from the same author and is an EXCELLENT piece of work so I give the author 5 stars in advance because: 1) his work has quality, 2) his ideas superb 3) This is honest work and price 4) The graphic EAPAD is nice and usefull 5) Finally I will be able to automatize the strategy of averaging against the trend that I use much more easily with pluses as trailing or break even that are not possible to do manually the same way. Very good you can choose to close the cycle or renew it. Thanks Vladislav for sharing your talent!<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5E980B6E-192D_big-1-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1289\">jc-hakuna-matata<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>jc-hakuna-matata \r\n\r\n<hr \/>\r\n\r\nexcellent tool<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/60DB4A0A-4003_big-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">skyparc<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>skyparc \r\n\r\n<hr \/>\r\n\r\nThank you Vlad, for Update BreakEven WithoutLOSS options in meta 5 version, now is great, also I am using VirtualTradePad another briliant and perfect usefull tool<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/609DDE48-9B08_big-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Jakote Molemi<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Jakote Molemi\r\n\r\n<hr \/>\r\n\r\nHello Vladislav, great program and very useful. There is a small hickup on the operation; please assist: Each time I update parameters (especially setting new levels for averaging), the program takes very very long time to test and update, how can I fix this trouble?\r\n\r\nI cannot attach a screenshot here you have disabled an option to reply to you and I do not know any other channel to reach you except here.\r\n<div class=\"user\">\r\n<div class=\"frame\">\r\n<div class=\"bg\"><img decoding=\"async\" title=\"Vladislav Andruschenko\" src=\"https:\/\/c.mql5.com\/avatar\/2022\/12\/63ac7246-191a.png\" srcset=\"https:\/\/c.mql5.com\/avatar\/2022\/12\/63ac7246-191a_big.png 2x\" alt=\"Vladislav Andruschenko\" width=\"60\" height=\"60\" \/><\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"review_reply__content\"><span class=\"review_reply__author\"><i class=\"icons-ux icons-ux_reply\"><\/i>Reply from developer\u00a0<strong><a class=\"author\" href=\"https:\/\/www.mql5.com\/en\/users\/vladon\">Vladislav <\/a><\/strong><\/span><span class=\"review_reply__date_link\"><span class=\"review_reply__date_created\" title=\"2021.06.08 17:36\">2021.06.08 17:36<\/span><\/span><\/div>\r\n<div class=\"review_reply__content\">\r\n<div id=\"reviewReplyContentBlock_184013\" class=\"review_reply__description\">Hello. Thank you. I didn't understand your mistake. are you talking about the eapadpro panel? it is updated every 10 seconds so as not to slow down the schedule. this does not affect the algorithm. please attach a screenshot or log files with the error to the discussion.<\/div>\r\n<\/div><\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/1112\">Vitali Lebianok<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Vitali Lebianok \r\n\r\n<hr \/>\r\n\r\n\u043e\u0447\u0435\u043d\u044c \u043f\u043e\u043b\u0435\u0437\u043d\u0430\u044f \u0438 \u0445\u043e\u0440\u043e\u0448\u0430\u044f \u0443\u0442\u0438\u043b\u0438\u0442\u0430 \u043f\u043e\u0437\u0432\u043e\u043b\u044f\u044e\u0449\u0430\u044f \u0437\u0430\u0434\u0430\u0442\u044c \u0441\u0432\u043e\u044e \u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u0443\u044e \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u044e \u0438 \u0431\u0435\u0437 \u043b\u0438\u0448\u043d\u0438\u0445 \u0445\u043b\u043e\u043f\u043e\u0442 \u043f\u043e\u043b\u0443\u0447\u0430\u0442\u044c \u043f\u0440\u0438\u0431\u044b\u043b\u044c \u043d\u043e \u0432\u043d\u0438\u043c\u0430\u0442\u0435\u043b\u044c\u043d\u043e \u043e\u0442\u043d\u0435\u0441\u0438\u0442\u0435\u0441\u044c \u043f\u0440\u0438 \u043d\u0430\u0441\u0442\u0440\u043e\u0439\u043a\u0435 \u043a \u043f\u0440\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u044e \u0442\u0435\u0441\u0442\u043e\u0432 , \u0430 \u0442\u0430\u043a \u0436\u0435 \u0441\u043e\u0432\u0435\u0442\u0443\u044e \u0434\u043b\u044f \u043a\u0430\u0436\u0434\u043e\u0439 \u0432\u0430\u043b\u044e\u0442\u043d\u043e\u0439 \u043f\u0430\u0440\u044b \u0432\u044b\u0440\u0430\u0431\u0430\u0442\u044b\u0432\u0430\u0442\u044c \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u044b\u0435 \u043d\u0430\u0441\u0442\u0440\u043e\u0439\u043a\u0438 .\u0422\u0410\u041a \u0416\u0415 \u0445\u043e\u0447\u0443 \u0437\u0430\u043c\u0435\u0442\u0438\u0442\u044c \u0447\u0442\u043e \u0430\u0432\u0442\u043e\u0440 \u043e\u0447\u0435\u043d\u044c \u0431\u044b\u0441\u0442\u0440\u043e \u0438 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u043f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u0440\u0430\u0437\u043e\u0431\u0440\u0430\u0442\u044c\u0441\u044f \u0441\u043e \u0432\u0441\u0435\u043c\u0438 \u0441\u043b\u043e\u0436\u043d\u043e\u0441\u0442\u044f\u043c\u0438 \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043c\u043e\u0433\u0443\u0442 \u0432\u043e\u0437\u043d\u0438\u043a\u043d\u0443\u0442\u044c \u043f\u0440\u0438 \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043d\u0438\u0438 \u0445\u043e\u0442\u0435\u043b\u043e\u0441\u044c \u0431\u044b \u043f\u043e\u0441\u0442\u0430\u0432\u0438\u0442\u044c \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u043e 5 \u0437\u0432\u0435\u0437\u0434 \u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0443 \u043d\u043e \u0438 \u0440\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u0447\u0438\u043a\u0443 )<\/blockquote><\/div><\/div><\/div>\n<\/div>\n<a href=\"javascript:complaintInline(22437715,31,3,0)\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"javascript:void(false);\"><\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"7\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-comentarios-sobre-exp-averager\">Comentarios sobre Exp Averager<\/h2>\n\n\n\n<div class=\"wp-block-columns has-electric-grass-gradient-background has-background has-medium-font-size is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<div class=\"wp-block-essential-blocks-icon  root-eb-icon-u811s\"><div class=\"eb-parent-wrapper eb-parent-eb-icon-u811s \"><div class=\"eb-icon-wrapper eb-icon-u811s eb-icon-view-default\" data-id=\"eb-icon-u811s\"><div class=\"eb-icon-container\"><i icon=\"fas fa-comment\" class=\"fas fa-comment \"><\/i><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-large-font-size is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p align=\"center\">\u00bfTienes alguna pregunta?<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-comments has-white-background-color has-background\">\t<div id=\"respond\" class=\"comment-respond wp-block-post-comments-form\">\n\t\t<h3 id=\"reply-title\" class=\"comment-reply-title\">Leave a Reply <small><a rel=\"nofollow\" id=\"cancel-comment-reply-link\" href=\"\/es\/wp-json\/wp\/v2\/posts\/70254#respond\" style=\"display:none;\">Cancel reply<\/a><\/small><\/h3><form action=\"https:\/\/expforex.com\/wp-comments-post.php\" method=\"post\" id=\"commentform\" class=\"comment-form\"><p class=\"comment-notes\"><span id=\"email-notes\">Your email address will not be published.<\/span> <span class=\"required-field-message\">Required fields are marked <span class=\"required\">*<\/span><\/span><\/p><p class=\"comment-form-comment\"><label for=\"comment\">Comment <span class=\"required\">*<\/span><\/label> <textarea id=\"comment\" name=\"comment\" cols=\"45\" rows=\"8\" maxlength=\"65525\" required=\"required\"><\/textarea><\/p><input name=\"wpml_language_code\" type=\"hidden\" value=\"es\" \/><p class=\"comment-form-author\"><label for=\"author\">Name <span class=\"required\">*<\/span><\/label> <input id=\"author\" name=\"author\" type=\"text\" value=\"\" size=\"30\" maxlength=\"245\" autocomplete=\"name\" required=\"required\" \/><\/p>\n<p class=\"comment-form-email\"><label for=\"email\">Email <span class=\"required\">*<\/span><\/label> <input id=\"email\" name=\"email\" type=\"text\" value=\"\" size=\"30\" maxlength=\"100\" aria-describedby=\"email-notes\" autocomplete=\"email\" required=\"required\" \/><\/p>\n<p class=\"comment-form-url\"><label for=\"url\">Website<\/label> <input id=\"url\" name=\"url\" type=\"text\" value=\"\" size=\"30\" maxlength=\"200\" autocomplete=\"url\" \/><\/p>\n<p class=\"comment-form-cookies-consent\"><input id=\"wp-comment-cookies-consent\" name=\"wp-comment-cookies-consent\" type=\"checkbox\" value=\"yes\" \/> <label for=\"wp-comment-cookies-consent\">Save my name, email, and website in this browser for the next time I comment.<\/label><\/p>\n<div class=\"excap-field\" data-excap-context=\"wp-comment\"><input type=\"text\" name=\"excap_hp\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" aria-hidden=\"true\" class=\"excap-hp\" \/><input type=\"hidden\" name=\"excap_context\" value=\"wp-comment\" \/><input type=\"hidden\" name=\"excap_started\" value=\"1788320192\" \/><div id=\"excap-wp-comment-990173\" class=\"excap-widget cf-turnstile\" data-sitekey=\"0x4AAAAAABufDnsNvmIbBbxd\" data-action=\"wp-comment\" data-theme=\"auto\" data-size=\"normal\" data-language=\"auto\" data-appearance=\"always\"><\/div><\/div><p class=\"form-submit\"><input name=\"submit\" type=\"submit\" id=\"submit\" class=\"submit\" value=\"Post Comment\" \/> <input type='hidden' name='comment_post_ID' value='70254' id='comment_post_ID' \/>\n<input type='hidden' name='comment_parent' id='comment_parent' value='0' \/>\n<\/p><\/form>\t<\/div><!-- #respond -->\n\t\n\n<h2 id=\"comments\" class=\"wp-block-comments-title\">4 responses to &#8220;Averager. Promediando posiciones de trading. \u00a1Apertura de operaciones contra la tendencia y en la tendencia!&#8221;<\/h2>\n\n<ol class=\"wp-block-comment-template\"><li id=\"comment-1708\" class=\"comment byuser comment-author-expforex bypostauthor even thread-even depth-1\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><div class=\"wp-block-avatar\"><img alt='Expforex Vladislav Avatar' src='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=40&#038;d=identicon&#038;r=r' srcset='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=80&#038;d=identicon&#038;r=r 2x' class='avatar avatar-40 photo wp-block-avatar__image' height='40' width='40'  style=\"border-radius:20px;\"\/><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-comment-author-name has-small-font-size\"><a rel=\"external nofollow ugc\" href=\"https:\/\/www.expforex.com\" target=\"_self\" >Expforex Vladislav<\/a><\/div>\n\n\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\" style=\"margin-top:0px;margin-bottom:0px\"><div class=\"wp-block-comment-date has-small-font-size\"><time datetime=\"2024-09-28T10:16:53+00:00\"><a href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/#comment-1708\">September 28, 2024<\/a><\/time><\/div>\n\n<\/div>\n\n\n<div class=\"wp-block-comment-content\"><p>Espa\u00f1ol. Averager. \u00a1Abriendo operaciones en contra de la tendencia y a favor de la tendencia!<br \/>\n<a href=\"https:\/\/youtu.be\/lmi5Bck0Pro\" rel=\"nofollow ugc\">https:\/\/youtu.be\/lmi5Bck0Pro<\/a><\/p>\n<p>AVERAGER \u2013 Apertura de posiciones adicionales en la tendencia y contra la tendencia con la funci\u00f3n del trailing stop general del beneficio.<br \/>\n???? GU\u00cdA COMPLETA de AVERAGER: <a href=\"https:\/\/www.expforex.com\/?p=25\" rel=\"nofollow ugc\">https:\/\/www.expforex.com\/?p=25<\/a><br \/>\n???? AVERAGER MT4: <a href=\"https:\/\/www.mql5.com\/es\/market\/product\/1289\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/es\/market\/product\/1289<\/a><br \/>\n???? AVERAGER MT5: <a href=\"https:\/\/www.mql5.com\/es\/market\/product\/1112\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/es\/market\/product\/1112<\/a><\/p>\n<p>00:00 Visi\u00f3n general<br \/>\n00:37 C\u00f3mo funciona Exp-Averager a favor de la tendencia<br \/>\n01:37 C\u00f3mo funciona Exp-Averager en contra de la tendencia<br \/>\n04:07 C\u00f3mo instalar Exp-Averager<br \/>\n04:54 C\u00f3mo probar Exp-Averager<\/p>\n<p>Ver en diferentes idiomas:<br \/>\n???? English: <a href=\"https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE<\/a><br \/>\n???? Espa\u00f1ol: <a href=\"https:\/\/www.youtube.com\/watch?v=lmi5Bck0Pro\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=lmi5Bck0Pro<\/a><br \/>\n???? Portugu\u00eas: <a href=\"https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk<\/a><br \/>\n???? Deutsch: <a href=\"https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w<\/a><br \/>\n???? Fran\u00e7ais: <a href=\"https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U<\/a><\/p>\n<p>Promediar posiciones con Exp-Averager:<br \/>\nEl Asesor Experto Averager es una poderosa herramienta de trading dise\u00f1ada para abrir posiciones adicionales tanto a favor de la tendencia como en contra de la tendencia. Su caracter\u00edstica clave es un trailing stop promedio inteligente para gestionar una serie de posiciones y ayudar a asegurar ganancias mientras el mercado se mueve.<\/p>\n<p>Caracter\u00edsticas principales:<\/p>\n<p>Incremento y decremento del lote (Volumen): Ajusta el tama\u00f1o del lote para cada posici\u00f3n, optimizando el riesgo.<br \/>\nEstrategia popular de promediado: Ideal para llevar posiciones no rentables al precio promedio y reducir p\u00e9rdidas.<br \/>\nTrailing Stop General: Un trailing stop que asegura beneficios en series de posiciones a medida que el mercado se mueve a favor del trader.<br \/>\nEstrategia Popular:<\/p>\n<p>Esta herramienta es ampliamente utilizada por traders que buscan llevar posiciones no rentables al precio promedio. Al abrir nuevas posiciones en la misma direcci\u00f3n, pero a diferentes niveles de precio, el trader puede reducir las p\u00e9rdidas al acercar el precio promedio al valor actual de mercado.<\/p>\n<p>Conclusi\u00f3n:<\/p>\n<p>El Asesor Experto Averager es una excelente soluci\u00f3n para traders que buscan optimizar sus estrategias de gesti\u00f3n de posiciones y beneficiarse de movimientos en el mercado. Con caracter\u00edsticas avanzadas como el trailing stop general, puede ayudar a maximizar las ganancias en series de posiciones.<\/p>\n<p>Hashtags:<br \/>\n#mql5 #mql4 #experto #EA #Expforex #forex #tradingforex #metatrader #metaquotes #mql #scalping #scalper #promediar #trading #acciones #mt5 #stopmovil #estrategiadetrading #estrategiaforex #Vladon #Expforex #herramientasdetrading #tradingautomatico #gesti\u00f3nderiesgos #rendimientotrading<\/p>\n<p>Palabras clave:<br \/>\nExp-Averager MT4, Exp-Averager MT5, herramienta de trading forex, promediar posiciones, trading a favor de la tendencia, trading en contra de la tendencia, trailing stop, ajuste del tama\u00f1o de lote, tama\u00f1o del volumen, Asesor Experto de MetaTrader, minimizar p\u00e9rdidas, gesti\u00f3n de beneficios, estrategias populares de trading, Vladon Expforex, automatizaci\u00f3n de trading, an\u00e1lisis t\u00e9cnico<\/p>\n<\/div>\n\n<div class=\"wp-block-comment-reply-link has-small-font-size\"><a rel=\"nofollow\" class=\"comment-reply-link\" href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/?replytocom=1708#respond\" data-commentid=\"1708\" data-postid=\"70254\" data-belowelement=\"comment-1708\" data-respondelement=\"respond\" data-replyto=\"Reply to Expforex Vladislav\" aria-label=\"Reply to Expforex Vladislav\">Reply<\/a><\/div><\/div>\n<\/div>\n\n<\/li><li id=\"comment-1709\" class=\"comment byuser comment-author-expforex bypostauthor odd alt thread-odd thread-alt depth-1\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><div class=\"wp-block-avatar\"><img alt='Expforex Vladislav Avatar' src='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=40&#038;d=identicon&#038;r=r' srcset='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=80&#038;d=identicon&#038;r=r 2x' class='avatar avatar-40 photo wp-block-avatar__image' height='40' width='40'  style=\"border-radius:20px;\"\/><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-comment-author-name has-small-font-size\"><a rel=\"external nofollow ugc\" href=\"https:\/\/www.expforex.com\" target=\"_self\" >Expforex Vladislav<\/a><\/div>\n\n\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\" style=\"margin-top:0px;margin-bottom:0px\"><div class=\"wp-block-comment-date has-small-font-size\"><time datetime=\"2024-09-28T10:15:22+00:00\"><a href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/#comment-1709\">September 28, 2024<\/a><\/time><\/div>\n\n<\/div>\n\n\n<div class=\"wp-block-comment-content\"><p>Portugu\u00eas. Averager. Abrindo neg\u00f3cios contra a tend\u00eancia e na tend\u00eancia!<br \/>\n<a href=\"https:\/\/youtu.be\/IfgJhxA5_lk\" rel=\"nofollow ugc\">https:\/\/youtu.be\/IfgJhxA5_lk<\/a><\/p>\n<p>Guia completo: <a href=\"https:\/\/www.expforex.com\/?p=25\" rel=\"nofollow ugc\">https:\/\/www.expforex.com\/?p=25<\/a><br \/>\n???? AVERAGER MT4: <a href=\"https:\/\/www.mql5.com\/pt\/market\/product\/1289\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/pt\/market\/product\/1289<\/a><br \/>\n???? AVERAGER MT5: <a href=\"https:\/\/www.mql5.com\/pt\/market\/product\/1112\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/pt\/market\/product\/1112<\/a><\/p>\n<p>00:00 Vis\u00e3o geral<br \/>\n00:37 Como o Exp-Averager funciona na tend\u00eancia!<br \/>\n01:37 Como o Exp-Averager funciona contra a tend\u00eancia!<br \/>\n04:07 Como instalar o Exp-Averager<br \/>\n04:54 Como testar o Exp-Averager<\/p>\n<p>Assista em diferentes idiomas:<br \/>\n???? English: <a href=\"https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE<\/a><br \/>\n???? Espa\u00f1ol: <a href=\"https:\/\/www.youtube.youtube.com\/watch?v=lmi5Bck0Pro\" rel=\"nofollow ugc\">https:\/\/www.youtube.youtube.com\/watch?v=lmi5Bck0Pro<\/a><br \/>\n???? Portugu\u00eas: <a href=\"https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk<\/a><br \/>\n???? Deutsch: <a href=\"https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w<\/a><br \/>\n???? Fran\u00e7ais: <a href=\"https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U<\/a><\/p>\n<p>Fazendo a m\u00e9dia das posi\u00e7\u00f5es:<br \/>\nO Expert Advisor Averager \u00e9 uma poderosa ferramenta de negocia\u00e7\u00e3o projetada para abrir posi\u00e7\u00f5es adicionais tanto a favor quanto contra a tend\u00eancia. Ele possui um trailing stop inteligente para gerenciar uma s\u00e9rie de posi\u00e7\u00f5es, garantindo que o lucro seja maximizado.<\/p>\n<p>Caracter\u00edsticas principais:<\/p>\n<p>Aumento e redu\u00e7\u00e3o do lote (volume): Permite ajustar o tamanho do lote para cada posi\u00e7\u00e3o.<br \/>\nEstrat\u00e9gia popular de promediado: Ideal para trazer posi\u00e7\u00f5es n\u00e3o lucrativas para o pre\u00e7o m\u00e9dio, minimizando as perdas.<br \/>\nTrailing Stop Geral do Lucro: A ferramenta ajuda a garantir ganhos \u00e0 medida que o mercado se move a favor do trader.<br \/>\nEstrat\u00e9gia Popular:<\/p>\n<p>O Averager \u00e9 amplamente utilizado por traders que buscam melhorar suas posi\u00e7\u00f5es n\u00e3o lucrativas. Ao abrir novas posi\u00e7\u00f5es na mesma dire\u00e7\u00e3o da original, mas em n\u00edveis de pre\u00e7o diferentes, o trader pode aproximar o pre\u00e7o m\u00e9dio da posi\u00e7\u00e3o ao pre\u00e7o de mercado atual, reduzindo as perdas potenciais.<\/p>\n<p>Conclus\u00e3o:<\/p>\n<p>No geral, o Expert Advisor Averager \u00e9 uma ferramenta poderosa e essencial para traders que desejam gerenciar suas posi\u00e7\u00f5es de forma eficaz e otimizar suas estrat\u00e9gias de negocia\u00e7\u00e3o. Com um trailing stop inteligente e a capacidade de ajustar o volume, o Averager \u00e9 ideal para quem busca seguir tend\u00eancias e maximizar o potencial de lucro.<\/p>\n<p>Hashtags:<br \/>\n#mql5 #mql4 #expert #EA #Expforex #forex #negocia\u00e7\u00e3odemoedas #metatrader #metaquotes #mql #scalping #scalper #tend\u00eancias #trading #a\u00e7\u00f5es #mt5 #stopmovel #estrategiadenegocia\u00e7\u00e3o #estrategiaforex #Vladon #Expforex #ferramentasdenegocia\u00e7\u00e3o #negocia\u00e7\u00e3oautom\u00e1tica #gerenciamentoderiscos #negocia\u00e7\u00f5esefetivas #lucrem\u00e1ximo<\/p>\n<p>Palavras-chave:<br \/>\nExp-Averager MT4, Exp-Averager MT5, ferramenta de negocia\u00e7\u00e3o forex, promediado de posi\u00e7\u00f5es, negocia\u00e7\u00e3o a favor da tend\u00eancia, negocia\u00e7\u00e3o contra a tend\u00eancia, trailing stop inteligente, ajuste de volume, estrat\u00e9gia de pre\u00e7o m\u00e9dio, gest\u00e3o de lucros, Vladon Expforex, automatiza\u00e7\u00e3o de negocia\u00e7\u00e3o, an\u00e1lise t\u00e9cnica<\/p>\n<\/div>\n\n<div class=\"wp-block-comment-reply-link has-small-font-size\"><a rel=\"nofollow\" class=\"comment-reply-link\" href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/?replytocom=1709#respond\" data-commentid=\"1709\" data-postid=\"70254\" data-belowelement=\"comment-1709\" data-respondelement=\"respond\" data-replyto=\"Reply to Expforex Vladislav\" aria-label=\"Reply to Expforex Vladislav\">Reply<\/a><\/div><\/div>\n<\/div>\n\n<\/li><li id=\"comment-1710\" class=\"comment byuser comment-author-expforex bypostauthor even thread-even depth-1\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><div class=\"wp-block-avatar\"><img alt='Expforex Vladislav Avatar' src='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=40&#038;d=identicon&#038;r=r' srcset='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=80&#038;d=identicon&#038;r=r 2x' class='avatar avatar-40 photo wp-block-avatar__image' height='40' width='40'  style=\"border-radius:20px;\"\/><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-comment-author-name has-small-font-size\"><a rel=\"external nofollow ugc\" href=\"https:\/\/www.expforex.com\" target=\"_self\" >Expforex Vladislav<\/a><\/div>\n\n\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\" style=\"margin-top:0px;margin-bottom:0px\"><div class=\"wp-block-comment-date has-small-font-size\"><time datetime=\"2024-09-28T10:02:05+00:00\"><a href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/#comment-1710\">September 28, 2024<\/a><\/time><\/div>\n\n<\/div>\n\n\n<div class=\"wp-block-comment-content\"><p>Deutsch. Averager. Deals er\u00f6ffnen gegen den Trend und mit dem Trend!<br \/>\n<a href=\"https:\/\/youtu.be\/0vc19EzKc6w\" rel=\"nofollow ugc\">https:\/\/youtu.be\/0vc19EzKc6w<\/a><\/p>\n<p>Vollst\u00e4ndige Anleitung: <a href=\"https:\/\/www.expforex.com\/?p=25\" rel=\"nofollow ugc\">https:\/\/www.expforex.com\/?p=25<\/a><br \/>\n???? AVERAGER MT4: <a href=\"https:\/\/www.mql5.com\/de\/market\/product\/1289\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/de\/market\/product\/1289<\/a><br \/>\n???? AVERAGER MT5: <a href=\"https:\/\/www.mql5.com\/de\/market\/product\/1112\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/de\/market\/product\/1112<\/a><\/p>\n<p>00:00 \u00dcbersicht<br \/>\n00:37 Wie Exp-Averager im Trend arbeitet!<br \/>\n01:37 Wie Exp-Averager gegen den Trend arbeitet!<br \/>\n04:07 Wie man den Exp-Averager installiert<br \/>\n04:54 Wie man den Exp-Averager testet<\/p>\n<p>Anleitungen in verschiedenen Sprachen:<br \/>\n???? English: <a href=\"https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE<\/a><br \/>\n???? Espa\u00f1ol: <a href=\"https:\/\/www.youtube.com\/watch?v=lmi5Bck0Pro\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=lmi5Bck0Pro<\/a><br \/>\n???? Portugu\u00eas: <a href=\"https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk<\/a><br \/>\n???? Deutsch: <a href=\"https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w<\/a><br \/>\n???? Fran\u00e7ais: <a href=\"https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U<\/a><\/p>\n<p>Durchschnittsbildung von Positionen:<br \/>\nDer Expert Advisor Averager ist ein leistungsstarkes Werkzeug zur Er\u00f6ffnung zus\u00e4tzlicher Positionen sowohl im Trend als auch gegen den Trend. Er bietet einen intelligenten Durchschnitts-Trailing-Stop, um Gewinne in einer Reihe von Positionen zu sichern.<\/p>\n<p>Hauptmerkmale:<\/p>\n<p>Erh\u00f6hung und Verringerung der Losgr\u00f6\u00dfe (Volumen): Erm\u00f6glicht die Anpassung der Losgr\u00f6\u00dfe f\u00fcr jede Position.<br \/>\nBeliebte Strategie der Durchschnittsbildung: Ideal, um verlustreiche Positionen auf den Durchschnittspreis zu bringen und Verluste zu minimieren.<br \/>\nAllgemeiner Trailing-Stop des Gewinns: Diese Funktion hilft Tradern, Gewinne zu sichern, wenn sich der Markt in ihre Richtung bewegt.<br \/>\nStrategie der Durchschnittsbildung:<\/p>\n<p>Das Averager-Tool wird h\u00e4ufig von Tradern verwendet, um verlustreiche Positionen durch das \u00d6ffnen neuer Positionen in derselben Richtung, jedoch auf unterschiedlichen Preisniveaus, auf den Durchschnittspreis zu bringen. Dies hilft, Verluste zu minimieren und Positionen effizienter zu verwalten.<\/p>\n<p>Schlussfolgerung:<\/p>\n<p>Der Expert Advisor Averager ist ein unverzichtbares Tool f\u00fcr Trader, die ihre Positionen effektiv verwalten und ihre Handelsstrategien optimieren m\u00f6chten. Mit einem intelligenten Trailing-Stop und der M\u00f6glichkeit, das Volumen zu steuern, ist das Averager-Tool ideal f\u00fcr Trader, die Markttrends nutzen und ihre Gewinne maximieren wollen.<\/p>\n<p>Hashtags:<br \/>\n#mql5 #mql4 #expert #EA #Expforex #forex #forextrading #metatrader #metaquotes #mql #scalping #scalper #trending #aktien #mt5 #trailingstop #handelsstrategie #handelsstrategieforex #Vladon #Expforex #handelswerkzeuge #automatischerhandel #risikomanagement #durchschnittsbildung #gewinnmaximierung<\/p>\n<p>Schl\u00fcsselw\u00f6rter:<br \/>\nExp-Averager MT4, Exp-Averager MT5, Forex-Handelswerkzeug, Trendfolge, Gegen-den-Trend-Handel, Durchschnittsbildung, intelligenter Trailing-Stop, Volumenanpassung, Verluste minimieren, Gewinn sichern, Vladon Expforex, Handelsstrategie optimieren, Markttrends<\/p>\n<\/div>\n\n<div class=\"wp-block-comment-reply-link has-small-font-size\"><a rel=\"nofollow\" class=\"comment-reply-link\" href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/?replytocom=1710#respond\" data-commentid=\"1710\" data-postid=\"70254\" data-belowelement=\"comment-1710\" data-respondelement=\"respond\" data-replyto=\"Reply to Expforex Vladislav\" aria-label=\"Reply to Expforex Vladislav\">Reply<\/a><\/div><\/div>\n<\/div>\n\n<\/li><li id=\"comment-1711\" class=\"comment byuser comment-author-expforex bypostauthor odd alt thread-odd thread-alt depth-1\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><div class=\"wp-block-avatar\"><img alt='Expforex Vladislav Avatar' src='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=40&#038;d=identicon&#038;r=r' srcset='https:\/\/secure.gravatar.com\/avatar\/984eead4c1aa4d3bde211774a128ef4265f548bea48588a95c2ff30ba0a44da2?s=80&#038;d=identicon&#038;r=r 2x' class='avatar avatar-40 photo wp-block-avatar__image' height='40' width='40'  style=\"border-radius:20px;\"\/><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-comment-author-name has-small-font-size\"><a rel=\"external nofollow ugc\" href=\"https:\/\/www.expforex.com\" target=\"_self\" >Expforex Vladislav<\/a><\/div>\n\n\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\" style=\"margin-top:0px;margin-bottom:0px\"><div class=\"wp-block-comment-date has-small-font-size\"><time datetime=\"2024-09-28T09:59:14+00:00\"><a href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/#comment-1711\">September 28, 2024<\/a><\/time><\/div>\n\n<\/div>\n\n\n<div class=\"wp-block-comment-content\"><p>Fran\u00e7ais. Averager. Ouvrir des deals \u00e0 contre-courant et sur la tendance !<br \/>\n<a href=\"https:\/\/youtu.be\/5c6FGmyoN9U\" rel=\"nofollow ugc\">https:\/\/youtu.be\/5c6FGmyoN9U<\/a><\/p>\n<p>Guide complet : <a href=\"https:\/\/www.expforex.com\/?p=25\" rel=\"nofollow ugc\">https:\/\/www.expforex.com\/?p=25<\/a><br \/>\n???? AVERAGER MT4 : <a href=\"https:\/\/www.mql5.com\/fr\/market\/product\/1289\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/fr\/market\/product\/1289<\/a><br \/>\n???? AVERAGER MT5 : <a href=\"https:\/\/www.mql5.com\/fr\/market\/product\/1112\" rel=\"nofollow ugc\">https:\/\/www.mql5.com\/fr\/market\/product\/1112<\/a><\/p>\n<p>00:00 Vue d&#8217;ensemble<br \/>\n00:37 Comment Exp-Averager fonctionne dans le sens de la tendance !<br \/>\n01:37 Comment Exp-Averager fonctionne \u00e0 contre-tendance !<br \/>\n04:07 Comment installer Exp-Averager<br \/>\n04:54 Comment tester Exp-Averager<\/p>\n<p>Vid\u00e9os explicatives :<br \/>\n???? <a href=\"https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=7NwAcGmN0yE<\/a> English.<br \/>\n???? <a href=\"https:\/\/www.youtube.com\/watch?v=lmi5Bck0Pro\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=lmi5Bck0Pro<\/a> Espa\u00f1ol.<br \/>\n???? <a href=\"https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=IfgJhxA5_lk<\/a> Portugu\u00eas.<br \/>\n???? <a href=\"https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=0vc19EzKc6w<\/a> Deutsch.<br \/>\n???? <a href=\"https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=5c6FGmyoN9U<\/a> Fran\u00e7ais.<\/p>\n<p>Moyenne des positions :<br \/>\nL&#8217;Expert Advisor Averager est un outil puissant qui permet d&#8217;ouvrir des positions suppl\u00e9mentaires \u00e0 la fois dans le sens de la tendance et \u00e0 contre-tendance, avec la fonction de trailing stop g\u00e9n\u00e9ral du profit.<\/p>\n<p>Caract\u00e9ristiques principales :<\/p>\n<p>Ajustement de la taille du lot (volume) : permet de modifier la taille du lot pour chaque position.<br \/>\nStrat\u00e9gie populaire de moyenne des positions : id\u00e9ale pour ramener les positions non rentables au prix moyen.<br \/>\nTrailing stop g\u00e9n\u00e9ral du profit : cette fonction permet de s\u00e9curiser les gains lorsque le march\u00e9 \u00e9volue en faveur du trader.<br \/>\nStrat\u00e9gie de moyenne des positions :<\/p>\n<p>L&#8217;Averager est couramment utilis\u00e9 pour ramener les positions non rentables au prix moyen. Cela consiste \u00e0 ouvrir de nouvelles positions dans la m\u00eame direction que la position initiale, mais \u00e0 un niveau de prix diff\u00e9rent. En proc\u00e9dant ainsi, le trader rapproche le prix moyen de la position au niveau actuel du march\u00e9, ce qui peut r\u00e9duire les pertes.<\/p>\n<p>Conclusion :<\/p>\n<p>L&#8217;Expert Advisor Averager est un outil essentiel pour les traders souhaitant mieux g\u00e9rer leurs positions et optimiser leurs strat\u00e9gies de trading. Il permet non seulement d&#8217;augmenter ou de diminuer la taille des positions, mais aussi de suivre les tendances du march\u00e9 pour maximiser les gains avant de quitter une position.<\/p>\n<p>Hashtags :<br \/>\n#mql5 #mql4 #expert #EA #Expforex #forex #forextrading #metatrader #metaquotes #mql #scalping #scalper #trending #bourse #mt5 #trailingstop #strategie #tradingstrategie #forexstrategie #tradingfrancais #traderfrancais #Vladon #Expforex #automatedtrading #gestionderisque #profitmaximisation<\/p>\n<p>Mots-cl\u00e9s :<br \/>\nExp-Averager MT4, Exp-Averager MT5, outil de trading, strat\u00e9gie de moyenne des positions, tendance, contre-tendance, trailing stop intelligent, gestion de position, Vladon Expforex, optimisation des strat\u00e9gies de trading, march\u00e9 Forex, profits<\/p>\n<\/div>\n\n<div class=\"wp-block-comment-reply-link has-small-font-size\"><a rel=\"nofollow\" class=\"comment-reply-link\" href=\"https:\/\/expforex.com\/es\/averager\/comment-page-1\/?replytocom=1711#respond\" data-commentid=\"1711\" data-postid=\"70254\" data-belowelement=\"comment-1711\" data-respondelement=\"respond\" data-replyto=\"Reply to Expforex Vladislav\" aria-label=\"Reply to Expforex Vladislav\">Reply<\/a><\/div><\/div>\n<\/div>\n\n<\/li><\/ol>\n\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"8\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-extra\">Extra<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-related-posts\">Entradas relacionadas<\/h2>\n<div class=\"root-eb-post-carousel-15gwf wp-block-essential-blocks-post-carousel\">\n    <div class=\"eb-parent-wrapper eb-parent-eb-post-carousel-15gwf \">\n        <div class=\"eb-post-carousel-15gwf style-2 slick-arrows equal-height dot-style-1 eb-post-carousel-wrapper\"\n            data-id=\"eb-post-carousel-15gwf\"\n            data-querydata=\"a:14:{s:6:&quot;source&quot;;s:4:&quot;post&quot;;s:11:&quot;sourceIndex&quot;;i:0;s:9:&quot;rest_base&quot;;s:5:&quot;posts&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:6:&quot;author&quot;;s:0:&quot;&quot;;s:10:&quot;taxonomies&quot;;a:1:{s:8:&quot;category&quot;;a:5:{s:4:&quot;name&quot;;s:10:&quot;Categories&quot;;s:9:&quot;rest_base&quot;;s:10:&quot;categories&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:4:&quot;slug&quot;;s:8:&quot;category&quot;;s:5:&quot;value&quot;;s:32:&quot;[{&quot;value&quot;:7,&quot;label&quot;:&quot;Software&quot;}]&quot;;}}s:8:&quot;per_page&quot;;s:2:&quot;15&quot;;s:6:&quot;offset&quot;;s:1:&quot;0&quot;;s:7:&quot;orderby&quot;;s:4:&quot;rand&quot;;s:5:&quot;order&quot;;s:4:&quot;desc&quot;;s:7:&quot;include&quot;;s:2:&quot;[]&quot;;s:7:&quot;exclude&quot;;s:0:&quot;&quot;;s:15:&quot;exclude_current&quot;;b:1;s:26:&quot;exclude_password_protected&quot;;b:0;}\"\n            data-slidersettings=\"{&quot;arrows&quot;:true,&quot;dots&quot;:true,&quot;autoplaySpeed&quot;:4000,&quot;speed&quot;:700,&quot;adaptiveHeight&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:true,&quot;slideToShowRange&quot;:3,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-circle-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-circle-right&quot;,&quot;addIcon&quot;:false,&quot;showFallbackImg&quot;:false,&quot;fallbackImgUrl&quot;:&quot;&quot;,&quot;isRTLEnable&quot;:false,&quot;TABslideToShowRange&quot;:3,&quot;MOBslideToShowRange&quot;:3}\"\n            data-attributes=\"{&quot;preset&quot;:&quot;style-2&quot;,&quot;showThumbnail&quot;:true,&quot;showTitle&quot;:true,&quot;titleLength&quot;:&quot;10&quot;,&quot;titleTag&quot;:&quot;h4&quot;,&quot;showContent&quot;:true,&quot;contentLength&quot;:20,&quot;expansionIndicator&quot;:&quot;...&quot;,&quot;showReadMore&quot;:true,&quot;readmoreText&quot;:&quot;Read More&quot;,&quot;showMeta&quot;:false,&quot;headerMeta&quot;:&quot;[]&quot;,&quot;footerMeta&quot;:&quot;[]&quot;,&quot;authorPrefix&quot;:&quot;by&quot;,&quot;datePrefix&quot;:&quot;on&quot;,&quot;showBlockContent&quot;:true,&quot;showFeaturedPost&quot;:false,&quot;featuredPostId&quot;:&quot;&quot;,&quot;showFeaturedPostTitle&quot;:true,&quot;showFeaturedPostContent&quot;:false,&quot;showFeaturedPostMeta&quot;:true,&quot;showFeaturedHeaderMeta&quot;:true,&quot;showFeaturedFooterMeta&quot;:true,&quot;featuredMetaItems&quot;:&quot;{}&quot;,&quot;featuredExcerptLength&quot;:10,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-circle-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-circle-right&quot;,&quot;showFallbackImg&quot;:false,&quot;isRTLEnable&quot;:false}\">\n\n            <div class=\"eb-post-carousel init-eb-post-carousel-15gwf\"\n                data-id=\"eb-post-carousel-15gwf\">\n                <article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"76898\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/tickhamster\/\">Tick Hamster Robot de trading autom\u00e1tico. \u00a1Nada extra!<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2020\/08\/TickHamster-MT45-2020.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/tickhamster\/\" title=\"tickhamsterrobotdetradingautomticonadaextra\">Tick Hamster Robot de trading autom\u00e1tico. \u00a1Nada extra!<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Tick Hamster \u2013 Asesor Experto con Optimizaci\u00f3n Autom\u00e1tica para Cualquier S\u00edmbolo de Trading en MetaTrader\n\nTick Hamster es un Asesor Experto&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/tickhamster\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"72211\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/xcustomea\/\">EA The xCustomEA: Asesor de Comercio Universal para Indicadores Personalizados. Constructor de Estrategias Personalizadas<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/08\/xCustom-MT45-2020-1.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/xcustomea\/\" title=\"eathexcustomea:asesordecomerciouniversalparaindicadorespersonalizados\">EA The xCustomEA: Asesor de Comercio Universal para Indicadores Personalizados.<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Asesor de comercio universal en indicadores personalizados para MetaTrader.\nExp &#8211; The xCustomEA Asesor de comercio universal en indicadores personalizados. The&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/xcustomea\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"77301\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/eapadpro\/\">EAPadPRO &#8211; Panel de informaci\u00f3n para nuestros expertos. Panel de control para Asesores Expertos<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/08\/logoEAPADPRO.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/eapadpro\/\" title=\"eapadpro-paneldeinformacinparanuestrosexpertospanelde\">EAPadPRO &#8211; Panel de informaci\u00f3n para nuestros expertos. Panel de<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Panel de informaci\u00f3n para todos nuestros asesores y utilidades para el terminal MetaTrader.  \nInstrucciones detalladas sobre los conceptos b\u00e1sicos&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/eapadpro\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"173902\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/official-expforex-license-vs-cracked-version\/\">Licencia oficial de EXPFOREX vs versiones crackeadas: por qu\u00e9 el software verificado importa para MT4 y MT5<\/a>\n                    <img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2026\/07\/expforex.com-Official-downloads-4-logo-Copy.png\" class=\"attachment-full size-full\" alt=\"expforex.com Official downloads 4 -logo\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/official-expforex-license-vs-cracked-version\/\" title=\"licenciaoficialdeexpforexvsversionescrackeadas:porquel\">Licencia oficial de EXPFOREX vs versiones crackeadas: por qu\u00e9 el<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Licencia oficial de EXPFOREX\n\n\n\nLicencia oficial de EXPFOREX vs versiones crackeadas: por qu\u00e9 el software verificado importa para MT4 y MT5\n\n\n\nTu&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/official-expforex-license-vs-cracked-version\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"150023\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/vtpprose\/\">VirtualTradePad PRO SE \u2014 Panel de trading profesional para MetaTrader MT4 y MT5<\/a>\n                    <img decoding=\"async\" width=\"1254\" height=\"1254\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2026\/05\/LOGO-VTP-PRO-SE-PREMIUM-MT45.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/vtpprose\/\" title=\"virtualtradepadprosepaneldetradingprofesionalparametatrader\">VirtualTradePad PRO SE \u2014 Panel de trading profesional para MetaTrader<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>VirtualTradePad PRO SE es un entorno profesional de gesti\u00f3n de operaciones para MetaTrader 4 y MetaTrader 5. Est\u00e1 dise\u00f1ado para&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/vtpprose\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"66099\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/aisniper\/\">AI Sniper. Asesor Experto Inteligente y Autom\u00e1tico para MetaTrader.<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/06\/TickSniper-AI-MT45-2024-3.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/aisniper\/\" title=\"aisniperasesorexpertointeligenteyautomticoparametatrader\">AI Sniper. Asesor Experto Inteligente y Autom\u00e1tico para MetaTrader.<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>AI Sniper es un robot de trading inteligente y autooptimizable dise\u00f1ado para las terminales MT4 y MT5. Aprovecha un algoritmo&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/aisniper\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"63962\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/templates\/\">Plantilla MQL de C\u00f3digo Abierto. Plantilla para Crear un Expert Advisor<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/Exp-Templates-1.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/templates\/\" title=\"plantillamqldecdigoabiertoplantillaparacrearunexpert\">Plantilla MQL de C\u00f3digo Abierto. Plantilla para Crear un Expert<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Resumen\n\n\n\nCrear Asesores Expertos (Expert Advisors, EAs) para probar tu estrategia utilizando cualquier indicador puede simplificarse utilizando plantillas y recursos de&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/templates\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"71813\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/ticksniper\/\">TickSniper Asesor Experto Autom\u00e1tico para MetaTrader. Tick scalper<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/08\/TickSniper-MT45-2020.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/ticksniper\/\" title=\"ticksniperasesorexpertoautomticoparametatradertickscalper\">TickSniper Asesor Experto Autom\u00e1tico para MetaTrader. Tick scalper<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Exp-TickSniper es un scalper Tick r\u00e1pido que selecciona autom\u00e1ticamente los par\u00e1metros para cada par de divisas por separado.\nEl EA ha&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/ticksniper\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"78221\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/swing\/\">Estrategia Swing (P\u00e9ndulo). Apertura autom\u00e1tica de 2 \u00f3rdenes<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2008\/12\/NEWLOGO_SWING-45-2019.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/swing\/\" title=\"estrategiaswingpnduloaperturaautomticade2rdenes\">Estrategia Swing (P\u00e9ndulo). Apertura autom\u00e1tica de 2 \u00f3rdenes<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>La estrategia P\u00e9ndulo o Swing implica la apertura secuencial de \u00f3rdenes pendientes con un tama\u00f1o de lote incrementado. El principio&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/swing\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"78134\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/the-x-testing-and-optimization\/\">The X y The xCustomEA: Pruebas y optimizaci\u00f3n<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2020\/07\/optimisationtesting.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/the-x-testing-and-optimization\/\" title=\"thexythexcustomea:pruebasyoptimizacin\">The X y The xCustomEA: Pruebas y optimizaci\u00f3n<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Descripci\u00f3n\n\n\n\nThe X y The xCustomEA son dos Expert Advisors (EAs) destacados en la comunidad de Forex (Forex), ganando una popularidad&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/the-x-testing-and-optimization\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"64594\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/virtualtradepad\/\">Panel de operaciones VirtualTradePad (VTP). Panel de operaciones para operar con un solo clic desde gr\u00e1ficos y teclado<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/08\/VirtualTradePAd_MT45_2020-1.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/virtualtradepad\/\" title=\"paneldeoperacionesvirtualtradepadvtppaneldeoperacionesparaoperar\">Panel de operaciones VirtualTradePad (VTP). Panel de operaciones para operar<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Panel de operaciones para operar con un solo clic desde gr\u00e1ficos y teclado. VirtualTradePad\u00a0or VTP &#8211; control panel for trade&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/virtualtradepad\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"79227\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/infopad\/\">InfoPad, Panel de Informaci\u00f3n en L\u00ednea para MetaTrader<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2017\/08\/InfoPad-MT45.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/infopad\/\" title=\"infopadpaneldeinformacinenlneaparametatrader\">InfoPad, Panel de Informaci\u00f3n en L\u00ednea para MetaTrader<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>InfoPad es un panel de informaci\u00f3n altamente \u00fatil dise\u00f1ado para proporcionar informaci\u00f3n crucial sobre el par de divisas espec\u00edfico seleccionado&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/infopad\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"78057\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/eapadpro-library\/\">BIBLIOTECA EAPADPRO &#8211; Agregar nuestro panel a tu EA<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_EAPADPRO.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/eapadpro-library\/\" title=\"bibliotecaeapadpro-agregarnuestropanelatuea\">BIBLIOTECA EAPADPRO &#8211; Agregar nuestro panel a tu EA<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>BIBLIOTECA EAPADPRO \u2013 Mejorando tu Asesor Experto (EA) con Nuestro Panel de Informaci\u00f3n\n\nLa BIBLIOTECA EAPADPRO ofrece una soluci\u00f3n robusta para&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/eapadpro-library\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"71436\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/testerpad\/\">Tester Pad es un simulador de trading Forex para el Strategy Tester. Trading con indicadores.<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_testerpad-ALL.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/testerpad\/\" title=\"testerpadesunsimuladordetradingforexparael\">Tester Pad es un simulador de trading Forex para el<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Trading con un clic en el gr\u00e1fico del Strategy Tester. La utilidad te permite probar manualmente tus estrategias en el&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/testerpad\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"75337\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/es\/safetylock\/\">SafetyLOCK PRO Protege tus posiciones utilizando \u00f3rdenes pendientes opuestas. HEDGE<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2020\/08\/NEWLOGO_safetylock4.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/es\/safetylock\/\" title=\"safetylockproprotegetusposicionesutilizandordenespendientesopuestashedge\">SafetyLOCK PRO Protege tus posiciones utilizando \u00f3rdenes pendientes opuestas. HEDGE<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>SAFETYLOCK: Asegura tus operaciones contra fuertes reversiones del mercado\nOperar en los mercados financieros implica altos riesgos, particularmente durante fuertes reversiones&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/es\/safetylock\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article>            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promediando posiciones. \u00a1Apertura de posiciones adicionales en la tendencia y contra la tendencia con la funci\u00f3n de trailing stop general de las ganancias!<br \/>\n\u00a1El asesor puede abrir posiciones adicionales en la tendencia y contra la tendencia!<br \/>\n\u00a1Incluye trailing stop promedio para una serie de posiciones!<br \/>\nAumento y disminuci\u00f3n del lote.<\/p>\n","protected":false},"author":2,"featured_media":39544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_eb_data_table":"","footnotes":"","_expseo_title":"Averager. \u00a1Promediando contra la tendencia y en la tendencia!","_expseo_description":"Promediando posiciones. \u00a1Apertura de posiciones adicionales en la tendencia y contra la tendencia con la funci\u00f3n de trailing stop general de las ganancias!","_expseo_canonical":"","_expseo_focus_keyword":"Averager","_expseo_robots_noindex":"","_expseo_robots_nofollow":"","_expseo_robots_advanced":"","_expseo_breadcrumb_title":"","_expseo_og_title":"","_expseo_og_description":"","_expseo_og_image":"","_expseo_twitter_title":"","_expseo_twitter_description":"","_expseo_twitter_image":"","_expseo_schema_page_type":"","_expseo_schema_article_type":"","_expseo_schema_product_activator":""},"categories":[534],"tags":[6454,6456,18424,932,6458,6452],"class_list":["post-70254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software-es","tag-control-del-lote-forex","tag-gestion-de-la-serie-de-posiciones","tag-mt-averager-ar","tag-position-management","tag-promediador-mt","tag-promedio-de-stop-loss"],"acf":{"metatrader4":"MT4","metatrader5":"MT5","type":"Mejor Utilidad ","typebrief":"Promediando posiciones a lo largo de la tendencia y contra la tendencia","mt4buy":"1289","mt5buy":"1112","typefreedemo":"DEMO","downloadfreedemo":404,"DirectDownloadLink":"https:\/\/expforex.com\/?sdm_process_download=1&download_id=4156","versions":"24.404","version_date":"2024","postanotherid":"4156","direct5":"mql5buy:\/\/1112.Averager+FULL\/","direct4":"mql4buy:\/\/1289.Exp+Averager\/","testimonials_list":"","schema_name":"Averager","schema_description":"","schema_type":"Utilities","schema_ratingValue":"4,92","schema_ratingCount":"33","schema_highPrice_MT4":"50.00","schema_rentprice_MT4":"0.00","schema_highPrice_MT5":"50.00","schema_rentprice_MT5":"0.00"},"_links":{"self":[{"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/posts\/70254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/comments?post=70254"}],"version-history":[{"count":1,"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/posts\/70254\/revisions"}],"predecessor-version":[{"id":172916,"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/posts\/70254\/revisions\/172916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/media\/39544"}],"wp:attachment":[{"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/media?parent=70254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/categories?post=70254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expforex.com\/es\/wp-json\/wp\/v2\/tags?post=70254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}