{"id":70672,"date":"2025-02-22T10:31:38","date_gmt":"2025-02-22T10:31:38","guid":{"rendered":"https:\/\/expforex.com\/extrareportpad\/"},"modified":"2026-06-30T13:31:47","modified_gmt":"2026-06-30T13:31:47","slug":"extrareportpad","status":"publish","type":"post","link":"https:\/\/expforex.com\/fr\/extrareportpad\/","title":{"rendered":"Extra Report Pad &#8211; Journal du Trader. Analyse professionnellement votre compte de trading. MyFxBook en graphique en direct. ExtraReportPad"},"content":{"rendered":"\n<p align=\"center\">\n  <div class=\"video-container-20 video-thumbnail\" onclick=\"loadVideo('video-container-20', 'SMRBtOuJZmA', 0)\">\n    <img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/03\/FR_YOUTUBE540_CORRECTED_ALL_EXTRAREPORTPAD_2024.png\" alt=\"Extra Report Pad - Journal du Trader. Analyse professionnellement votre compte de trading. MyFxBook en graphique en direct. ExtraReportPad Video Thumbnail\" class=\"video-image\">\n    <div class=\"play-button\"><\/div>\n  <\/div>\n<\/p>\n\n\n\n<div class=\"wp-block-essential-blocks-advanced-tabs alignwide root-eb-advanced-tabs-b7hkfqw\"><div class=\"eb-parent-wrapper eb-parent-eb-advanced-tabs-b7hkfqw \"><div class=\"eb-advanced-tabs-b7hkfqw eb-advanced-tabs-wrapper horizontal\" data-min-height=\"true\"><div class=\"eb-tabs-nav\"><ul class=\"tabTitles\" data-tabs-ul-id=\"eb-advanced-tabs-b7hkfqw\"><li data-title-tab-id=\"1\" data-title-custom-id=\"main\" id=\"main\" class=\"active\"><i icon=\"fas fa-home\" class=\"fas fa-home tabIcon\"><\/i><h6 class=\"tab-title-text\">Accueil<\/h6><\/li><li data-title-tab-id=\"2\" data-title-custom-id=\"Documentation\" id=\"Documentation\" class=\"inactive\"><i icon=\"fas fa-graduation-cap\" class=\"fas fa-graduation-cap tabIcon\"><\/i><h6 class=\"tab-title-text\">Documentation<\/h6><\/li><li data-title-tab-id=\"3\" data-title-custom-id=\"Settings\" id=\"Settings\" class=\"inactive\"><i icon=\"fas fa-cog\" class=\"fas fa-cog tabIcon\"><\/i><h6 class=\"tab-title-text\">Param\u00e8tres<\/h6><\/li><li data-title-tab-id=\"4\" data-title-custom-id=\"faq\" id=\"faq\" class=\"inactive\"><i icon=\"fas fa-question\" class=\"fas fa-question tabIcon\"><\/i><h6 class=\"tab-title-text\">FAQ<\/h6><\/li><li data-title-tab-id=\"5\" data-title-custom-id=\"changelog\" id=\"changelog\" class=\"inactive\"><i icon=\"fas fa-code\" class=\"fas fa-code tabIcon\"><\/i><h6 class=\"tab-title-text\">Journal<\/h6><\/li><li data-title-tab-id=\"6\" data-title-custom-id=\"reviews\" id=\"reviews\" class=\"inactive\"><i icon=\"far fa-star\" class=\"far fa-star tabIcon\"><\/i><h6 class=\"tab-title-text\">Avis\u00a0<\/h6><\/li><li data-title-tab-id=\"7\" data-title-custom-id=\"comments\" id=\"comments\" class=\"inactive\"><i icon=\"far fa-comments\" class=\"far fa-comments tabIcon\"><\/i><h6 class=\"tab-title-text\">Commentaires<\/h6><\/li><li data-title-tab-id=\"8\" data-title-custom-id=\"Extra\" id=\"Extra\" class=\"inactive\"><i icon=\"fas fa-bolt\" class=\"fas fa-bolt tabIcon\"><\/i><h6 class=\"tab-title-text\">Extra<\/h6><\/li><\/ul><\/div><div class=\"eb-tabs-contents\">\n<div class=\"eb-tab-wrapper\" data-tab-id=\"1\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-a-propos-d-extra-report-pad\">\u00c0 propos d&#8217;Extra Report Pad<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Extra Report Pad<\/strong> Journal des traders. Il s&#8217;agit d&#8217;un panneau statistique fournissant une analyse de votre compte de trading pour MetaTrader.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Les r\u00e9sultats de l&#8217;analyse sont affich\u00e9s sur le graphique en temps r\u00e9el.<br>Le trading multi-devises est tr\u00e8s populaire. Cependant, plus le nombre de transactions est \u00e9lev\u00e9, plus il est difficile d&#8217;analyser la rentabilit\u00e9 de chaque transaction. L&#8217;analyse professionnelle des transactions par mois et le calcul des statistiques par transaction sont des t\u00e2ches encore plus complexes.<br>Le panneau <strong>Extra Report Pad<\/strong> offre une solution efficace pour analyser votre compte et pr\u00e9parer des statistiques d\u00e9taill\u00e9es en temps r\u00e9el en <strong>HTML<\/strong>, CSV ou graphique, similaire \u00e0 <strong>MyFxBook<\/strong>.<br>Si vous cherchez \u00e0 obtenir une compr\u00e9hension compl\u00e8te des performances de votre syst\u00e8me de trading, plusieurs outils sont disponibles pour vous aider \u00e0 atteindre cet objectif.<br><strong>Extra Report Pad<\/strong> inclut des Rapports, Statistiques, <strong>myfxbook<\/strong>, Journaux de trading, analyse de compte, statistiques de performance, <strong>analytics<\/strong>, et un <strong>dashboard<\/strong> innovant.<br>En utilisant <strong>Extra Report Pad<\/strong>, vous pouvez analyser en d\u00e9tail les performances de votre syst\u00e8me de trading et obtenir des informations pr\u00e9cieuses sur les domaines de force et les faiblesses potentielles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Que vous soyez un nouveau trader cherchant \u00e0 am\u00e9liorer vos performances ou un trader exp\u00e9riment\u00e9 souhaitant optimiser votre strat\u00e9gie de trading, ces <strong>Extra Report Pad<\/strong> peuvent vous fournir les informations dont vous avez besoin pour prendre des d\u00e9cisions \u00e9clair\u00e9es et atteindre vos objectifs financiers.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-comment-fonctionne-extra-report-pad\">Comment fonctionne Extra Report Pad ?<\/h2>\n\n\n\n<div class=\"wp-block-essential-blocks-slider root-eb-slider-4i1s6\"><div class=\"eb-parent-wrapper eb-parent-eb-slider-4i1s6 eb_animation eb___animated eb___zoomIn\"><div class=\"eb-slider-wrapper eb-slider-4i1s6\" data-blockid=\"eb-slider-4i1s6\" data-version=\"v4\" data-settings=\"eyJhcnJvd3MiOnRydWUsImFkYXB0aXZlSGVpZ2h0Ijp0cnVlLCJhdXRvcGxheSI6dHJ1ZSwiYXV0b3BsYXlTcGVlZCI6NjAyNCwiZG90cyI6dHJ1ZSwiZmFkZSI6ZmFsc2UsImluZmluaXRlIjp0cnVlLCJwYXVzZU9uSG92ZXIiOnRydWUsInNsaWRlc1RvU2hvdyI6MSwic3BlZWQiOjc0MSwidmVydGljYWwiOmZhbHNlLCJjdXJyZW50U2xpZGUiOjAsInJ0bCI6ZmFsc2UsInJlc3BvbnNpdmUiOlt7ImJyZWFrcG9pbnQiOjEwMjUsInNldHRpbmdzIjp7InNsaWRlc1RvU2hvdyI6MX19LHsiYnJlYWtwb2ludCI6NzY3LCJzZXR0aW5ncyI6eyJzbGlkZXNUb1Nob3ciOjF9fV19\" data-arrownexticon=\"fas fa-chevron-right\" data-arrowprevicon=\"fas fa-chevron-left\" data-lightbox=\"false\"><div class=\"eb-slider-init eb-slider-type-content\"><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_00_3714.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_00_3714.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Journal du Trader &#8211; analyse professionnellement votre compte de trading. MyFxBook en graphique en direct<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_01_0500.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_01_0500.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Principales fonctions de Extra Report Pad-<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_02_2321.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_02_2321.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Rapport d\u00e9taill\u00e9 sur les transactions\/ordres cl\u00f4tur\u00e9s en mode en ligne<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_02_4309.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_02_4309.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Filtrage des transactions par date, symbole (symbol), magic, commentaire<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_1125.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_1125.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Graphique de rentabilit\u00e9 et rapport de compte actuel<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_2528.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_2528.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Rapport sur chaque symbole (symbol)<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_3724.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_3724.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Rapport sur chaque magic<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_5019.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_03_5019.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Rapport sur chaque commentaire<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_04_2726.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_04_2726.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Exporter le rapport en HTML et CSV<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_04_0521.png\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/EN_ALL_EXTRAREPORTPAD_2024-Time-0_04_0521.png\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad Statistiques par p\u00e9riode de temps<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-9721.jpg\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-9721.jpg\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad : Voir les statistiques par temps<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-9286.jpg\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-9286.jpg\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad : Rapport d\u00e9taill\u00e9 avec filtres<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-8915.jpg\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-8915.jpg\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad : Enregistrer le rapport d\u00e9taill\u00e9 en HTML<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-7268.jpg\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-7268.jpg\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad : Voir les statistiques par magics<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-7265.jpg\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-7265.jpg\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad : Voir les statistiques par symboles (symbols)<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-6598.jpg\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-6598.jpg\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad : Enregistrer le rapport d\u00e9taill\u00e9 en HTML<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><div class=\"eb-slider-item content-2\" data-src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-6418.jpg\"><div><img class=\"eb-slider-image\" data-lazy=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/ind5-extra-report-pad-screen-6418.jpg\"\/><\/div><div class=\"eb-slider-content align-center\"><p class=\"eb-slider-title\">Extra Report Pad : Enregistrer le rapport d\u00e9taill\u00e9 en HTML<\/p><div class=\"eb-slider-button-wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-disent-les-gens-a-propos-de-extra-report-pad\">Que disent les gens \u00e0 propos de Extra Report Pad?<\/h2>\n\n\n<div class=\"testimonials_slider single-photo\"><ul class=\"testimonials_slider_ul\"><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FD7FE08-D1BE_big-75x75.jpeg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FD7FE08-D1BE_big-150x150.jpeg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FD7FE08-D1BE_big.jpeg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FD7FE08-D1BE_big-150x150.jpeg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FD7FE08-D1BE_big-150x150.jpeg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FD7FE08-D1BE_big-75x75.jpeg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5FD7FE08-D1BE_big.jpeg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Aller Uja \r\n\r\n<hr \/>\r\n\r\nA good tool, thanks to the developer.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/ru\/market\/product\/36730\">Aller Uja<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642f4de2-7237_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642f4de2-7237_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642f4de2-7237_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642f4de2-7237_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642f4de2-7237_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642f4de2-7237_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642f4de2-7237_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>cbarryftmo\r\n\r\n<hr \/>\r\n\r\nAt last, I've discovered exactly what I needed! I'd been searching for a tool to assess the performance of various EAs over time, but couldn't find one. The program I downloaded earlier lacked the feature to label prices traded by specific EAs.<strong> This tool fulfills my requirement perfectly. I'm extremely grateful for the expertise behind its development and the superior ability to download information. Thank you so much!<\/strong><\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056\">cbarryftmo<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Easily the best reporting tool I've used<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">Timmy T<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Enormously useful report indicator, works perfectly on MT4, exactly what I needed. Thank you so much for such a fantastic reporting tool \ud83d\ude42<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Messages#!tab=reviews&#038;id=review_38531233\">Blazej Ornatowski<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Great job guys. Thanks and good luck with everything.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">\u0410\u043d\u0434\u0440\u0435\u0439 \u041f\u0435\u0448\u043a\u043e\u0432<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>\u042d\u0442\u043e \u043b\u0443\u0447\u0448\u0435\u0435 \u043f\u0440\u0438\u043b\u043e\u0436\u0435\u043d\u0438\u0435 \u0434\u043b\u044f \u0441\u0431\u043e\u0440\u0430 \u0441\u0442\u0430\u0442\u0438\u0441\u0442\u0438\u043a\u0438 \u043f\u043e \u0441\u0447\u0435\u0442\u0443.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">Andrey Tsygankov <\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>\u041e\u0442\u043b\u0438\u0447\u043d\u044b\u0439 \u043f\u0440\u043e\u0434\u0443\u043a\u0442! \u041e\u0442\u0437\u044b\u0432\u0447\u0438\u0432\u044b\u0439 \u0430\u0432\u0442\u043e\u0440!<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">Nikolay Fartuchnyy<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>This indicator is amazing. It also has the max upside watermark and the lowest drawdown that was in profit per trade. Compare it to the actual profit or loss, then use an EA like Account Protector and tell it to take profit or stop loss at the average high watermark and stop loss at at the lowest above the largest drawdowns. It will increase your profits and mimimize your losses. just review your trades daily or weekly and you will find this tool invaluable. And the reports are far better than Metatraders. And it gives you a report analysis of all your trades with win and lose rate, profit ration, lowest overall drawdown, etc. You can also filter your trades by comment or magic number to get a drilled down deeper insight. Great job author!<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">Robert Torres Jr <\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Childerich \r\nGreat product! It\u2019s been very helpful and easy to use.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730\">Childerich<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Jcb Mlwijk \r\nExcellent reporting functionality that provides you with detailed insights into their trading performance. The tool generates trade history reports, including key metrics such as profit\/loss analysis, drawdown, and risk exposure.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730\">Jcb Mlwijk <\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/618E1649-9997_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/618E1649-9997_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/618E1649-9997_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/618E1649-9997_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/618E1649-9997_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/618E1649-9997_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/618E1649-9997_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Mustafa Nail Sertoglu\r\n\r\n<hr \/>\r\n\r\ndear Vlad, THX for this DETAILED INDI, it will help for ALL TRADERS !!! Congrats !!!<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/ru\/market\/product\/15056\">Mustafa Nail Sertoglu<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642418d3-d942_big-1-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642418d3-d942_big-1-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642418d3-d942_big-1.jpg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642418d3-d942_big-1-150x150.jpg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642418d3-d942_big-1-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642418d3-d942_big-1-75x75.jpg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/642418d3-d942_big-1.jpg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Fabrizio Malavasi\r\n\r\n<hr \/>\r\n\r\nThis reporting app it's a very useful tool to analyse the trades order history.The \"Time\" button that show the profit\/entry along the time It's interesting too. It has a very nice graphic form. You made as usual an excellent job!\r\n\r\nThanks a lots!<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/ru\/market\/product\/15056\">Fabrizio Malavasi<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5F2914B9-BFB2_big-75x75.jpeg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5F2914B9-BFB2_big-150x150.jpeg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5F2914B9-BFB2_big.jpeg.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5F2914B9-BFB2_big-150x150.jpeg\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5F2914B9-BFB2_big-150x150.jpeg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5F2914B9-BFB2_big-75x75.jpeg 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5F2914B9-BFB2_big.jpeg 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Yusuf Mansawala\r\n\r\n<hr \/>\r\n\r\nIt's a useful tool for Fund Mangers and Clients trading with multiple signals or multiple copy trading services, as it can sort out your account statement into a powerful decision making tool.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/ru\/market\/product\/15056\">Yusuf Mansawala<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5AFADC2F-CDFD_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5AFADC2F-CDFD_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5AFADC2F-CDFD_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5AFADC2F-CDFD_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5AFADC2F-CDFD_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5AFADC2F-CDFD_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/5AFADC2F-CDFD_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>hwschmidt\r\n\r\n<hr \/>\r\n\r\nTolles Tool. Sehr viele Informationen die man bisher nicht hatte. F\u00fcr mich besonders gut weil ich die Daten jetzt besser nach Excel \u00fcbertragen kann ohne das die Formatierung leidet. Danke<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/ru\/market\/product\/15056\">hwschmidt<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><li class=\"testimonials_slider_li\"><div class=\"single-photo-img\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6487747c-ff90_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6487747c-ff90_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6487747c-ff90_big.png.webp 200w\" sizes=\"(max-width:767px) 150px, 150px\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6487747c-ff90_big-150x150.png\" class=\"attachment-be_thumbnail size-be_thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6487747c-ff90_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6487747c-ff90_big-75x75.png 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/6487747c-ff90_big.png 200w\" sizes=\"(max-width:767px) 150px, 150px\" \/><\/picture><\/div><div class=\"bq_wrapper\"><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>sofrito\r\n\r\n<hr \/>\r\n\r\nMe parece una herramienta muy \u00fatil, encima gratis. Gracias.<\/blockquote><\/div><\/div><div class=\"hr_dots\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"author\"><h5 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/ru\/market\/product\/15056\">sofrito<\/a><\/h5><span class=\"company\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/span><\/div><\/li><\/ul><div class=\"slider_pager slider_pagination\"><\/div><\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vous-pouvez-telecharger-l-assistant-extra-report-pad-gratuitement\">Vous pouvez t\u00e9l\u00e9charger l&#8217;assistant Extra Report Pad gratuitement<\/h2>\n\n\n\n<div class=\"wp-block-essential-blocks-call-to-action nfd-wb-animate nfd-wb-zoom-in nfd-delay-50  root-eb-call-to-action-mfk0b\"><div class=\"eb-parent-wrapper eb-parent-eb-call-to-action-mfk0b eb_animation eb___animated eb___flash\"><div class=\"eb-cia-wrapper eb-call-to-action-mfk0b\" data-icon=\"fas fa-gift\"><div class=\"eb-cia-text-wrapper\"><i class=\"fas fa-gift eb-cia-icon\" icon=\"fas fa-gift\"><\/i><h4 class=\"eb-cia-title\">COMPLETEMENT GRATUIT !<\/h4><p class=\"eb-cia-description\">C&#8217;est la version COMPLETEMENT GRATUITE sans limites !<br>Vous pouvez t\u00e9l\u00e9charger et installer notre programme gratuitement !<\/p><\/div><div class=\"eb-cia-button-wrapper\"><a href=\"https:\/\/expforex.com\/fr\/?p=4177\" target=\"_blank\" rel=\"noopener\"><div class=\"eb-cia-button is-extra-large hvr-pulse-grow\">Je veux pour GRATUIT !<\/div><\/a><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-links\">Links<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Rapport de compte professionnel GRATUIT<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"2\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\"><div class=\"root-eb-toc-n8usydf wp-block-essential-blocks-table-of-contents\"><div class=\"eb-parent-wrapper eb-parent-eb-toc-n8usydf \"><div class=\"eb-toc-container eb-toc-n8usydf  eb-toc-is-not-sticky eb-toc-collapsible eb-toc-initially-collapsed eb-toc-scrollToTop style-1 list-style-none\" data-scroll-top=\"false\" data-scroll-top-icon=\"fas fa-angle-up\" data-collapsible=\"true\" data-sticky-hide-mobile=\"false\" data-sticky=\"false\" data-scroll-target=\"scroll_to_toc\" data-copy-link=\"true\" data-editor-type=\"\" data-hide-desktop=\"false\" data-hide-tab=\"false\" data-hide-mobile=\"false\" data-itemcollapsed=\"false\" data-highlight-scroll=\"false\"><div class=\"eb-toc-header\"><h2 class=\"eb-toc-title\">Table des mati\u00e8res (cliquez pour afficher)<\/h2><\/div><div class=\"eb-toc-wrapper hide-content\" data-headers=\"[{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00c0 propos d&apos;Extra Report Pad&quot;,&quot;text&quot;:&quot;\\u00c0 propos d&apos;Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-0&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Comment fonctionne Extra Report Pad ?&quot;,&quot;text&quot;:&quot;Comment fonctionne Extra Report Pad ?&quot;,&quot;link&quot;:&quot;comment-fonctionne-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Que disent les gens \\u00e0 propos de Extra Report Pad?&quot;,&quot;text&quot;:&quot;Que disent les gens \\u00e0 propos de Extra Report Pad?&quot;,&quot;link&quot;:&quot;eb-table-content-2&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Vous pouvez t\\u00e9l\\u00e9charger l&apos;assistant Extra Report Pad gratuitement&quot;,&quot;text&quot;:&quot;Vous pouvez t\\u00e9l\\u00e9charger l&apos;assistant Extra Report Pad gratuitement&quot;,&quot;link&quot;:&quot;eb-table-content-3&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;COMPLETEMENT GRATUIT !&quot;,&quot;text&quot;:&quot;COMPLETEMENT GRATUIT !&quot;,&quot;link&quot;:&quot;completement-gratuit&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Links&quot;,&quot;text&quot;:&quot;Links&quot;,&quot;link&quot;:&quot;links&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Description&quot;,&quot;text&quot;:&quot;Description&quot;,&quot;link&quot;:&quot;description&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Avant-propos&quot;,&quot;text&quot;:&quot;Avant-propos&quot;,&quot;link&quot;:&quot;avant-propos&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Avantages&quot;,&quot;text&quot;:&quot;Avantages&quot;,&quot;link&quot;:&quot;avantages&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Ancien Rapport D\\u00e9taill\\u00e9 MetaTrader&quot;,&quot;text&quot;:&quot;Ancien Rapport D\\u00e9taill\\u00e9 MetaTrader&quot;,&quot;link&quot;:&quot;eb-table-content-9&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Nouveau Rapport D\\u00e9taill\\u00e9 Cr\\u00e9\\u00e9 par Extra Report Pad&quot;,&quot;text&quot;:&quot;Nouveau Rapport D\\u00e9taill\\u00e9 Cr\\u00e9\\u00e9 par Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-10&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Exporter en HTML et CSV&quot;,&quot;text&quot;:&quot;Exporter en HTML et CSV&quot;,&quot;link&quot;:&quot;exporter-en-html-et-csv&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Exemple de HTML :&quot;,&quot;text&quot;:&quot;Exemple de HTML :&quot;,&quot;link&quot;:&quot;exemple-de-html&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Exemple de CSV :&quot;,&quot;text&quot;:&quot;Exemple de CSV :&quot;,&quot;link&quot;:&quot;exemple-de-csv&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Onglets et Contr\\u00f4les&quot;,&quot;text&quot;:&quot;Onglets et Contr\\u00f4les&quot;,&quot;link&quot;:&quot;eb-table-content-14&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Taille de la Police, Minimiser et Fermer le Panneau. Param\\u00e8tres&quot;,&quot;text&quot;:&quot;Taille de la Police, Minimiser et Fermer le Panneau. Param\\u00e8tres&quot;,&quot;link&quot;:&quot;eb-table-content-15&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Filtres&quot;,&quot;text&quot;:&quot;Filtres&quot;,&quot;link&quot;:&quot;filtres&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet TRADES&quot;,&quot;text&quot;:&quot;Onglet TRADES&quot;,&quot;link&quot;:&quot;onglet-trades&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;HISTORY Onglet&quot;,&quot;text&quot;:&quot;HISTORY Onglet&quot;,&quot;link&quot;:&quot;history-onglet&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;TOUTES LES TRANSACTIONS Onglet&quot;,&quot;text&quot;:&quot;TOUTES LES TRANSACTIONS Onglet&quot;,&quot;link&quot;:&quot;toutes-les-transactions-onglet&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;RAPPORTS Onglet&quot;,&quot;text&quot;:&quot;RAPPORTS Onglet&quot;,&quot;link&quot;:&quot;rapports-onglet&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet Graphique&quot;,&quot;text&quot;:&quot;Onglet Graphique&quot;,&quot;link&quot;:&quot;onglet-graphique&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet DISTRIBUTION&quot;,&quot;text&quot;:&quot;Onglet DISTRIBUTION&quot;,&quot;link&quot;:&quot;onglet-distribution&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet Symboles, Magics, Commentaires&quot;,&quot;text&quot;:&quot;Onglet Symboles, Magics, Commentaires&quot;,&quot;link&quot;:&quot;onglet-symboles-magics-commentaires&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Conclusions&quot;,&quot;text&quot;:&quot;Conclusions&quot;,&quot;link&quot;:&quot;conclusions&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Variables externes et param\\u00e8tres d&apos;Extra Report Pad&quot;,&quot;text&quot;:&quot;Variables externes et param\\u00e8tres d&apos;Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-25&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Questions et r\\u00e9ponses fr\\u00e9quentes sur Extra Report Pad&quot;,&quot;text&quot;:&quot;Questions et r\\u00e9ponses fr\\u00e9quentes sur Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-26&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Journal Extra Report Pad&quot;,&quot;text&quot;:&quot;Journal Extra Report Pad&quot;,&quot;link&quot;:&quot;journal-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Avis sur Extra Report Pad&quot;,&quot;text&quot;:&quot;Avis sur Extra Report Pad&quot;,&quot;link&quot;:&quot;avis-sur-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Commentaires sur Extra Report Pad&quot;,&quot;text&quot;:&quot;Commentaires sur Extra Report Pad&quot;,&quot;link&quot;:&quot;commentaires-sur-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Extra&quot;,&quot;text&quot;:&quot;Extra&quot;,&quot;link&quot;:&quot;extra&quot;}]\" data-visible=\"[true,true,true,true,true,false]\" data-delete-headers=\"[{&quot;label&quot;:&quot;\\u00c0 propos d&apos;Extra Report Pad&quot;,&quot;value&quot;:&quot;\\u00e0-propos-dextra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Comment fonctionne Extra Report Pad ?&quot;,&quot;value&quot;:&quot;comment-fonctionne-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Que disent les gens \\u00e0 propos de Extra Report Pad?&quot;,&quot;value&quot;:&quot;que-disent-les-gens-\\u00e0-propos-de-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Vous pouvez t\\u00e9l\\u00e9charger l&apos;assistant Extra Report Pad gratuitement&quot;,&quot;value&quot;:&quot;vous-pouvez-t\\u00e9l\\u00e9charger-lassistant-extra-report-pad-gratuitement&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;COMPLETEMENT GRATUIT !&quot;,&quot;value&quot;:&quot;completement-gratuit&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Links&quot;,&quot;value&quot;:&quot;links&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Description&quot;,&quot;value&quot;:&quot;description&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Avant-propos&quot;,&quot;value&quot;:&quot;avant-propos&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Avantages&quot;,&quot;value&quot;:&quot;avantages&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Ancien Rapport D\\u00e9taill\\u00e9 MetaTrader&quot;,&quot;value&quot;:&quot;ancien-rapport-d\\u00e9taill\\u00e9-metatrader&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Nouveau Rapport D\\u00e9taill\\u00e9 Cr\\u00e9\\u00e9 par Extra Report Pad&quot;,&quot;value&quot;:&quot;nouveau-rapport-d\\u00e9taill\\u00e9-cr\\u00e9\\u00e9-par-extra-report-pad&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Exporter en HTML et CSV&quot;,&quot;value&quot;:&quot;exporter-en-html-et-csv&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Exemple de HTML :&quot;,&quot;value&quot;:&quot;exemple-de-html&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Exemple de CSV :&quot;,&quot;value&quot;:&quot;exemple-de-csv&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglets et Contr\\u00f4les&quot;,&quot;value&quot;:&quot;onglets-et-contr\\u00f4les&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Taille de la Police, Minimiser et Fermer le Panneau. Param\\u00e8tres&quot;,&quot;value&quot;:&quot;taille-de-la-police-minimiser-et-fermer-le-panneau-param\\u00e8tres&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Filtres&quot;,&quot;value&quot;:&quot;filtres&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet TRADES&quot;,&quot;value&quot;:&quot;onglet-trades&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;HISTORY Onglet&quot;,&quot;value&quot;:&quot;history-onglet&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;TOUTES LES TRANSACTIONS Onglet&quot;,&quot;value&quot;:&quot;toutes-les-transactions-onglet&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;RAPPORTS Onglet&quot;,&quot;value&quot;:&quot;rapports-onglet&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet Graphique&quot;,&quot;value&quot;:&quot;onglet-graphique&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet DISTRIBUTION&quot;,&quot;value&quot;:&quot;onglet-distribution&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet Symboles, Magics, Commentaires&quot;,&quot;value&quot;:&quot;onglet-symboles-magics-commentaires&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Conclusions&quot;,&quot;value&quot;:&quot;conclusions&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Variables externes et param\\u00e8tres d&apos;Extra Report Pad&quot;,&quot;value&quot;:&quot;variables-externes-et-param\\u00e8tres-dextra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Questions et r\\u00e9ponses fr\\u00e9quentes sur Extra Report Pad&quot;,&quot;value&quot;:&quot;questions-et-r\\u00e9ponses-fr\\u00e9quentes-sur-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Journal Extra Report Pad&quot;,&quot;value&quot;:&quot;journal-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Avis sur Extra Report Pad&quot;,&quot;value&quot;:&quot;avis-sur-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Commentaires sur Extra Report Pad&quot;,&quot;value&quot;:&quot;commentaires-sur-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Extra&quot;,&quot;value&quot;:&quot;extra&quot;,&quot;isDelete&quot;:true}]\" data-smooth=\"true\" data-top-offset=\"500\"><div class=\"eb-toc__list-wrap\"><ul class=\"eb-toc__list\"><li><a href=\"#description\">Description<\/a><ul class=\"eb-toc__list\"><li><a href=\"#avant-propos\">Avant-propos<\/a><li><a href=\"#avantages\">Avantages<\/a><li><a href=\"#eb-table-content-9\">Ancien Rapport D\u00e9taill\u00e9 MetaTrader<\/a><li><a href=\"#eb-table-content-10\">Nouveau Rapport D\u00e9taill\u00e9 Cr\u00e9\u00e9 par Extra Report Pad<\/a><\/li><\/ul><li><a href=\"#exporter-en-html-et-csv\">Exporter en HTML et CSV<\/a><ul class=\"eb-toc__list\"><li><a href=\"#exemple-de-html\">Exemple de HTML :<\/a><li><a href=\"#exemple-de-csv\">Exemple de CSV :<\/a><\/li><\/ul><li><a href=\"#eb-table-content-14\">Onglets et Contr\u00f4les<\/a><ul class=\"eb-toc__list\"><li><a href=\"#eb-table-content-15\">Taille de la Police, Minimiser et Fermer le Panneau. Param\u00e8tres<\/a><li><a href=\"#filtres\">Filtres<\/a><li><a href=\"#onglet-trades\">Onglet TRADES<\/a><li><a href=\"#history-onglet\">HISTORY Onglet<\/a><li><a href=\"#toutes-les-transactions-onglet\">TOUTES LES TRANSACTIONS Onglet<\/a><li><a href=\"#rapports-onglet\">RAPPORTS Onglet<\/a><li><a href=\"#onglet-graphique\">Onglet Graphique<\/a><li><a href=\"#onglet-distribution\">Onglet DISTRIBUTION<\/a><li><a href=\"#onglet-symboles-magics-commentaires\">Onglet Symboles, Magics, Commentaires<\/a><\/li><\/ul><li><a href=\"#conclusions\">Conclusions<\/a><\/ul><\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"root-eb-toc-f2xgj wp-block-essential-blocks-table-of-contents\"><div class=\"eb-parent-wrapper eb-parent-eb-toc-f2xgj \"><div class=\"eb-toc-container eb-toc-f2xgj eb-toc-sticky-right eb-toc-is-sticky eb-toc-collapsible eb-toc-initially-collapsed eb-toc-scrollToTop style-1 \" data-scroll-top=\"false\" data-scroll-top-icon=\"fas fa-angle-up\" data-collapsible=\"true\" data-sticky-hide-mobile=\"true\" data-sticky=\"true\" data-scroll-target=\"scroll_to_toc\" data-copy-link=\"true\" data-editor-type=\"\" data-hide-desktop=\"false\" data-hide-tab=\"false\" data-hide-mobile=\"false\" data-itemcollapsed=\"true\" data-highlight-scroll=\"false\"><div class=\"eb-toc-header\"><span class=\"eb-toc-close eb-toc-sticky-right\"><\/span><h2 class=\"eb-toc-title\">List<\/h2><\/div><div class=\"eb-toc-wrapper \" data-headers=\"[{&quot;level&quot;:2,&quot;content&quot;:&quot;\\u00c0 propos d&apos;Extra Report Pad&quot;,&quot;text&quot;:&quot;\\u00c0 propos d&apos;Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-0&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Comment fonctionne Extra Report Pad ?&quot;,&quot;text&quot;:&quot;Comment fonctionne Extra Report Pad ?&quot;,&quot;link&quot;:&quot;comment-fonctionne-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Que disent les gens \\u00e0 propos de Extra Report Pad?&quot;,&quot;text&quot;:&quot;Que disent les gens \\u00e0 propos de Extra Report Pad?&quot;,&quot;link&quot;:&quot;eb-table-content-2&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Vous pouvez t\\u00e9l\\u00e9charger l&apos;assistant Extra Report Pad gratuitement&quot;,&quot;text&quot;:&quot;Vous pouvez t\\u00e9l\\u00e9charger l&apos;assistant Extra Report Pad gratuitement&quot;,&quot;link&quot;:&quot;eb-table-content-3&quot;},{&quot;level&quot;:4,&quot;content&quot;:&quot;COMPLETEMENT GRATUIT !&quot;,&quot;text&quot;:&quot;COMPLETEMENT GRATUIT !&quot;,&quot;link&quot;:&quot;completement-gratuit&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Links&quot;,&quot;text&quot;:&quot;Links&quot;,&quot;link&quot;:&quot;links&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Description&quot;,&quot;text&quot;:&quot;Description&quot;,&quot;link&quot;:&quot;description&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Avant-propos&quot;,&quot;text&quot;:&quot;Avant-propos&quot;,&quot;link&quot;:&quot;avant-propos&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Avantages&quot;,&quot;text&quot;:&quot;Avantages&quot;,&quot;link&quot;:&quot;avantages&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Ancien Rapport D\\u00e9taill\\u00e9 MetaTrader&quot;,&quot;text&quot;:&quot;Ancien Rapport D\\u00e9taill\\u00e9 MetaTrader&quot;,&quot;link&quot;:&quot;eb-table-content-9&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Nouveau Rapport D\\u00e9taill\\u00e9 Cr\\u00e9\\u00e9 par Extra Report Pad&quot;,&quot;text&quot;:&quot;Nouveau Rapport D\\u00e9taill\\u00e9 Cr\\u00e9\\u00e9 par Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-10&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Exporter en HTML et CSV&quot;,&quot;text&quot;:&quot;Exporter en HTML et CSV&quot;,&quot;link&quot;:&quot;exporter-en-html-et-csv&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Exemple de HTML :&quot;,&quot;text&quot;:&quot;Exemple de HTML :&quot;,&quot;link&quot;:&quot;exemple-de-html&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Exemple de CSV :&quot;,&quot;text&quot;:&quot;Exemple de CSV :&quot;,&quot;link&quot;:&quot;exemple-de-csv&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Onglets et Contr\\u00f4les&quot;,&quot;text&quot;:&quot;Onglets et Contr\\u00f4les&quot;,&quot;link&quot;:&quot;eb-table-content-14&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Taille de la Police, Minimiser et Fermer le Panneau. Param\\u00e8tres&quot;,&quot;text&quot;:&quot;Taille de la Police, Minimiser et Fermer le Panneau. Param\\u00e8tres&quot;,&quot;link&quot;:&quot;eb-table-content-15&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Filtres&quot;,&quot;text&quot;:&quot;Filtres&quot;,&quot;link&quot;:&quot;filtres&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet TRADES&quot;,&quot;text&quot;:&quot;Onglet TRADES&quot;,&quot;link&quot;:&quot;onglet-trades&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;HISTORY Onglet&quot;,&quot;text&quot;:&quot;HISTORY Onglet&quot;,&quot;link&quot;:&quot;history-onglet&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;TOUTES LES TRANSACTIONS Onglet&quot;,&quot;text&quot;:&quot;TOUTES LES TRANSACTIONS Onglet&quot;,&quot;link&quot;:&quot;toutes-les-transactions-onglet&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;RAPPORTS Onglet&quot;,&quot;text&quot;:&quot;RAPPORTS Onglet&quot;,&quot;link&quot;:&quot;rapports-onglet&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet Graphique&quot;,&quot;text&quot;:&quot;Onglet Graphique&quot;,&quot;link&quot;:&quot;onglet-graphique&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet DISTRIBUTION&quot;,&quot;text&quot;:&quot;Onglet DISTRIBUTION&quot;,&quot;link&quot;:&quot;onglet-distribution&quot;},{&quot;level&quot;:3,&quot;content&quot;:&quot;Onglet Symboles, Magics, Commentaires&quot;,&quot;text&quot;:&quot;Onglet Symboles, Magics, Commentaires&quot;,&quot;link&quot;:&quot;onglet-symboles-magics-commentaires&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Conclusions&quot;,&quot;text&quot;:&quot;Conclusions&quot;,&quot;link&quot;:&quot;conclusions&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Variables externes et param\\u00e8tres d&apos;Extra Report Pad&quot;,&quot;text&quot;:&quot;Variables externes et param\\u00e8tres d&apos;Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-25&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Questions et r\\u00e9ponses fr\\u00e9quentes sur Extra Report Pad&quot;,&quot;text&quot;:&quot;Questions et r\\u00e9ponses fr\\u00e9quentes sur Extra Report Pad&quot;,&quot;link&quot;:&quot;eb-table-content-26&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Journal Extra Report Pad&quot;,&quot;text&quot;:&quot;Journal Extra Report Pad&quot;,&quot;link&quot;:&quot;journal-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Avis sur Extra Report Pad&quot;,&quot;text&quot;:&quot;Avis sur Extra Report Pad&quot;,&quot;link&quot;:&quot;avis-sur-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Commentaires sur Extra Report Pad&quot;,&quot;text&quot;:&quot;Commentaires sur Extra Report Pad&quot;,&quot;link&quot;:&quot;commentaires-sur-extra-report-pad&quot;},{&quot;level&quot;:2,&quot;content&quot;:&quot;Extra&quot;,&quot;text&quot;:&quot;Extra&quot;,&quot;link&quot;:&quot;extra&quot;}]\" data-visible=\"[true,true,true,true,false,false]\" data-delete-headers=\"[{&quot;label&quot;:&quot;\\u00c0 propos d&apos;Extra Report Pad&quot;,&quot;value&quot;:&quot;\\u00e0-propos-dextra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Comment fonctionne Extra Report Pad ?&quot;,&quot;value&quot;:&quot;comment-fonctionne-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Que disent les gens \\u00e0 propos de Extra Report Pad?&quot;,&quot;value&quot;:&quot;que-disent-les-gens-\\u00e0-propos-de-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Vous pouvez t\\u00e9l\\u00e9charger l&apos;assistant Extra Report Pad gratuitement&quot;,&quot;value&quot;:&quot;vous-pouvez-t\\u00e9l\\u00e9charger-lassistant-extra-report-pad-gratuitement&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;COMPLETEMENT GRATUIT !&quot;,&quot;value&quot;:&quot;completement-gratuit&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Links&quot;,&quot;value&quot;:&quot;links&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Description&quot;,&quot;value&quot;:&quot;description&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Avant-propos&quot;,&quot;value&quot;:&quot;avant-propos&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Avantages&quot;,&quot;value&quot;:&quot;avantages&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Ancien Rapport D\\u00e9taill\\u00e9 MetaTrader&quot;,&quot;value&quot;:&quot;ancien-rapport-d\\u00e9taill\\u00e9-metatrader&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Nouveau Rapport D\\u00e9taill\\u00e9 Cr\\u00e9\\u00e9 par Extra Report Pad&quot;,&quot;value&quot;:&quot;nouveau-rapport-d\\u00e9taill\\u00e9-cr\\u00e9\\u00e9-par-extra-report-pad&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Exporter en HTML et CSV&quot;,&quot;value&quot;:&quot;exporter-en-html-et-csv&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Exemple de HTML :&quot;,&quot;value&quot;:&quot;exemple-de-html&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Exemple de CSV :&quot;,&quot;value&quot;:&quot;exemple-de-csv&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglets et Contr\\u00f4les&quot;,&quot;value&quot;:&quot;onglets-et-contr\\u00f4les&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Taille de la Police, Minimiser et Fermer le Panneau. Param\\u00e8tres&quot;,&quot;value&quot;:&quot;taille-de-la-police-minimiser-et-fermer-le-panneau-param\\u00e8tres&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Filtres&quot;,&quot;value&quot;:&quot;filtres&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet TRADES&quot;,&quot;value&quot;:&quot;onglet-trades&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;HISTORY Onglet&quot;,&quot;value&quot;:&quot;history-onglet&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;TOUTES LES TRANSACTIONS Onglet&quot;,&quot;value&quot;:&quot;toutes-les-transactions-onglet&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;RAPPORTS Onglet&quot;,&quot;value&quot;:&quot;rapports-onglet&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet Graphique&quot;,&quot;value&quot;:&quot;onglet-graphique&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet DISTRIBUTION&quot;,&quot;value&quot;:&quot;onglet-distribution&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Onglet Symboles, Magics, Commentaires&quot;,&quot;value&quot;:&quot;onglet-symboles-magics-commentaires&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Conclusions&quot;,&quot;value&quot;:&quot;conclusions&quot;,&quot;isDelete&quot;:false},{&quot;label&quot;:&quot;Variables externes et param\\u00e8tres d&apos;Extra Report Pad&quot;,&quot;value&quot;:&quot;variables-externes-et-param\\u00e8tres-dextra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Questions et r\\u00e9ponses fr\\u00e9quentes sur Extra Report Pad&quot;,&quot;value&quot;:&quot;questions-et-r\\u00e9ponses-fr\\u00e9quentes-sur-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Journal Extra Report Pad&quot;,&quot;value&quot;:&quot;journal-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Avis sur Extra Report Pad&quot;,&quot;value&quot;:&quot;avis-sur-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Commentaires sur Extra Report Pad&quot;,&quot;value&quot;:&quot;commentaires-sur-extra-report-pad&quot;,&quot;isDelete&quot;:true},{&quot;label&quot;:&quot;Extra&quot;,&quot;value&quot;:&quot;extra&quot;,&quot;isDelete&quot;:true}]\" data-smooth=\"true\" data-top-offset=\"150\"><div class=\"eb-toc__list-wrap\"><ul class=\"eb-toc__list\"><li><a href=\"#description\">Description<\/a><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\">\n                    <path d=\"M6.75 9.75L9 7.5L11.25 9.75\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <path d=\"M9 15.75C9.88642 15.75 10.7642 15.5754 11.5831 15.2362C12.4021 14.897 13.1462 14.3998 13.773 13.773C14.3998 13.1462 14.897 12.4021 15.2362 11.5831C15.5754 10.7642 15.75 9.88642 15.75 9C15.75 8.11358 15.5754 7.23583 15.2362 6.41689C14.897 5.59794 14.3998 4.85383 13.773 4.22703C13.1462 3.60023 12.4021 3.10303 11.5831 2.76381C10.7642 2.42459 9.88642 2.25 9 2.25C7.20979 2.25 5.4929 2.96116 4.22703 4.22703C2.96116 5.4929 2.25 7.20979 2.25 9C2.25 10.7902 2.96116 12.5071 4.22703 13.773C5.4929 15.0388 7.20979 15.75 9 15.75Z\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <\/svg><ul class=\"eb-toc__list\"><li><a href=\"#avant-propos\">Avant-propos<\/a><li><a href=\"#avantages\">Avantages<\/a><li><a href=\"#eb-table-content-9\">Ancien Rapport D\u00e9taill\u00e9 MetaTrader<\/a><li><a href=\"#eb-table-content-10\">Nouveau Rapport D\u00e9taill\u00e9 Cr\u00e9\u00e9 par Extra Report Pad<\/a><\/li><\/ul><li><a href=\"#exporter-en-html-et-csv\">Exporter en HTML et CSV<\/a><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\">\n                    <path d=\"M6.75 9.75L9 7.5L11.25 9.75\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <path d=\"M9 15.75C9.88642 15.75 10.7642 15.5754 11.5831 15.2362C12.4021 14.897 13.1462 14.3998 13.773 13.773C14.3998 13.1462 14.897 12.4021 15.2362 11.5831C15.5754 10.7642 15.75 9.88642 15.75 9C15.75 8.11358 15.5754 7.23583 15.2362 6.41689C14.897 5.59794 14.3998 4.85383 13.773 4.22703C13.1462 3.60023 12.4021 3.10303 11.5831 2.76381C10.7642 2.42459 9.88642 2.25 9 2.25C7.20979 2.25 5.4929 2.96116 4.22703 4.22703C2.96116 5.4929 2.25 7.20979 2.25 9C2.25 10.7902 2.96116 12.5071 4.22703 13.773C5.4929 15.0388 7.20979 15.75 9 15.75Z\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <\/svg><ul class=\"eb-toc__list\"><li><a href=\"#exemple-de-html\">Exemple de HTML :<\/a><li><a href=\"#exemple-de-csv\">Exemple de CSV :<\/a><\/li><\/ul><li><a href=\"#eb-table-content-14\">Onglets et Contr\u00f4les<\/a><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\">\n                    <path d=\"M6.75 9.75L9 7.5L11.25 9.75\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <path d=\"M9 15.75C9.88642 15.75 10.7642 15.5754 11.5831 15.2362C12.4021 14.897 13.1462 14.3998 13.773 13.773C14.3998 13.1462 14.897 12.4021 15.2362 11.5831C15.5754 10.7642 15.75 9.88642 15.75 9C15.75 8.11358 15.5754 7.23583 15.2362 6.41689C14.897 5.59794 14.3998 4.85383 13.773 4.22703C13.1462 3.60023 12.4021 3.10303 11.5831 2.76381C10.7642 2.42459 9.88642 2.25 9 2.25C7.20979 2.25 5.4929 2.96116 4.22703 4.22703C2.96116 5.4929 2.25 7.20979 2.25 9C2.25 10.7902 2.96116 12.5071 4.22703 13.773C5.4929 15.0388 7.20979 15.75 9 15.75Z\" stroke=\"#252D3B\" stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\n                    <\/svg><ul class=\"eb-toc__list\"><li><a href=\"#eb-table-content-15\">Taille de la Police, Minimiser et Fermer le Panneau. Param\u00e8tres<\/a><li><a href=\"#filtres\">Filtres<\/a><li><a href=\"#onglet-trades\">Onglet TRADES<\/a><li><a href=\"#history-onglet\">HISTORY Onglet<\/a><li><a href=\"#toutes-les-transactions-onglet\">TOUTES LES TRANSACTIONS Onglet<\/a><li><a href=\"#rapports-onglet\">RAPPORTS Onglet<\/a><li><a href=\"#onglet-graphique\">Onglet Graphique<\/a><li><a href=\"#onglet-distribution\">Onglet DISTRIBUTION<\/a><li><a href=\"#onglet-symboles-magics-commentaires\">Onglet Symboles, Magics, Commentaires<\/a><\/li><\/ul><li><a href=\"#conclusions\">Conclusions<\/a><\/ul><\/div><\/div><button class=\"eb-toc-button  eb-toc-button-right\"><div>List<\/div><\/button><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-description\">Description<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Extra Report Pad<\/strong> est une <strong>solution professionnelle<\/strong> pour <strong>analyser efficacement votre compte de trading<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trader&#8217;s Diary<\/strong> analyse professionnellement votre compte de trading, similaire \u00e0 <strong>MyFxBook<\/strong> avec des graphiques en direct.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd&#8217;hui, il est essentiel de trader plusieurs paires de devises simultan\u00e9ment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Extra Report Pad<\/strong> est un <strong>outil professionnel<\/strong> pour analyser votre compte de trading. <strong>Trader&#8217;s Diary<\/strong> analyse professionnellement votre compte de trading sur des graphiques en direct, tout comme <strong>MyFxBook<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, plus vous effectuez de transactions, plus il devient difficile de <strong>analyser professionnellement<\/strong> la rentabilit\u00e9 de votre compte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Analyser les transactions par mois devient encore plus difficile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, calculer des <strong>donn\u00e9es statistiques<\/strong> pour chaque transaction individuellement est encore plus complexe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons trouv\u00e9 une solution : <strong>Notre panneau peut <strong>analyser professionnellement<\/strong> votre compte et compiler des statistiques en autant de d\u00e9tails que possible en temps r\u00e9el.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un <strong>indicateur<\/strong> pour collecter et analyser votre compte de trading.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/extrareportpad2018new1.gif\" alt=\"Extra Report Pad : Notre panneau peut analyser professionnellement votre compte et compiler des statistiques en temps r\u00e9el\" class=\"wp-image-70438\"\/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-avant-propos\">Avant-propos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis le d\u00e9but de notre activit\u00e9 sur le Forex, beaucoup de temps s&#8217;est \u00e9coul\u00e9, et le trading sur le march\u00e9 Forex nous a occup\u00e9s avec des t\u00e2ches telles que l&#8217;analyse des comptes de trading. Cela est particuli\u00e8rement vrai pour les experts qui s&#8217;appuient sur des syst\u00e8mes automatis\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Analyser les paires de devises rentables \u00e0 partir du rapport standard <strong>MetaTrader<\/strong> est tr\u00e8s difficile. Il ne contient pas de donn\u00e9es d\u00e9taill\u00e9es sur les transactions, sans parler des donn\u00e9es sur les paires de devises rentables et des statistiques mensuelles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez surveiller votre compte en utilisant l&#8217;un des services de collecte de <strong>statistiques<\/strong>, mais ce n&#8217;est pas enti\u00e8rement pratique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es ne sont pas obtenues <strong>en temps r\u00e9el<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Lors du test de l&#8217;un de nos <strong><a href=\"https:\/\/www.expforex.com\/fr\/?p=10\" target=\"_blank\" rel=\"noreferrer noopener\">scalpeurs pour le Forex, TickSniper,<\/a><\/strong> nous avons rencontr\u00e9 pr\u00e9cis\u00e9ment ce probl\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D&#8217;ailleurs, vous pouvez voir un exemple de <a href=\"https:\/\/expforex.com\/fr\/trade-statistics-of-ticksniper-and-the-best-advisors-from-expforex\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>rapport avec Extra Report Pad pour TickSniper<\/strong><\/a>.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir test\u00e9 sur une p\u00e9riode mensuelle, nous avons d\u00fb diss\u00e9quer manuellement le rapport pour d\u00e9terminer quelles paires \u00e9taient rentables et lesquelles ne l&#8217;\u00e9taient pas\u2014et en fonction des donn\u00e9es, affiner davantage le syst\u00e8me.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Nous avons trouv\u00e9 une solution \u00e0 ce probl\u00e8me et cr\u00e9\u00e9 l&#8217;indicateur <strong>EXTRA REPORT PAD<\/strong>, capable d&#8217;<strong>analyser professionnellement<\/strong> votre compte automatiquement et d&#8217;afficher des informations d\u00e9taill\u00e9es en <strong>temps r\u00e9el !<\/strong><\/strong><\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-avantages\">Avantages<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Notre <strong>indicateur<\/strong> est con\u00e7u pour analyser le trading Forex en temps r\u00e9el. Utilisez des statistiques compl\u00e8tes et toutes les donn\u00e9es pouvant \u00eatre extraites du terminal <strong>MetaTrader<\/strong> !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MyFxBook Mini<\/strong> est int\u00e9gr\u00e9 dans votre fen\u00eatre de terminal et est toujours \u00e0 port\u00e9e de main !<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Un rapport d\u00e9taill\u00e9 t\u00e9l\u00e9charg\u00e9 en HTML contient 500% plus d&#8217;informations que le rapport standard MT.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/ezgif-5-0b2fb33764-1200x675.gif\" alt=\"Extra Report Pad : Un rapport d\u00e9taill\u00e9 t\u00e9l\u00e9charg\u00e9 en HTML contient 500% plus d'informations que le rapport standard MT.\" class=\"wp-image-27172\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/ezgif-5-0b2fb33764-1200x675.gif 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/ezgif-5-0b2fb33764-500x281.gif 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/ezgif-5-0b2fb33764-300x169.gif 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/ezgif-5-0b2fb33764-768x432.gif 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/ezgif-5-0b2fb33764-133x75.gif 133w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/ezgif-5-0b2fb33764-700x394.gif 700w\" sizes=\"(max-width:767px) 700px, (max-width:1200px) 100vw, 1200px\" \/><\/figure>\n<\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1276\" height=\"1055\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28.png\" alt=\"Extra Report Pad : Rapports HTML Standard et Extra\" class=\"wp-image-70619\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28.png 1276w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28-500x413.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28-1200x992.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28-300x248.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28-768x635.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28-91x75.png 91w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-25-28-700x579.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1276px) 100vw, 1276px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ancien-rapport-detaille-metatrader\">Ancien Rapport D\u00e9taill\u00e9 MetaTrader<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"589\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s515966811-1.jpg\" alt=\"Extra Report Pad : Ancien Rapport D\u00e9taill\u00e9 MetaTrader\" class=\"wp-image-7071\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s515966811-1.jpg 800w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s515966811-1-500x368.jpg 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s515966811-1-300x221.jpg 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s515966811-1-768x565.jpg 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s515966811-1-102x75.jpg 102w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s515966811-1-700x515.jpg 700w\" sizes=\"(max-width:767px) 700px, (max-width:800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-nouveau-rapport-detaille-cree-par-extra-report-pad\">Nouveau Rapport D\u00e9taill\u00e9 Cr\u00e9\u00e9 par Extra Report Pad<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"525\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-1200x525.png\" alt=\"Extra Report Pad : Nouveau Rapport D\u00e9taill\u00e9 Cr\u00e9\u00e9 par Extra Report Pad\" class=\"wp-image-27189\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-1200x525.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-500x219.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-300x131.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-768x336.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-1536x672.png 1536w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-150x66.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43-700x306.png 700w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-22_17-48-43.png 1879w\" sizes=\"(max-width:767px) 700px, (max-width:1200px) 100vw, 1200px\" \/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1885\" height=\"800\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41.png\" alt=\"Extra Report Pad : Nouveau Rapport de MetaTrader\" class=\"wp-image-70631\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41.png 1885w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41-500x212.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41-1200x509.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41-300x127.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41-768x326.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41-1536x652.png 1536w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41-150x64.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2024-11-15_11-30-41-700x297.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1885px) 100vw, 1885px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1048\" height=\"516\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-18-02.png\" alt=\"Extra Report Pad\" class=\"wp-image-27169\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-18-02.png 1048w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-18-02-500x246.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-18-02-300x148.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-18-02-768x378.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-18-02-150x75.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-18-02-700x345.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1048px) 100vw, 1048px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-exporter-en-html-et-csv\">Exporter en HTML et CSV<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons ajout\u00e9 le bouton <strong>EXPORTER en HTML<\/strong> \u00e0 Extra Report Pad, qui exporte l&#8217;ensemble du rapport depuis le graphique dans un fichier HTML s\u00e9par\u00e9.<br>Toutes les transactions sont filtr\u00e9es selon les filtres utilis\u00e9s dans le panneau.<br>Par exemple, vous pouvez s\u00e9lectionner une seule paire de devises, un num\u00e9ro magique sp\u00e9cifique ou un mois sp\u00e9cifique.<br>Le rapport g\u00e9n\u00e9r\u00e9 ne contiendra que les donn\u00e9es filtr\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour ouvrir votre Rapport D\u00e9taill\u00e9 HTML :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ouvrez le dossier Data.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"415\" height=\"400\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-6.png\" alt=\"Extra Report Pad : Ouvrir le Dossier Data\" class=\"wp-image-5622\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-6.png 415w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-6-300x289.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-6-78x75.png 78w\" sizes=\"(max-width:767px) 415px, 415px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le fichier de rapport est cr\u00e9\u00e9 dans le dossier : <strong>VOTRE TERMINAL  MQL4  Files  EXTRAREPORTPAD  EXTRAREPORTPAD<\/strong> AccountNumber.html<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"640\" height=\"470\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-7.png\" alt=\"Le fichier de rapport est cr\u00e9\u00e9 dans le dossier : VOTRE TERMINAL  MQL4  Files  EXTRAREPORTPAD  EXTRAREPORTPAD AccountNumber.html\" class=\"wp-image-5623\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-7.png 640w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-7-500x367.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-7-300x220.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/01\/image-7-102x75.png 102w\" sizes=\"(max-width:767px) 640px, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-exemple-de-html\">Exemple de HTML :<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2018-08-28_12-31-00.png\" alt=\"\" class=\"wp-image-70643\" style=\"object-fit:cover\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2018-08-28_12-31-00.png 640w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2018-08-28_12-31-00-500x375.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2018-08-28_12-31-00-300x225.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2018-08-28_12-31-00-100x75.png 100w\" sizes=\"(max-width:767px) 640px, 640px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1437\" height=\"672\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25.png\" alt=\"Extra Report Pad : Exemple\" class=\"wp-image-70655\" style=\"object-fit:cover\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25.png 1437w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25-500x234.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25-1200x561.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25-300x140.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25-768x359.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25-150x70.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/11\/2021-09-07_9-46-25-700x327.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1437px) 100vw, 1437px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"926\" height=\"857\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-17-33.png\" alt=\"Extra Report Pad : Rapport D\u00e9taill\u00e9\" class=\"wp-image-27171\" style=\"object-fit:cover\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-17-33.png 926w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-17-33-500x463.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-17-33-300x278.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-17-33-768x711.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-17-33-81x75.png 81w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-17-33-700x648.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:926px) 100vw, 926px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"985\" height=\"493\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-19-11.png\" alt=\"Extra Report Pad : Performance Graphique\" class=\"wp-image-27170\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-19-11.png 985w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-19-11-500x250.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-19-11-300x150.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-19-11-768x384.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-19-11-150x75.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_12-19-11-700x350.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:985px) 100vw, 985px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-exemple-de-csv\">Exemple de CSV :<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"180\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-1200x180.jpg\" alt=\"Extra Report Pad : Exemple CSV\" class=\"wp-image-5647\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-1200x180.jpg 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-500x75.jpg 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-300x45.jpg 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-768x115.jpg 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-1536x230.jpg 1536w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-150x22.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19-700x105.jpg 700w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-01-02_20-07-19.jpg 1764w\" sizes=\"(max-width:767px) 700px, (max-width:1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-onglets-et-controles\">Onglets et Contr\u00f4les<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Notre panneau se compose actuellement de 9 onglets :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>TRADES<\/strong> &#8211; Affiche les transactions actuellement ouvertes.<\/li>\n\n\n\n<li><strong>HISTORY<\/strong> &#8211; Affiche les transactions ferm\u00e9es de l&#8217;historique.<\/li>\n\n\n\n<li><strong>TOUTES LES TRANSACTIONS<\/strong> &#8211; Affiche \u00e0 la fois les transactions ouvertes et ferm\u00e9es.<\/li>\n\n\n\n<li><strong>RAPPORTS<\/strong> &#8211; Montre un rapport d\u00e9taill\u00e9 sur les transactions ferm\u00e9es de votre compte de trading.<\/li>\n\n\n\n<li><strong>GRAPHIQUE DE PROFIT<\/strong> &#8211; Fournit une repr\u00e9sentation visuelle des tendances de profit au fil du temps, vous permettant d&#8217;\u00e9valuer la rentabilit\u00e9 globale de vos transactions et de voir les sch\u00e9mas ou fluctuations dans vos performances de trading.<\/li>\n\n\n\n<li><strong>DISTRIBUTION Symboles<\/strong> &#8211; Montre la distribution des transactions ACHAT et VENTE avec le nombre total, ainsi que le nombre de transactions rentables pour chaque paire de devises s\u00e9par\u00e9ment. Il affiche \u00e9galement la distribution des transactions rentables, leur profit total et la taille du lot pour chaque paire de devises individuellement, ainsi que la distribution des transactions perdantes pour chaque symbole.<\/li>\n\n\n\n<li><strong>DISTRIBUTION par Commentaires<\/strong> &#8211; Montre la distribution des transactions cat\u00e9goris\u00e9es par des commentaires sp\u00e9cifiques, y compris le nombre total de transactions ACHAT et VENTE, les transactions rentables, leur profit total et la taille du lot bas\u00e9 sur chaque commentaire unique. Il montre \u00e9galement la distribution des transactions perdantes pour chaque cat\u00e9gorie de commentaires.<\/li>\n\n\n\n<li><strong>DISTRIBUTION par Num\u00e9ros Magiques<\/strong> &#8211; Montre la distribution des transactions cat\u00e9goris\u00e9es par num\u00e9ros magiques, d\u00e9taillant le nombre total de transactions ACHAT et VENTE, les transactions rentables, leur profit total et la taille du lot pour chaque num\u00e9ro magique individuellement. Il affiche \u00e9galement la distribution des transactions perdantes pour chaque num\u00e9ro magique.<\/li>\n\n\n\n<li><strong>DISTRIBUTION Temps<\/strong> &#8211; Affiche le nombre de transactions, ainsi que le profit ou la perte par heures, jours de la semaine et mois. En regardant les noms des colonnes, vous pouvez obtenir des donn\u00e9es pour chaque cat\u00e9gorie.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Notre panneau est construit sur un mod\u00e8le am\u00e9lior\u00e9 des panneaux de trading <strong><a href=\"https:\/\/www.expforex.com\/fr\/?p=15\" target=\"_blank\" rel=\"noreferrer noopener\">VIRTUALTRADEPAD<\/a><\/strong> et <strong><a href=\"https:\/\/www.expforex.com\/fr\/?p=35\" target=\"_blank\" rel=\"noreferrer noopener\">EAPADPRO<\/a><\/strong>, donc certains \u00e9l\u00e9ments sont r\u00e9p\u00e9t\u00e9s.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Attention !<\/strong> Pour afficher toutes les positions de l&#8217;historique du compte, vous devez s\u00e9lectionner l&#8217;onglet historique complet du compte dans Historique du Compte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Allez \u00e0 l&#8217;onglet Historique du Compte et faites un clic droit &#8211; s\u00e9lectionnez<\/strong> <strong>Tout l&#8217;Historique<\/strong>.<\/p>\n<\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"758\" height=\"343\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/147523471-1.png\" alt=\"Extra Report Pad : Tout l'Historique\" class=\"wp-image-7077\" style=\"width:814px;height:auto\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/147523471-1.png 758w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/147523471-1-500x226.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/147523471-1-300x136.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/147523471-1-150x68.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/147523471-1-700x317.png 700w\" sizes=\"(max-width:767px) 700px, 758px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-taille-de-la-police-minimiser-et-fermer-le-panneau-parametres\">Taille de la Police, Minimiser et Fermer le Panneau. Param\u00e8tres<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"528\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48-1200x528.png\" alt=\"Extra Report Pad : Taille de la Police, Minimiser et Fermer le Panneau. Param\u00e8tres\" class=\"wp-image-27179\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48-1200x528.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48-500x220.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48-300x132.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48-768x338.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48-150x66.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48-700x308.png 700w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-09-21_13-59-48.png 1533w\" sizes=\"(max-width:767px) 700px, (max-width:1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez changer la taille de la police pour le panneau directement sur le panneau lui-m\u00eame, ainsi que r\u00e9duire et fermer le panneau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Langues disponibles<\/strong> : Anglais, Ukrainien, Portugais, Espagnol, Italien, Fran\u00e7ais, Allemand, Chinois, Japonais, Cor\u00e9en et Turc.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-filtres\">Filtres<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Filtrer par Symbole<\/strong>;<\/li>\n\n\n\n<li><strong>Filtrer par Date<\/strong>;<\/li>\n\n\n\n<li><strong>Filtrer par Magic<\/strong>;<\/li>\n\n\n\n<li><strong>Filtrer par Commentaire<\/strong>.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Dans chaque onglet, vous pouvez filtrer les statistiques par disponibilit\u00e9, historique, paires de devises, mois de trading et num\u00e9ro magique. De plus, vous pouvez utiliser Date Personnalis\u00e9e et Commentaire Personnalis\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1301\" height=\"241\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22.png\" alt=\"Extra Report Pad : Filtres\" class=\"wp-image-70450\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22.png 1301w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22-500x93.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22-1200x222.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22-300x56.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22-768x142.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22-150x28.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-04-22-700x130.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1301px) 100vw, 1301px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-onglet-trades\">Onglet TRADES<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cet onglet affiche les transactions actuellement ouvertes, et dans les variables externes, vous pouvez s\u00e9lectionner les types de colonnes \u00e0 afficher.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il y a 21 colonnes disponibles pour afficher les statistiques<\/strong>.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Column_Number<\/strong> &#8211; Affiche le num\u00e9ro de s\u00e9quence de la transaction dans le rapport ;<\/li>\n\n\n\n<li><strong>Column_Symbol<\/strong> &#8211; Affiche la paire de devises de la transaction ;<\/li>\n\n\n\n<li><strong>Column_Type<\/strong> &#8211; Affiche le type d&#8217;ordre [Quel stop a \u00e9t\u00e9 d\u00e9clench\u00e9 sur cette transaction] ;<\/li>\n\n\n\n<li><strong>Column_Lot<\/strong> &#8211; Affiche le LOT de la transaction (position) ;<\/li>\n\n\n\n<li><strong>Column_OpenTime<\/strong> &#8211; Indique l&#8217;heure d&#8217;ouverture de la transaction ;<\/li>\n\n\n\n<li><strong>Column_OpenPrice<\/strong> &#8211; Indique le prix d&#8217;ouverture de la transaction ;<\/li>\n\n\n\n<li><strong>Column_CloseTime<\/strong> &#8211; Indique l&#8217;heure de fermeture de la transaction ;<\/li>\n\n\n\n<li><strong>Column_TimeBetween<\/strong> &#8211; Affiche le temps de maintien de la transaction en heures et minutes ;<\/li>\n\n\n\n<li><strong>Column_ClosePrice<\/strong> &#8211; Indique le prix de fermeture de la transaction ;<\/li>\n\n\n\n<li><strong>Column_SL<\/strong> &#8211; Indique le stop loss de la transaction (mis en \u00e9vidence si la transaction a \u00e9t\u00e9 ferm\u00e9e au stop loss) ;<\/li>\n\n\n\n<li><strong>Column_TP<\/strong> &#8211; Affiche le take profit de la transaction (mis en \u00e9vidence si la transaction a \u00e9t\u00e9 ferm\u00e9e au take profit) ;<\/li>\n\n\n\n<li><strong>Column_Commission<\/strong> &#8211; Affiche la commission de la transaction (position) ;<\/li>\n\n\n\n<li><strong>Column_Swap<\/strong> &#8211; Affiche le swap de la transaction (position) ;<\/li>\n\n\n\n<li><strong>Column_Profit<\/strong> &#8211; Affiche le r\u00e9sultat de la transaction dans la devise du d\u00e9p\u00f4t ;<\/li>\n\n\n\n<li><strong>Column_Points<\/strong> &#8211; Affiche le r\u00e9sultat de la transaction en points (pips) ;<\/li>\n\n\n\n<li><strong>Column_NetProfit<\/strong> &#8211; Affiche le profit net (profit net = Profit + Swap + Commission) ;<\/li>\n\n\n\n<li><strong>Column_Percent<\/strong> &#8211; Indique le pourcentage du profit net par rapport au solde au moment de la fermeture de la transaction ;<\/li>\n\n\n\n<li><strong>Column_Magic<\/strong> &#8211; Affiche le num\u00e9ro magique de la transaction ;<\/li>\n\n\n\n<li><strong>Column_Comment<\/strong> &#8211; Affiche le commentaire de la transaction (position) ;<\/li>\n\n\n\n<li><strong>Column_Balance<\/strong> &#8211; Affiche le solde obtenu apr\u00e8s la fermeture de la transaction ;<\/li>\n\n\n\n<li><strong>Column_Max<\/strong> &#8211; Indique la d\u00e9viation maximale du prix de la transaction dans la devise du d\u00e9p\u00f4t ;<\/li>\n\n\n\n<li><strong>Column_Min<\/strong> &#8211; Indique la d\u00e9viation minimale du prix dans la devise du d\u00e9p\u00f4t ;<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veuillez noter !<\/strong> Les param\u00e8tres <strong>Column_Max<\/strong> et <strong>Column_Min<\/strong> montrent le profit maximal et minimal dans la devise du d\u00e9p\u00f4t. L&#8217;analyse est effectu\u00e9e en trouvant les barres minutes de la paire de devises. Pour des donn\u00e9es plus pr\u00e9cises, vous devez t\u00e9l\u00e9charger tout l&#8217;historique du graphique M1 pour la paire de devises.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1311\" height=\"701\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29.png\" alt=\"Extra Report Pad : Il y a 21 colonnes disponibles pour afficher les statistiques\" class=\"wp-image-70474\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29.png 1311w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29-500x267.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29-1200x642.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29-300x160.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29-768x411.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29-140x75.png 140w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-06-29-700x374.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1311px) 100vw, 1311px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Ici, vous pouvez \u00e9galement filtrer les transactions par <strong>MagicNumber<\/strong> &#8211; <strong>Magics<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En bas de cet onglet, vous avez la possibilit\u00e9 de masquer certaines paires de devises et dates des statistiques. Pour ce faire, cliquez sur la case \u00e0 cocher \u00e0 c\u00f4t\u00e9 du nom.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Important !<\/strong> Vous devez d\u00e9cocher (retirer la coche de) les cases <strong>AllSymbols<\/strong> ou <strong>AllDates<\/strong> pour filtrer par dates ou paires de devises sp\u00e9cifiques (symboles).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-history-onglet\"><strong>HISTORY<\/strong> Onglet<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cet onglet affiche les transactions ferm\u00e9es de l&#8217;historique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les colonnes et leur visibilit\u00e9 peuvent \u00e9galement \u00eatre ajust\u00e9es dans les param\u00e8tres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Identique \u00e0 l&#8217;onglet TRADES.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1311\" height=\"701\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51.png\" alt=\"Extra Report Pad : Onglet Historique\" class=\"wp-image-70462\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51.png 1311w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51-500x267.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51-1200x642.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51-300x160.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51-768x411.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51-140x75.png 140w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-05-51-700x374.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1311px) 100vw, 1311px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez \u00e9galement faire d\u00e9filer les pages de statistiques si le nombre de transactions ne tient pas \u00e0 l&#8217;\u00e9cran.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1311\" height=\"701\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09.png\" alt=\"Extra Report Pad : Filtres dans l'Onglet Historique\" class=\"wp-image-70486\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09.png 1311w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09-500x267.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09-1200x642.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09-300x160.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09-768x411.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09-140x75.png 140w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-09-700x374.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1311px) 100vw, 1311px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-toutes-les-transactions-onglet\"><strong>TOUTES LES TRANSACTIONS<\/strong> Onglet<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cet onglet affiche \u00e0 la fois les transactions ferm\u00e9es de l&#8217;historique et les transactions actuellement ouvertes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les noms des colonnes, ainsi que leur visibilit\u00e9, peuvent \u00e9galement \u00eatre ajust\u00e9s dans les param\u00e8tres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Similaire aux onglets TRADES et HISTORY.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1311\" height=\"701\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57.png\" alt=\"Extra Report Pad : Onglet Toutes les Transactions\" class=\"wp-image-70498\" style=\"object-fit:cover\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57.png 1311w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57-500x267.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57-1200x642.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57-300x160.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57-768x411.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57-140x75.png 140w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-07-57-700x374.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1311px) 100vw, 1311px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rapports-onglet\"><strong>RAPPORTS<\/strong> Onglet<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cet onglet affiche les statistiques d\u00e9taill\u00e9es totales de votre compte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es statistiques sont calcul\u00e9es en utilisant les formules exactes utilis\u00e9es dans le rapport MT4.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des donn\u00e9es suppl\u00e9mentaires sont \u00e9galement calcul\u00e9es en utilisant des formules provenant d&#8217;autres ressources (par exemple, MQL5).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutes les statistiques sont affich\u00e9es en temps r\u00e9el (les informations se mettent \u00e0 jour toutes les 10 secondes. Vous pouvez ajuster cela dans les param\u00e8tres).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1311\" height=\"701\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45.png\" alt=\"Extra Report Pad : Onglet Rapports\" class=\"wp-image-70510\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45.png 1311w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45-500x267.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45-1200x642.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45-300x160.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45-768x411.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45-140x75.png 140w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-08-45-700x374.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1311px) 100vw, 1311px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Vous pouvez filtrer les donn\u00e9es par symboles, magics, commentaires et dates de transaction :<\/p>\n<\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1311\" height=\"701\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23.png\" alt=\"Extra Report Pad : Filtres dans l'Onglet Rapports\" class=\"wp-image-70522\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23.png 1311w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23-500x267.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23-1200x642.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23-300x160.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23-768x411.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23-140x75.png 140w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-23-700x374.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1311px) 100vw, 1311px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cet onglet affiche les statistiques de base suivantes :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Profit Brut<\/strong> &#8211; Profit total, la somme des profits de toutes les transactions rentables ;<\/li>\n\n\n\n<li><strong>Perte Brute<\/strong> &#8211; Perte totale, la somme des pertes de toutes les transactions perdantes ;<\/li>\n\n\n\n<li><strong>Profit Net Total<\/strong> &#8211; Profit net, montrant la diff\u00e9rence entre le profit total et la perte totale ;<\/li>\n\n\n\n<li><strong>PL des Transactions Ferm\u00e9es<\/strong> &#8211; Profit net des transactions ferm\u00e9es ;<\/li>\n\n\n\n<li><strong>PL Flottant<\/strong> &#8211; Profit net des transactions actuellement ouvertes ;<\/li>\n\n\n\n<li><strong>Marge<\/strong> &#8211; La marge actuellement utilis\u00e9e ;<\/li>\n\n\n\n<li><strong>SOLDE<\/strong> &#8211; Solde actuel du compte ;<\/li>\n\n\n\n<li><strong>Equit\u00e9<\/strong> &#8211; Fonds actuellement disponibles ;<\/li>\n\n\n\n<li><strong>Marge Libre<\/strong> &#8211; Marge libre actuelle disponible sur le compte de trading ;<\/li>\n\n\n\n<li><strong>Facteur de Profit<\/strong> &#8211; Ratio de rentabilit\u00e9 entre le profit total et la perte totale ;<\/li>\n\n\n\n<li><strong>Payoff Attendu<\/strong> &#8211; L&#8217;esp\u00e9rance math\u00e9matique du gain, calcul\u00e9e en utilisant la formule suivante ;<\/li>\n\n\n\n<li><strong>Facteur de R\u00e9cup\u00e9ration<\/strong> &#8211; Calcul\u00e9 comme le ratio du profit absolu au drawdown maximal. Plus le facteur de r\u00e9cup\u00e9ration est \u00e9lev\u00e9, plus le syst\u00e8me se r\u00e9tablit rapidement apr\u00e8s un drawdown ;<\/li>\n\n\n\n<li><strong>Drawdown Absolu<\/strong> &#8211; La diff\u00e9rence entre le d\u00e9p\u00f4t initial et la valeur de solde la plus basse pendant le processus de test ;<\/li>\n\n\n\n<li><strong>DrawDown Maximal<\/strong> &#8211; Max de (Pic Maximal &#8211; Pic Minimal suivant) ;<\/li>\n\n\n\n<li>Le pourcentage de drawdown maximal montre le ratio du drawdown maximal par rapport \u00e0 la valeur de l&#8217;extr\u00eame locale sup\u00e9rieure correspondante ;<\/li>\n\n\n\n<li><strong>MaxDrawDown%<\/strong> &#8211; (MaxDrawDown \/ MaxPeak) * 100% ;<\/li>\n\n\n\n<li><strong>Total des Transactions<\/strong> &#8211; Le nombre total de transactions effectu\u00e9es par un expert pendant le processus de test ;<\/li>\n\n\n\n<li><strong>Positions Courtes (Gagn\u00e9es%)<\/strong> &#8211; Nombre total de positions courtes (transactions) et le pourcentage de positions courtes rentables (Positions Courtes Rentables \/ Positions Courtes Totales * 100%) ;<\/li>\n\n\n\n<li><strong>Positions Longues (Gagn\u00e9es%)<\/strong> &#8211; Nombre total de positions longues et le pourcentage de positions longues rentables (Positions Longues Rentables \/ Positions Longues Totales * 100%) ;<\/li>\n\n\n\n<li><strong>Transactions Rentables (% du Total)<\/strong> &#8211; Nombre total de transactions rentables et le pourcentage du nombre total de transactions (ProfitTrades \/ TotalTrades * 100%) ;<\/li>\n\n\n\n<li><strong>Transactions Perdues (% du Total)<\/strong> &#8211; Nombre total de transactions perdantes et le pourcentage du nombre total de transactions (LossTrades \/ TotalTrades * 100%) ;<\/li>\n\n\n\n<li><strong>Plus Grande Transaction Rentable<\/strong> &#8211; Le plus grand profit parmi les transactions rentables ;<\/li>\n\n\n\n<li><strong>Plus Grande Transaction Perdue<\/strong> &#8211; La plus grande perte parmi les transactions perdantes ;<\/li>\n\n\n\n<li><strong>Profit Moyen par Transaction Rentable<\/strong> &#8211; Le profit moyen des transactions rentables (GrossProfit \/ ProfitTrades) ;<\/li>\n\n\n\n<li><strong>Perte Moyenne par Transaction Perdue<\/strong> &#8211; La perte moyenne des transactions perdantes (GrossLoss \/ LossTrades) ;<\/li>\n\n\n\n<li><strong>Maximum de Gains Cons\u00e9cutifs<\/strong> (profit en argent) &#8211; Le nombre maximum de transactions rentables cons\u00e9cutives et le profit total de cette s\u00e9rie ;<\/li>\n\n\n\n<li><strong>Maximum de Pertes Cons\u00e9cutives<\/strong> (perte en argent) &#8211; Le nombre maximum de transactions perdantes cons\u00e9cutives et la perte totale de cette s\u00e9rie ;<\/li>\n\n\n\n<li><strong>Profit Cons\u00e9cutif Maximal<\/strong> (nombre de gains) &#8211; Le profit maximal d&#8217;une s\u00e9rie continue de transactions rentables et le nombre de transactions dans cette s\u00e9rie ;<\/li>\n\n\n\n<li><strong>Perte Cons\u00e9cutive Maximale<\/strong> (nombre de pertes) &#8211; La perte maximale d&#8217;une s\u00e9rie continue de transactions perdantes et le nombre de transactions dans cette s\u00e9rie ;<\/li>\n\n\n\n<li><strong>Gains Cons\u00e9cutifs Moyens<\/strong> &#8211; Le nombre moyen de transactions dans une s\u00e9rie continue de gains rentables ;<\/li>\n\n\n\n<li><strong>Pertes Cons\u00e9cutives Moyennes<\/strong> &#8211; Le nombre moyen de transactions dans une s\u00e9rie continue de pertes.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-onglet-graphique\">Onglet Graphique<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ci-dessous, un graphique montrant l&#8217;\u00e9volution du solde.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1311\" height=\"701\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55.png\" alt=\"Extra Report Pad : Onglet Graphique\" class=\"wp-image-70534\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55.png 1311w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55-500x267.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55-1200x642.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55-300x160.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55-768x411.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55-140x75.png 140w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-09-55-700x374.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1311px) 100vw, 1311px\" \/><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Attention !<\/strong> Toutes les donn\u00e9es sont redessin\u00e9es si vous changez les filtres par symboles, commentaires, num\u00e9ros magiques ou mois de transaction !<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez le voir s\u00e9par\u00e9ment pour chaque paire de devises,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cochez la case correspondante, et les donn\u00e9es seront analys\u00e9es pour la paire de devises s\u00e9lectionn\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-onglet-distribution\">Onglet DISTRIBUTION<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cet onglet montre la distribution des transactions par paires de devises et profit\/perte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier bloc montre le nombre de transactions ferm\u00e9es : transactions ACHAT et transactions VENTE. Dans chaque cat\u00e9gorie, il affiche le nombre de transactions rentables.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"433\" height=\"183\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-57.png\" alt=\"Extra Report Pad : Onglet Distribution\" class=\"wp-image-70558\" style=\"width:554px;height:auto\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-57.png 433w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-57-300x127.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-57-150x63.png 150w\" sizes=\"(max-width:767px) 433px, 433px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le deuxi\u00e8me bloc montre les transactions rentables dans la devise du d\u00e9p\u00f4t pour ACHAT et VENTE s\u00e9par\u00e9ment, et affiche \u00e9galement le lot total des transactions rentables ACHAT et VENTE.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"359\" height=\"166\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-06.png\" alt=\"Extra Report Pad : Distribution par Symbole\" class=\"wp-image-70570\" style=\"width:544px;height:auto\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-06.png 359w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-06-300x139.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-06-150x69.png 150w\" sizes=\"(max-width:767px) 359px, 359px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le troisi\u00e8me bloc montre les transactions non rentables dans la devise du d\u00e9p\u00f4t pour ACHAT et VENTE s\u00e9par\u00e9ment, et affiche \u00e9galement le lot total des transactions perdues dans les transactions ACHAT et VENTE.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"356\" height=\"165\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-14.png\" alt=\"Extra Report Pad : Distribution par Symbole 2\" class=\"wp-image-70582\" style=\"width:544px;height:auto\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-14.png 356w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-14-300x139.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-11-14-150x70.png 150w\" sizes=\"(max-width:767px) 356px, 356px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-onglet-symboles-magics-commentaires\">Onglet Symboles, Magics, Commentaires<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ces onglets affichent les donn\u00e9es totales par symboles, num\u00e9ros magiques et commentaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1292\" height=\"283\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1.png\" alt=\"Extra Report Pad : Onglet Symboles, Magics, Commentaires\" class=\"wp-image-70606\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1.png 1292w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1-500x110.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1-1200x263.png 1200w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1-300x66.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1-768x168.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1-150x33.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-10-25-1-700x153.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1292px) 100vw, 1292px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1172\" height=\"822\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-12-14.png\" alt=\"Extra Report Pad : Onglet Symboles, Magics, Commentaires 2\" class=\"wp-image-70594\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-12-14.png 1172w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-12-14-500x351.png 500w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-12-14-300x210.png 300w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-12-14-768x539.png 768w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-12-14-107x75.png 107w, https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/2024-11-15_11-12-14-700x491.png 700w\" sizes=\"(max-width:767px) 700px, (max-width:1172px) 100vw, 1172px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"202\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s801922861.jpg\" alt=\"\" class=\"wp-image-7092\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s801922861.jpg 800w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s801922861-500x126.jpg 500w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s801922861-300x76.jpg 300w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s801922861-768x194.jpg 768w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s801922861-150x38.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2024\/02\/s801922861-700x177.jpg 700w\" sizes=\"(max-width:767px) 700px, (max-width:800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusions\">Conclusions<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;indicateur <strong>Extra Report Pad<\/strong> pour l&#8217;analyse des donn\u00e9es statistiques du compte de trading s&#8217;est av\u00e9r\u00e9 tr\u00e8s pratique \u00e0 utiliser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Expforex, Vladon, Rapport, Statistiques, MyFxBook, Journal de Trading, Analyse de Compte, FxStat, Statistiques de Performance, Analytique, Analyser Votre Syst\u00e8me de Trading, Tableau de Bord Innovant.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons mis beaucoup d&#8217;efforts dans son d\u00e9veloppement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Extra Report Pad<\/strong> est meilleur que <strong>MyFxBook<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">L&#8217;<strong>indicateur d&#8217;analyse des donn\u00e9es statistiques du compte de trading<\/strong> est tr\u00e8s pratique \u00e0 utiliser apr\u00e8s que nous ayons mis beaucoup d&#8217;efforts dans son d\u00e9veloppement. <strong>Extra Report Pad<\/strong> est meilleur que <strong>MyFxBook<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez t\u00e9l\u00e9charger mon indicateur dans la section Fichiers !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci d&#8217;avoir lu l&#8217;article jusqu&#8217;\u00e0 la fin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez remercier l&#8217;auteur pour ce projet, vous pouvez cliquer sur le bouton <strong>Merci<\/strong> ou <a href=\"https:\/\/www.mql5.com\/fr\/users\/vladon\/seller\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>acheter un de nos produits<\/strong><\/a>.<\/p>\n<\/blockquote>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"3\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-variables-externes-et-parametres-d-extra-report-pad\">Variables externes et param\u00e8tres d&#8217;Extra Report Pad<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Param\u00e8tre<\/th><th>Description<\/th><\/tr><\/thead><tbody><tr><td><strong>AccountHolderName<\/strong><\/td><td>D\u00e9finit si le nom du titulaire du compte doit \u00eatre affich\u00e9 dans le rapport HTML.\n            <ul>\n                <li><strong>false<\/strong> \u2014 Le nom du titulaire du compte ne sera pas affich\u00e9 en HTML.<\/li>\n                <li><strong>true<\/strong> \u2014 Le nom du titulaire du compte sera imprim\u00e9 dans le rapport.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>RewriteHTMLReport<\/strong><\/td><td>D\u00e9finit si le rapport HTML doit \u00eatre \u00e9cras\u00e9 lors de son enregistrement.\n            <ul>\n                <li><strong>false<\/strong> \u2014 Un nouveau rapport HTML est cr\u00e9\u00e9 avec des num\u00e9ros et des noms diff\u00e9rents \u00e0 chaque clic.<\/li>\n                <li><strong>true<\/strong> \u2014 Le rapport HTML est \u00e9cras\u00e9 \u00e0 chaque sauvegarde, rempla\u00e7ant l&#8217;ancien rapport par le nouveau.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>CreateImages<\/strong><\/td><td>Sp\u00e9cifie si des images doivent \u00eatre enregistr\u00e9es lors de la g\u00e9n\u00e9ration du rapport HTML.\n            <ul>\n                <li><strong>false<\/strong> \u2014 Les images ne seront pas cr\u00e9\u00e9es ou enregistr\u00e9es dans le rapport HTML.<\/li>\n                <li><strong>true<\/strong> \u2014 Les images seront cr\u00e9\u00e9es et enregistr\u00e9es lors de la g\u00e9n\u00e9ration du HTML.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>DatesOfHistory<\/strong><\/td><td>D\u00e9finit la plage de dates de l&#8217;historique au format <strong>aaaa.mm.jj-aaaa.mm.jj<\/strong> pour g\u00e9n\u00e9rer les rapports.\n            <ul>\n                <li>Exemple : &#8220;2023.01.01-2023.12.31&#8221; \u2014 Le rapport couvrira les transactions du 1er janvier 2023 au 31 d\u00e9cembre 2023.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td colspan=\"2\"><strong>Param\u00e8tres d&#8217;affichage des colonnes<\/strong><\/td><\/tr><tr><td><strong>Column_Number<\/strong><\/td><td>Affiche ou masque le num\u00e9ro de position dans le tableau.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le num\u00e9ro de position sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le num\u00e9ro de position ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Symbol<\/strong><\/td><td>Sp\u00e9cifie si afficher le symbole de l&#8217;instrument financier (par exemple, EURUSD).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le symbole sera affich\u00e9 dans le rapport.<\/li>\n                <li><strong>false<\/strong> \u2014 Le symbole ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Type<\/strong><\/td><td>Affiche le type de transaction (BUY\/SELL).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le type de transaction sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le type de transaction ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_3Lot<\/strong><\/td><td>Sp\u00e9cifie si afficher la taille du lot de la position (par exemple, 0.1 lots).\n            <ul>\n                <li><strong>true<\/strong> \u2014 La taille du lot sera affich\u00e9e.<\/li>\n                <li><strong>false<\/strong> \u2014 La taille du lot ne sera pas affich\u00e9e.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_OpenTime<\/strong><\/td><td>Affiche l&#8217;heure d&#8217;ouverture de la position.\n            <ul>\n                <li><strong>true<\/strong> \u2014 L&#8217;heure d&#8217;ouverture sera affich\u00e9e.<\/li>\n                <li><strong>false<\/strong> \u2014 L&#8217;heure d&#8217;ouverture ne sera pas affich\u00e9e.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_OpenPrice<\/strong><\/td><td>Affiche le prix auquel la transaction a \u00e9t\u00e9 ouverte.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le prix d&#8217;ouverture sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le prix d&#8217;ouverture ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_CloseTime<\/strong><\/td><td>Sp\u00e9cifie si afficher l&#8217;heure de cl\u00f4ture de la transaction.\n            <ul>\n                <li><strong>true<\/strong> \u2014 L&#8217;heure de cl\u00f4ture sera affich\u00e9e.<\/li>\n                <li><strong>false<\/strong> \u2014 L&#8217;heure de cl\u00f4ture ne sera pas affich\u00e9e.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_TimeBetween<\/strong><\/td><td>Affiche l&#8217;intervalle de temps entre l&#8217;ouverture et la cl\u00f4ture d&#8217;une position.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le temps entre l&#8217;ouverture et la cl\u00f4ture sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 L&#8217;intervalle ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_ClosePrice<\/strong><\/td><td>Affiche le prix de cl\u00f4ture de la transaction.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le prix de cl\u00f4ture sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le prix de cl\u00f4ture ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_SL<\/strong><\/td><td>Sp\u00e9cifie si afficher le niveau de Stop Loss (SL).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le SL sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le SL ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_SLPoints<\/strong><\/td><td>Affiche le nombre de points pour le Stop Loss (SL).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Les points pour le SL seront affich\u00e9s.<\/li>\n                <li><strong>false<\/strong> \u2014 Les points pour le SL ne seront pas affich\u00e9s.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Show_SLCurency<\/strong><\/td><td>D\u00e9finit si afficher la devise du Stop Loss (SL).\n            <ul>\n                <li><strong>true<\/strong> \u2014 La devise du SL sera affich\u00e9e.<\/li>\n                <li><strong>false<\/strong> \u2014 La devise du SL ne sera pas affich\u00e9e.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_TP<\/strong><\/td><td>Sp\u00e9cifie si afficher le niveau de Take Profit (TP).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le TP sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le TP ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_TPPoints<\/strong><\/td><td>Affiche le nombre de points pour le Take Profit (TP).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Les points pour le TP seront affich\u00e9s.<\/li>\n                <li><strong>false<\/strong> \u2014 Les points pour le TP ne seront pas affich\u00e9s.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Show_TPCurency<\/strong><\/td><td>Sp\u00e9cifie si afficher la devise du Take Profit (TP).\n            <ul>\n                <li><strong>true<\/strong> \u2014 La devise du TP sera affich\u00e9e.<\/li>\n                <li><strong>false<\/strong> \u2014 La devise du TP ne sera pas affich\u00e9e.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_commission<\/strong><\/td><td>Montre si afficher la commission de la transaction.\n            <ul>\n                <li><strong>true<\/strong> \u2014 La commission sera affich\u00e9e.<\/li>\n                <li><strong>false<\/strong> \u2014 La commission ne sera pas affich\u00e9e.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Swap<\/strong><\/td><td>Sp\u00e9cifie si afficher les frais de swap (charges pour le maintien d&#8217;une position overnight).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Les swaps seront affich\u00e9s.<\/li>\n                <li><strong>false<\/strong> \u2014 Les swaps ne seront pas affich\u00e9s.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Profit<\/strong><\/td><td>Affiche le profit ou la perte pour la transaction.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le profit sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le profit ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Pos<\/strong><\/td><td>Sp\u00e9cifie si afficher la position.\n            <ul>\n                <li><strong>true<\/strong> \u2014 La position sera affich\u00e9e.<\/li>\n                <li><strong>false<\/strong> \u2014 La position ne sera pas affich\u00e9e.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_NetProfit<\/strong><\/td><td>Affiche le profit net de la transaction.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le profit net sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le profit net ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Percent<\/strong><\/td><td>Affiche le pourcentage de profit.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le pourcentage de profit sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le pourcentage de profit ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Magic<\/strong><\/td><td>Affiche le num\u00e9ro magique de la transaction (si utilis\u00e9).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le num\u00e9ro magique sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le num\u00e9ro magique ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Comment<\/strong><\/td><td>Affiche le commentaire sur la transaction (si disponible).\n            <ul>\n                <li><strong>true<\/strong> \u2014 Les commentaires seront affich\u00e9s.<\/li>\n                <li><strong>false<\/strong> \u2014 Les commentaires ne seront pas affich\u00e9s.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Balance<\/strong><\/td><td>Sp\u00e9cifie si afficher le solde du compte.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Le solde sera affich\u00e9.<\/li>\n                <li><strong>false<\/strong> \u2014 Le solde ne sera pas affich\u00e9.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>Column_Max<\/strong><\/td><td>D\u00e9finit la valeur maximale pour une colonne. Une valeur de 0 signifie pas de limite.<\/td><\/tr><tr><td><strong>Column_Min<\/strong><\/td><td>D\u00e9finit la valeur minimale pour une colonne. Une valeur de 0 signifie pas de limite.<\/td><\/tr><tr><td colspan=\"2\"><strong>Autres param\u00e8tres<\/strong><\/td><\/tr><tr><td><strong>FilterDepositByTime<\/strong><\/td><td>Ignore les d\u00e9p\u00f4ts lors du filtrage par temps.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Les d\u00e9p\u00f4ts seront exclus du filtre.<\/li>\n                <li><strong>false<\/strong> \u2014 Les d\u00e9p\u00f4ts seront inclus dans le filtre.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>FilterOnlyif2orMore<\/strong><\/td><td>Filtre les transactions uniquement s&#8217;il y en a 2 ou plus.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Seules les transactions avec 2 ou plus seront incluses dans le filtre.<\/li>\n                <li><strong>false<\/strong> \u2014 N&#8217;importe quel nombre de transactions sera inclus, m\u00eame s&#8217;il y en a moins de 2.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td colspan=\"2\"><strong>Param\u00e8tres de d\u00e9bogage<\/strong><\/td><\/tr><tr><td><strong>OrderHistoryFromTerminal<\/strong><\/td><td>Sp\u00e9cifie si charger l&#8217;historique des ordres depuis le terminal ou depuis la biblioth\u00e8que.\n            <ul>\n                <li><strong>true<\/strong> \u2014 L&#8217;historique sera charg\u00e9 depuis le terminal.<\/li>\n                <li><strong>false<\/strong> \u2014 L&#8217;historique sera charg\u00e9 depuis la biblioth\u00e8que.<\/li>\n            <\/ul>\n            <\/td><\/tr><tr><td><strong>UseFilters<\/strong><\/td><td>D\u00e9finit si utiliser les filtres ou les d\u00e9sactiver pour r\u00e9duire la charge sur la RAM et le CPU.\n            <ul>\n                <li><strong>true<\/strong> \u2014 Les filtres seront appliqu\u00e9s.<\/li>\n                <li><strong>false<\/strong> \u2014 Les filtres seront d\u00e9sactiv\u00e9s pour r\u00e9duire la charge du syst\u00e8me.<\/li>\n            <\/ul>\n            <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"4\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-questions-et-reponses-frequentes-sur-extra-report-pad\">Questions et r\u00e9ponses fr\u00e9quentes sur Extra Report Pad<\/h2>\n\n\n\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-3m9iu\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-3m9iu eb_animation eb___animated eb___fadeIn\"><div class=\"eb-infobox-3m9iu eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><img decoding=\"async\" class=\"eb-infobox-image\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/Expforex-FAQ.png\" alt=\"\"\/><\/div><\/div><div class=\"contents-wrapper\"><h6 class=\"title\">Notre FAQ g\u00e9n\u00e9rale<\/h6><p class=\"description\">R\u00e9ponses aux questions les plus populaires<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor hvr-pulse infobox-btn  hvr-pulse\" href=\"https:\/\/expforex.com\/fr\/?p=293\" target=\"_blank\" rel=\"noopener\">Click Me!<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;indicateur pour analyser les donn\u00e9es statistiques du compte de trading s&#8217;est av\u00e9r\u00e9 tr\u00e8s pratique \u00e0 utiliser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons consacr\u00e9 beaucoup d&#8217;efforts \u00e0 sa mise en \u0153uvre.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Merci d&#8217;avoir lu l&#8217;article jusqu&#8217;\u00e0 la fin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez t\u00e9l\u00e9charger mon indicateur dans la section Fichiers !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez remercier l&#8217;auteur de ce projet &#8211; vous pouvez cliquer sur le bouton Merci. <a href=\"https:\/\/www.mql5.com\/ru\/users\/vladon\/seller\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ou acheter l&#8217;un de nos produits<\/strong><\/a><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Qu&#8217;est-ce qu&#8217;Extra Report Pad ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br><strong>Extra Report Pad<\/strong> est un <strong>outil professionnel<\/strong> con\u00e7u pour <strong>analyser efficacement votre compte de trading<\/strong>. Il offre une analyse statistique compl\u00e8te en temps r\u00e9el, permettant aux traders de surveiller et d&#8217;\u00e9valuer leurs performances de trading avec une plus grande pr\u00e9cision par rapport aux outils standards comme <strong>MyFxBook<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Comment Extra Report Pad se compare-t-il \u00e0 MyFxBook ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br>Alors que <strong>MyFxBook<\/strong> fournit une analyse de graphique en direct pour les comptes de trading, <strong>Extra Report Pad<\/strong> offre des rapports <strong>HTML<\/strong> plus d\u00e9taill\u00e9s et contenant <strong>500% d&#8217;informations suppl\u00e9mentaires<\/strong>. Il n&#8217;analyse pas seulement les transactions ouvertes et ferm\u00e9es, mais fournit \u00e9galement des donn\u00e9es <strong>statistiques approfondies<\/strong> et des informations sur les <strong>performances mensuelles<\/strong>, en faisant un choix sup\u00e9rieur pour les traders professionnels.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Quels sont les principaux avantages d&#8217;utiliser Extra Report Pad ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br>Les principaux avantages d&#8217;<strong>Extra Report Pad<\/strong> incluent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Analyse en temps r\u00e9el :<\/strong> Fournit des statistiques et des donn\u00e9es \u00e0 jour.<\/li>\n\n\n\n<li><strong>Rapports complets :<\/strong> G\u00e9n\u00e8re des rapports d\u00e9taill\u00e9s avec des informations \u00e9tendues.<\/li>\n\n\n\n<li><strong>Personnalisation :<\/strong> Permet de filtrer par symboles, dates, num\u00e9ros magiques et commentaires.<\/li>\n\n\n\n<li><strong>Facilit\u00e9 d&#8217;utilisation :<\/strong> Int\u00e9gr\u00e9 dans le terminal MetaTrader pour un acc\u00e8s sans faille.<\/li>\n\n\n\n<li><strong>Statistiques am\u00e9lior\u00e9es :<\/strong> Offre une analyse plus approfondie par rapport aux rapports standards.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Comment puis-je exporter mes donn\u00e9es de trading en utilisant Extra Report Pad ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br><strong>Extra Report Pad<\/strong> vous permet d&#8217;exporter vos donn\u00e9es de trading aux formats <strong>HTML<\/strong> et <strong>CSV<\/strong>. En cliquant sur le bouton <strong>EXPORTER en HTML<\/strong>, vous pouvez g\u00e9n\u00e9rer un rapport d\u00e9taill\u00e9 filtr\u00e9 selon vos crit\u00e8res choisis (par exemple, paire de devises sp\u00e9cifique, num\u00e9ro magique ou mois). Les fichiers export\u00e9s sont enregistr\u00e9s dans le r\u00e9pertoire <strong>YOUR TERMINAL  MQL4  Files  EXTRAREPORTPAD<\/strong>, facilitant l&#8217;acc\u00e8s et la r\u00e9vision de vos performances de trading en dehors de la plateforme MetaTrader.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Quels types de filtres sont disponibles dans Extra Report Pad ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br><strong>Extra Report Pad<\/strong> offre plusieurs options de filtrage pour personnaliser votre analyse :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Filtrer par symbole :<\/strong> S\u00e9lectionnez des paires de devises sp\u00e9cifiques.<\/li>\n\n\n\n<li><strong>Filtrer par date :<\/strong> Choisissez des p\u00e9riodes de trading particuli\u00e8res.<\/li>\n\n\n\n<li><strong>Filtrer par Magic :<\/strong> Filtrer les transactions en fonction des num\u00e9ros magiques.<\/li>\n\n\n\n<li><strong>Filtrer par commentaire :<\/strong> Trier les transactions par commentaires.<\/li>\n\n\n\n<li><strong>Date et commentaire personnalis\u00e9s :<\/strong> Cr\u00e9ez des filtres personnalis\u00e9s pour une analyse plus pr\u00e9cise.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ces filtres aident \u00e0 isoler et examiner des aspects sp\u00e9cifiques de vos performances de trading.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Extra Report Pad peut-il g\u00e9rer plusieurs paires de devises simultan\u00e9ment ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br>Oui, <strong>Extra Report Pad<\/strong> est con\u00e7u pour g\u00e9rer et analyser plusieurs paires de devises simultan\u00e9ment. Il permet aux traders de surveiller plusieurs transactions sur diff\u00e9rentes paires \u00e0 la fois, ce qui le rend essentiel pour les strat\u00e9gies de trading modernes impliquant le trading de plusieurs devises simultan\u00e9ment. L&#8217;outil simplifie la complexit\u00e9 de la gestion de nombreuses transactions en fournissant des donn\u00e9es statistiques d\u00e9taill\u00e9es et organis\u00e9es.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"> <strong>Quelles sont les langues disponibles pour Extra Report Pad ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br><strong>Extra Report Pad<\/strong> prend en charge plusieurs langues pour r\u00e9pondre \u00e0 une base d&#8217;utilisateurs diversifi\u00e9e. Les langues disponibles incluent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Anglais<\/li>\n\n\n\n<li>Ukrainien<\/li>\n\n\n\n<li>Portugais<\/li>\n\n\n\n<li>Espagnol<\/li>\n\n\n\n<li>Italien<\/li>\n\n\n\n<li>Fran\u00e7ais<\/li>\n\n\n\n<li>Allemand<\/li>\n\n\n\n<li>Chinois<\/li>\n\n\n\n<li>Japonais<\/li>\n\n\n\n<li>Cor\u00e9en<\/li>\n\n\n\n<li>Turc<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette prise en charge multilingue garantit que les traders de diverses r\u00e9gions peuvent utiliser l&#8217;outil efficacement.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Comment Extra Report Pad am\u00e9liore-t-il l&#8217;analyse des transactions par rapport aux rapports standards de MetaTrader ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br>Les rapports standards de <strong>MetaTrader<\/strong> manquent de donn\u00e9es d\u00e9taill\u00e9es sur les transactions individuelles, les paires de devises rentables et les statistiques mensuelles. <strong>Extra Report Pad<\/strong> r\u00e9pond \u00e0 ces limitations en fournissant :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Donn\u00e9es de transaction d\u00e9taill\u00e9es :<\/strong> Informations compl\u00e8tes sur chaque transaction, y compris les heures d&#8217;ouverture\/fermeture, les prix, les profits\/pertes, et plus encore.<\/li>\n\n\n\n<li><strong>Analyse mensuelle :<\/strong> D\u00e9compose les performances des transactions par mois pour une meilleure analyse des tendances.<\/li>\n\n\n\n<li><strong>Statistiques avanc\u00e9es :<\/strong> Calcule des m\u00e9triques telles que le facteur de profit, le facteur de r\u00e9cup\u00e9ration, les drawdowns, et plus encore.<\/li>\n\n\n\n<li><strong>Mises \u00e0 jour en temps r\u00e9el :<\/strong> Met \u00e0 jour continuellement les donn\u00e9es toutes les 10 secondes, garantissant que les traders disposent des derni\u00e8res informations.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces am\u00e9liorations permettent aux traders d&#8217;effectuer une analyse plus approfondie et professionnelle de leurs activit\u00e9s de trading.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"> <strong>Extra Report Pad est-il facile \u00e0 installer et \u00e0 int\u00e9grer avec MetaTrader ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br>Oui, <strong>Extra Report Pad<\/strong> est con\u00e7u pour une int\u00e9gration transparente avec le terminal <strong>MetaTrader<\/strong>. L&#8217;installation consiste \u00e0 placer les fichiers de l&#8217;indicateur dans le r\u00e9pertoire <strong>MQL4(5)  Indicators<\/strong>. Une fois install\u00e9, l&#8217;outil appara\u00eet comme un panneau int\u00e9gr\u00e9 dans MetaTrader, permettant un acc\u00e8s facile \u00e0 toutes ses fonctionnalit\u00e9s sans perturber votre flux de travail de trading.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Quel support et quelles ressources sont disponibles pour les utilisateurs d&#8217;Extra Report Pad ?<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9ponse :<\/strong><br>Les utilisateurs d&#8217;<strong>Extra Report Pad<\/strong> ont acc\u00e8s \u00e0 divers supports et ressources, y compris :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Documentation compl\u00e8te :<\/strong> Guides d\u00e9taill\u00e9s et instructions sur l&#8217;utilisation des fonctionnalit\u00e9s de l&#8217;indicateur.<\/li>\n\n\n\n<li><strong>Fichiers t\u00e9l\u00e9chargeables :<\/strong> Fichiers d&#8217;indicateur facilement accessibles disponibles dans la section <strong>Fichiers<\/strong>.<\/li>\n\n\n\n<li><strong>Support client :<\/strong> Assistance pour tout probl\u00e8me technique ou toute question.<\/li>\n\n\n\n<li><strong>Ressources communautaires :<\/strong> Liens vers des produits connexes et des outils suppl\u00e9mentaires tels que <strong>VIRTUALTRADEPAD<\/strong> et <strong>EAPADPRO<\/strong> pour une analyse de trading am\u00e9lior\u00e9e.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, les utilisateurs peuvent exprimer leur appr\u00e9ciation en cliquant sur le bouton <strong>Merci<\/strong> ou en achetant d&#8217;autres produits, favorisant une communaut\u00e9 de soutien autour de l&#8217;outil.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"5\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-journal-extra-report-pad\">Journal Extra Report Pad<\/h2>\n\n\n\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"6\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-avis-sur-extra-report-pad\">Avis sur Extra Report Pad<\/h2>\n\n\n\n<div class=\"wp-block-columns has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background has-medium-font-size is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<div class=\"wp-block-essential-blocks-icon  root-eb-icon-4o2mk\"><div class=\"eb-parent-wrapper eb-parent-eb-icon-4o2mk \"><div class=\"eb-icon-wrapper eb-icon-4o2mk eb-icon-view-default\" data-id=\"eb-icon-4o2mk\"><div class=\"eb-icon-container\"><i icon=\"fas fa-star\" class=\"fas fa-star \"><\/i><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-large-font-size is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p align=\"center\">Merci pour vos commentaires\u00a0!<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"javascript:complaintInline(22437715,31,3,0)\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><div class=\"testimonials_list \"><div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/expforex.com\/extrareportpad\/\">Vlad<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote><p>\u0421\u043f\u0430\u0441\u0438\u0431\u043e \u0437\u0430 \u0438\u043d\u0434\u0438\u043a\u0430\u0442\u043e\u0440! \u041f\u0440\u0435\u043c\u0438\u0430\u043b\u044c\u043d\u044b\u0439 \u0434\u0438\u0437\u0430\u043f\u0439\u043d \u0438 \u043e\u0447\u0435\u043d\u044c \u043c\u043e\u0449\u043d\u0430\u044f \u0441\u0442\u0430\u0442\u0441\u0438\u0442\u0438\u043a\u0430 !<br \/>\n\u042d\u0442\u043e  \u0442\u043e\u0442 \u043b\u0443\u0447\u0448\u0438\u0439 \u0438\u043d\u0434\u0438\u043a\u0430\u0442\u043e\u0440, \u043a\u043e\u0442\u043e\u044b\u0440\u0439 \u0434\u043e\u043b\u0436\u0435\u043d \u0431\u044b\u0442\u044c \u0443 \u043a\u0430\u0436\u0434\u043e\u0433\u043e \u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u0442\u0435\u043b\u044f \u0438 \u0442\u0440\u0435\u0439\u0434\u0435\u0440\u0430!!!<br \/>\n\u041c\u0435\u0433\u0430 \u0440\u0435\u0441\u043f\u0435\u043a\u0442<\/p>\n<div class=\"excr-testimonial-images\" style=\"margin:14px 0;text-align:center;display:flex;gap:10px;flex-wrap:wrap;justify-content:center\"><a href=\"https:\/\/expforex.com\/wp-content\/uploads\/expforex-comment-images\/extrareportpad\/2026\/06\/excr-7231-khI2eUBtxnCXPc.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/expforex-comment-images\/extrareportpad\/2026\/06\/excr-7231-khI2eUBtxnCXPc.png\" alt=\"2026-02-27_22-17-35.png\" loading=\"lazy\" style=\"max-width:220px;height:auto;border-radius:12px\"><\/a><\/div><hr><div style=\"text-align:center;margin:10px 0\"><img decoding=\"async\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/LOGONEW-2024-2.png\" alt=\"Vladislav Expforex\" width=\"60\" height=\"60\" loading=\"lazy\"><\/div><strong>Reply from ExpForex:<\/strong><br><p>\u0421\u043f\u0430\u0441\u0438\u0431\u043e \u0437\u0430 \u043e\u0442\u0437\u044b\u0432. \u041f\u0440\u0438\u044f\u0442\u043d\u043e \u0447\u0438\u0442\u0430\u0442\u044c \u043e\u0442\u0437\u044b\u0432\u044b \u043d\u0430 \u0441\u0432\u043e\u0438 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u043c\u044b. \u042d\u0442\u043e \u043c\u043e\u0442\u0438\u0432\u0438\u0440\u0443\u0435\u0442 \u0438 \u0434\u0430\u043b\u044c\u0448\u0435 \u0434\u0435\u043b\u0430\u0442\u044c \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u043e\u0431\u043d\u043e\u0432\u043b\u0435\u043d\u0438\u044f \u043f\u043e \u0432\u0441\u0435\u043c \u043c\u043e\u0438\u043c \u043f\u0440\u043e\u0435\u043a\u0442\u0430\u043c. <\/p>\n<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">Long Thanh Ho<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>One of the best trading tools out there to review your trading progress<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">Timmy T<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Easily the best reporting tool I've used<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png.webp 60w\" sizes=\"(max-width: 768px) 100vw, 1200px\"><img decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/12\/avatar_na2-4.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">sterh2019<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>\u041a\u0440\u0443\u0442\u0430\u044f \u0432\u0435\u0449\u044c. \u0414\u0430\u0436\u0435 \u043d\u0435 \u0437\u043d\u0430\u043b, \u0447\u0442\u043e \u0435\u0441\u0442\u044c \u043d\u0430\u0441\u0442\u043e\u043b\u044c\u043a\u043e \u043f\u043e\u043b\u044c\u043d\u044b\u0439 \u0438\u043d\u0441\u0442\u0440\u0443\u043c\u0435\u043d\u0442 \u0434\u043b\u044f \u0432\u0435\u0434\u0435\u043d\u0438\u044f \u0441\u0442\u0430\u0442\u0438\u0441\u0442\u0438\u043a\u0438, \u0434\u0430 \u0435\u0449\u0451 \u0438 \u0432 \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u043e\u0439 \u0432\u0435\u0440\u0441\u0438\u0438. \u0421\u043f\u0430\u0441\u0438\u0431\u043e \u0430\u0432\u0442\u043e\u0440\u0443.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/06\/67A3A0D6-9254_big-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Messages#!tab=reviews&#038;id=review_38531233\">Blazej Ornatowski<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Enormously useful report indicator, works perfectly on MT4, exactly what I needed. Thank you so much for such a fantastic reporting tool \ud83d\ude42<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/60601728-95C8_big-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">Andrey Tsygankov <\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>\u042d\u0442\u043e \u043b\u0443\u0447\u0448\u0435\u0435 \u043f\u0440\u0438\u043b\u043e\u0436\u0435\u043d\u0438\u0435 \u0434\u043b\u044f \u0441\u0431\u043e\u0440\u0430 \u0441\u0442\u0430\u0442\u0438\u0441\u0442\u0438\u043a\u0438 \u043f\u043e \u0441\u0447\u0435\u0442\u0443.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-75x75.jpg.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-150x150.jpg.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1.jpg.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1.jpg\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1.jpg 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-150x150.jpg 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/5DDD2FFC-40D5_big-1-75x75.jpg 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">Robert Torres Jr <\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>This indicator is amazing. It also has the max upside watermark and the lowest drawdown that was in profit per trade. Compare it to the actual profit or loss, then use an EA like Account Protector and tell it to take profit or stop loss at the average high watermark and stop loss at at the lowest above the largest drawdowns. It will increase your profits and mimimize your losses. just review your trades daily or weekly and you will find this tool invaluable. And the reports are far better than Metatraders. And it gives you a report analysis of all your trades with win and lose rate, profit ration, lowest overall drawdown, etc. You can also filter your trades by comment or magic number to get a drilled down deeper insight. Great job author!<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/663a55ad-bf12_big-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">Nikolay Fartuchnyy<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>\u041e\u0442\u043b\u0438\u0447\u043d\u044b\u0439 \u043f\u0440\u043e\u0434\u0443\u043a\u0442! \u041e\u0442\u0437\u044b\u0432\u0447\u0438\u0432\u044b\u0439 \u0430\u0432\u0442\u043e\u0440!<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/67C299B1-D7C4_big-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/15056?source=Site+Profile+Seller#!tab=reviews\">\u0410\u043d\u0434\u0440\u0435\u0439 \u041f\u0435\u0448\u043a\u043e\u0432<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Great job guys. Thanks and good luck with everything.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">PedroFerreira007<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Muito \u00fatil ! Obrigado ! ( apenas algumas d\u00favidas quanto ao filtro \"tempo\", pois poder\u00e1 depender dos hor\u00e1rios brooker e plataforma.. )<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">Brendan Wayne King<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Very good reporting tool - could I ask that in the Export to HTML Magics section to add the comments column? That way it makes it easier to correlate the magic number to the specific EA or trade comment without having to cross match them manually another way.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">FKMCapital <\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote><div class=\"text\">\r\n<div>\r\n<div id=\"reviewContentBlock_37313090\">\r\n\r\noverall good indicator, delivery valuable information. My only criticism is the CSV export can use some improvements or maybe change it to excel format where you can do much more, otherwise love it.\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div id=\"reviewSettings_37313090\" class=\"options\"><\/div>\r\n<div id=\"replies_37313090\" class=\"review_reply_list\">\r\n<div id=\"reply_235269\" class=\"review_reply\">\r\n<div class=\"user\">\r\n<div class=\"frame\">\r\n<div class=\"bg\"><img decoding=\"async\" title=\"Vladislav Andruschenko\" src=\"https:\/\/c.mql5.com\/avatar\/2023\/12\/658d9ef5-c3a3.png\" srcset=\"https:\/\/c.mql5.com\/avatar\/2023\/12\/658d9ef5-c3a3_big.png 2x\" alt=\"Vladislav Andruschenko\" width=\"60\" height=\"60\" \/><\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"review_reply__content\"><span class=\"review_reply__author\"><i class=\"icons-ux icons-ux_reply\"><\/i>Reply from developer\u00a0<strong><a class=\"author\" href=\"https:\/\/www.mql5.com\/en\/users\/vladon\">Vladislav\u00a0<\/a><\/strong><\/span>\r\n<div id=\"reviewReplyContentBlock_235269\" class=\"review_reply__description\">\"Thank you for your feedback! We're glad you find the indicator valuable. Regarding CSV export, MQL only supports CSV format, but it is specifically structured for Excel compatibility. You can easily open it in Excel and work with the data as needed. Let us know if you have any other suggestions!\"<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div><\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2025\/05\/avatar_na2_big-5-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730?source=Site+Profile+Seller#!tab=reviews\">Hung Vu<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>The indicator is very intuitive and detailed, suitable for synthesizing long-term performance Hopefully the author can add functions such as: deleting comments, magic number in the indicator's filter list (because after a long time the number will exceed the screen), creating a chart showing Equity\/Balance (profit\/loss) of the account over time in history.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730\">Childerich<\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Childerich \r\nGreat product! It\u2019s been very helpful and easy to use.<\/blockquote><\/div><\/div><\/div>\n<div class=\"item \"><div class=\"photo\"><div class=\"image_frame no_link scale-with-grid has_border\"><div class=\"image_wrapper\"><picture class=\"expfo-imgopt-picture\"><source type=\"image\/webp\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png.webp 75w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png.webp 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png.webp 200w\" sizes=\"(max-width:767px) 200px, 200px\"><img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png\" class=\"scale-with-grid wp-post-image\" alt=\"\" srcset=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1.png 200w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-150x150.png 150w, https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/avatar_na2_big1-75x75.png 75w\" sizes=\"(max-width:767px) 200px, 200px\" \/><\/picture><\/div><\/div><\/div><div class=\"desc\"><h4 class=\"title \"><a target=\"_blank\" href=\"https:\/\/www.mql5.com\/en\/market\/product\/36730\">Jcb Mlwijk <\/a><\/h4><p class=\"subtitle\">\u2b50\u2b50\u2b50\u2b50\u2b50<\/p><hr class=\"hr_color\" \/><div class=\"blockquote\"><span class=\"mfn-blockquote-icon\"><i class=\"icon-quote\" aria-hidden=\"true\"><\/i><\/span><blockquote>Jcb Mlwijk \r\nExcellent reporting functionality that provides you with detailed insights into their trading performance. The tool generates trade history reports, including key metrics such as profit\/loss analysis, drawdown, and risk exposure.<\/blockquote><\/div><\/div><\/div>\n<\/div>\n<a href=\"javascript:void(false);\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"javascript:complaintInline(8327451,31,3,0)\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"javascript:void(false);\"><\/a><a href=\"javascript:void(false);\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"javascript:complaintInline(10603778,31,3,0)\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"javascript:complaintInline(19098930,31,3,0)\"><\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"7\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-commentaires-sur-extra-report-pad\">Commentaires sur Extra Report Pad<\/h2>\n\n\n\n<div class=\"wp-block-columns has-electric-grass-gradient-background has-background has-medium-font-size is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<div class=\"wp-block-essential-blocks-icon  root-eb-icon-ih3ws\"><div class=\"eb-parent-wrapper eb-parent-eb-icon-ih3ws \"><div class=\"eb-icon-wrapper eb-icon-ih3ws eb-icon-view-default\" data-id=\"eb-icon-ih3ws\"><div class=\"eb-icon-container\"><i icon=\"fas fa-comment\" class=\"fas fa-comment \"><\/i><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-large-font-size is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p align=\"center\">Vous avez une question\u00a0?<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-comments has-white-background-color has-background\">\t<div id=\"respond\" class=\"comment-respond wp-block-post-comments-form\">\n\t\t<h3 id=\"reply-title\" class=\"comment-reply-title\">Leave a Reply <small><a rel=\"nofollow\" id=\"cancel-comment-reply-link\" href=\"\/fr\/wp-json\/wp\/v2\/posts\/70672#respond\" style=\"display:none;\">Cancel reply<\/a><\/small><\/h3><form action=\"https:\/\/expforex.com\/wp-comments-post.php\" method=\"post\" id=\"commentform\" class=\"comment-form\"><p class=\"comment-notes\"><span id=\"email-notes\">Your email address will not be published.<\/span> <span class=\"required-field-message\">Required fields are marked <span class=\"required\">*<\/span><\/span><\/p><p class=\"comment-form-comment\"><label for=\"comment\">Comment <span class=\"required\">*<\/span><\/label> <textarea id=\"comment\" name=\"comment\" cols=\"45\" rows=\"8\" maxlength=\"65525\" required=\"required\"><\/textarea><\/p><input name=\"wpml_language_code\" type=\"hidden\" value=\"fr\" \/><p class=\"comment-form-author\"><label for=\"author\">Name <span class=\"required\">*<\/span><\/label> <input id=\"author\" name=\"author\" type=\"text\" value=\"\" size=\"30\" maxlength=\"245\" autocomplete=\"name\" required=\"required\" \/><\/p>\n<p class=\"comment-form-email\"><label for=\"email\">Email <span class=\"required\">*<\/span><\/label> <input id=\"email\" name=\"email\" type=\"text\" value=\"\" size=\"30\" maxlength=\"100\" aria-describedby=\"email-notes\" autocomplete=\"email\" required=\"required\" \/><\/p>\n<p class=\"comment-form-url\"><label for=\"url\">Website<\/label> <input id=\"url\" name=\"url\" type=\"text\" value=\"\" size=\"30\" maxlength=\"200\" autocomplete=\"url\" \/><\/p>\n<p class=\"comment-form-cookies-consent\"><input id=\"wp-comment-cookies-consent\" name=\"wp-comment-cookies-consent\" type=\"checkbox\" value=\"yes\" \/> <label for=\"wp-comment-cookies-consent\">Save my name, email, and website in this browser for the next time I comment.<\/label><\/p>\n<div class=\"excap-field\" data-excap-context=\"wp-comment\"><input type=\"text\" name=\"excap_hp\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" aria-hidden=\"true\" class=\"excap-hp\" \/><input type=\"hidden\" name=\"excap_context\" value=\"wp-comment\" \/><input type=\"hidden\" name=\"excap_started\" value=\"1788368419\" \/><div id=\"excap-wp-comment-464368\" class=\"excap-widget cf-turnstile\" data-sitekey=\"0x4AAAAAABufDnsNvmIbBbxd\" data-action=\"wp-comment\" data-theme=\"auto\" data-size=\"normal\" data-language=\"auto\" data-appearance=\"always\"><\/div><\/div><p class=\"form-submit\"><input name=\"submit\" type=\"submit\" id=\"submit\" class=\"submit\" value=\"Post Comment\" \/> <input type='hidden' name='comment_post_ID' value='70672' id='comment_post_ID' \/>\n<input type='hidden' name='comment_parent' id='comment_parent' value='0' \/>\n<\/p><\/form>\t<\/div><!-- #respond -->\n\t\n\n\n\n\n\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"eb-tab-wrapper\" data-tab-id=\"8\" data-tab-parent-id=\"eb-advanced-tabs-b7hkfqw\"><div class=\"eb-tab-inner\">\n<h2 class=\"wp-block-heading\" id=\"h-extra\">Extra<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-articles-similaires\">Articles Similaires<\/h2>\n\n\n<div class=\"root-eb-post-carousel-15gwf wp-block-essential-blocks-post-carousel\">\n    <div class=\"eb-parent-wrapper eb-parent-eb-post-carousel-15gwf \">\n        <div class=\"eb-post-carousel-15gwf style-2 slick-arrows equal-height dot-style-1 eb-post-carousel-wrapper\"\n            data-id=\"eb-post-carousel-15gwf\"\n            data-querydata=\"a:14:{s:6:&quot;source&quot;;s:4:&quot;post&quot;;s:11:&quot;sourceIndex&quot;;i:0;s:9:&quot;rest_base&quot;;s:5:&quot;posts&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:6:&quot;author&quot;;s:0:&quot;&quot;;s:10:&quot;taxonomies&quot;;a:1:{s:8:&quot;category&quot;;a:5:{s:4:&quot;name&quot;;s:10:&quot;Categories&quot;;s:9:&quot;rest_base&quot;;s:10:&quot;categories&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:4:&quot;slug&quot;;s:8:&quot;category&quot;;s:5:&quot;value&quot;;s:32:&quot;[{&quot;value&quot;:7,&quot;label&quot;:&quot;Software&quot;}]&quot;;}}s:8:&quot;per_page&quot;;s:2:&quot;15&quot;;s:6:&quot;offset&quot;;s:1:&quot;0&quot;;s:7:&quot;orderby&quot;;s:4:&quot;rand&quot;;s:5:&quot;order&quot;;s:4:&quot;desc&quot;;s:7:&quot;include&quot;;s:2:&quot;[]&quot;;s:7:&quot;exclude&quot;;s:0:&quot;&quot;;s:15:&quot;exclude_current&quot;;b:1;s:26:&quot;exclude_password_protected&quot;;b:0;}\"\n            data-slidersettings=\"{&quot;arrows&quot;:true,&quot;dots&quot;:true,&quot;autoplaySpeed&quot;:4000,&quot;speed&quot;:700,&quot;adaptiveHeight&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:true,&quot;slideToShowRange&quot;:3,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-circle-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-circle-right&quot;,&quot;addIcon&quot;:false,&quot;showFallbackImg&quot;:false,&quot;fallbackImgUrl&quot;:&quot;&quot;,&quot;isRTLEnable&quot;:false,&quot;TABslideToShowRange&quot;:3,&quot;MOBslideToShowRange&quot;:3}\"\n            data-attributes=\"{&quot;preset&quot;:&quot;style-2&quot;,&quot;showThumbnail&quot;:true,&quot;showTitle&quot;:true,&quot;titleLength&quot;:&quot;10&quot;,&quot;titleTag&quot;:&quot;h4&quot;,&quot;showContent&quot;:true,&quot;contentLength&quot;:20,&quot;expansionIndicator&quot;:&quot;...&quot;,&quot;showReadMore&quot;:true,&quot;readmoreText&quot;:&quot;Read More&quot;,&quot;showMeta&quot;:false,&quot;headerMeta&quot;:&quot;[]&quot;,&quot;footerMeta&quot;:&quot;[]&quot;,&quot;authorPrefix&quot;:&quot;by&quot;,&quot;datePrefix&quot;:&quot;on&quot;,&quot;showBlockContent&quot;:true,&quot;showFeaturedPost&quot;:false,&quot;featuredPostId&quot;:&quot;&quot;,&quot;showFeaturedPostTitle&quot;:true,&quot;showFeaturedPostContent&quot;:false,&quot;showFeaturedPostMeta&quot;:true,&quot;showFeaturedHeaderMeta&quot;:true,&quot;showFeaturedFooterMeta&quot;:true,&quot;featuredMetaItems&quot;:&quot;{}&quot;,&quot;featuredExcerptLength&quot;:10,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-circle-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-circle-right&quot;,&quot;showFallbackImg&quot;:false,&quot;isRTLEnable&quot;:false}\">\n\n            <div class=\"eb-post-carousel init-eb-post-carousel-15gwf\"\n                data-id=\"eb-post-carousel-15gwf\">\n                <article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"78796\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/trade-statistics-of-ticksniper-and-the-best-advisors-from-expforex\/\">Rapport de trading de TickSniper et des conseillers d&#8217;Expforex<\/a>\n                    <img decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2017\/08\/23021312-1.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/trade-statistics-of-ticksniper-and-the-best-advisors-from-expforex\/\" title=\"rapportdetradingdeticksniperetdesconseillersdexpforex\">Rapport de trading de TickSniper et des conseillers d&#8217;Expforex<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Description\n\n\n\nNous avons r\u00e9sum\u00e9 les r\u00e9sultats de trading sommaires et d\u00e9taill\u00e9s de nos experts&nbsp;TickSniper,&nbsp;Good Santa,&nbsp;Tick Hamster,&nbsp;The X, sur nos comptes de&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/trade-statistics-of-ticksniper-and-the-best-advisors-from-expforex\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"77292\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/eapadpro\/\">EAPadPRO &#8211; Panneau d&#8217;information pour nos experts. Tableau de bord pour les Conseillers Experts<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/08\/logoEAPADPRO.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/eapadpro\/\" title=\"eapadpro-panneaudinformationpournosexpertstableaudebord\">EAPadPRO &#8211; Panneau d&#8217;information pour nos experts. Tableau de bord<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Panneau d&#8217;information pour tous nos conseillers et utilitaires pour le terminal MetaTrader.  \nInstructions d\u00e9taill\u00e9es sur les bases de la&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/eapadpro\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"71807\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/ticksniper\/\">TickSniper Expert Advisor Automatique pour MetaTrader. Scalpeur Tick<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/08\/TickSniper-MT45-2020.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/ticksniper\/\" title=\"ticksniperexpertadvisorautomatiquepourmetatraderscalpeurtick\">TickSniper Expert Advisor Automatique pour MetaTrader. Scalpeur Tick<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Exp-TickSniper est un scalpeur Tick rapide qui s\u00e9lectionne automatiquement les param\u00e8tres pour chaque paire de devises s\u00e9par\u00e9ment.\nL&#8217;EA a \u00e9t\u00e9 d\u00e9velopp\u00e9&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/ticksniper\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"70244\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/averager\/\">Averager. Moyennage des positions de trading. Ouverture de transactions contre la tendance et sur la tendance !<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_Averager-45.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/averager\/\" title=\"averagermoyennagedespositionsdetradingouverturedetransactionscontre\">Averager. Moyennage des positions de trading. Ouverture de transactions contre<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Moyennage des positions. Ouverture de positions suppl\u00e9mentaires sur la tendance et contre la tendance avec la fonction de stop suiveur&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/averager\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"69936\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/assistant\/\">Assistant &#8211; le meilleur panneau de trading gratuit pour supporter les positions et les transactions avec StopLoss \/ TakeProfit \/ Trailing Stop r\u00e9els\/virtuels<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_Assistant-45.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/assistant\/\" title=\"assistant-lemeilleurpanneaudetradinggratuitpoursupporter\">Assistant &#8211; le meilleur panneau de trading gratuit pour supporter<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Configuration automatique des stop loss, take profit, trailing stop, niveaux de breakeven, activation des stops virtuels.\n\nExp Assistant vous aidera \u00e0&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/assistant\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"74893\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/closeifprofitorloss\/\">CLP CloseIfProfitorLoss. Contr\u00f4le du profit ou de la perte totale avec profit suiveur.<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2020\/08\/NEWLOGO_ProfitorLoss-45.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/closeifprofitorloss\/\" title=\"clpcloseifprofitorlosscontrleduprofitoudelapertetotale\">CLP CloseIfProfitorLoss. Contr\u00f4le du profit ou de la perte totale<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>L&#8217;Expert Advisor (EA) offre des fonctionnalit\u00e9s avanc\u00e9es pour g\u00e9rer et fermer les positions sur MetaTrader, sp\u00e9cifiquement lorsqu&#8217;un niveau pr\u00e9d\u00e9termin\u00e9 de&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/closeifprofitorloss\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"66090\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/aisniper\/\">AI Sniper. Expert Advisor Intelligent et Automatique pour MetaTrader.<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2024\/06\/TickSniper-AI-MT45-2024-3.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/aisniper\/\" title=\"aisniperexpertadvisorintelligentetautomatiquepourmetatrader\">AI Sniper. Expert Advisor Intelligent et Automatique pour MetaTrader.<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>AI Sniper est un robot de trading intelligent et auto-optimisant con\u00e7u pour les terminaux MT4 et MT5. Il utilise un&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/aisniper\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"64584\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/virtualtradepad\/\">Panneau de trading VirtualTradePad (VTP). Trade Pad pour un trading en un clic \u00e0 partir d&#8217;un graphique et d&#8217;un clavier<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/08\/VirtualTradePAd_MT45_2020-1.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/virtualtradepad\/\" title=\"panneaudetradingvirtualtradepadvtptradepadpouruntrading\">Panneau de trading VirtualTradePad (VTP). Trade Pad pour un trading<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>VirtualTradePad ou VTP &#8211; panneau de contr\u00f4le pour le trading en un clic dans les terminaux MetaTrader. Le programme pour&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/virtualtradepad\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"173912\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/official-expforex-license-vs-cracked-version\/\">Licence officielle EXPFOREX vs versions crack\u00e9es : pourquoi un logiciel v\u00e9rifi\u00e9 est essentiel pour MT4 et MT5<\/a>\n                    <img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2026\/07\/expforex.com-Official-downloads-4-logo-Copy.png\" class=\"attachment-full size-full\" alt=\"expforex.com Official downloads 4 -logo\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/official-expforex-license-vs-cracked-version\/\" title=\"licenceofficielleexpforexvsversionscrackes:pourquoiunlogiciel\">Licence officielle EXPFOREX vs versions crack\u00e9es : pourquoi un logiciel<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Licence officielle EXPFOREX\n\n\n\nLicence officielle EXPFOREX vs versions crack\u00e9es : pourquoi un logiciel v\u00e9rifi\u00e9 est essentiel pour MT4 et MT5\n\n\n\nVotre environnement&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/official-expforex-license-vs-cracked-version\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"71426\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/testerpad\/\">Forex Tester Pad est un simulateur de trading pour le testeur de strat\u00e9gie. Trading avec indicateurs.<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2021\/08\/NEWLOGO_testerpad-ALL.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/testerpad\/\" title=\"forextesterpadestunsimulateurdetradingpourle\">Forex Tester Pad est un simulateur de trading pour le<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Trading en un clic sur le graphique du Testeur de Strat\u00e9gie. L&#8217;utilitaire vous permet de tester manuellement vos strat\u00e9gies dans&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/testerpad\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"78124\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/the-x-testing-and-optimization\/\">The X et The xCustomEA\u00a0: tests et optimisation<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2020\/07\/optimisationtesting.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/the-x-testing-and-optimization\/\" title=\"thexetthexcustomea:testsetoptimisation\">The X et The xCustomEA\u00a0: tests et optimisation<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Description\n\n\n\nThe X et The xCustomEA sont deux Experts Advisors (EAs) remarquables dans la communaut\u00e9 de trading Forex, gagnant en popularit\u00e9&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/the-x-testing-and-optimization\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"73876\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/thex\/\">The X &#8211; Conseiller Expert Universel (EA) pour le Forex Utilisant des Indicateurs Standards<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2020\/08\/TheX-MT45-2020.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/thex\/\" title=\"thex-conseillerexpertuniverseleapourleforex\">The X &#8211; Conseiller Expert Universel (EA) pour le Forex<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>Conseiller Expert Universel (EA) pour MetaTrader avec Fonctionnalit\u00e9s \u00c9tendues  \nLe Conseiller Expert The X est un outil de trading&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/thex\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"75327\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/safetylock\/\">SafetyLOCK PRO Prot\u00e9gez vos positions en utilisant des ordres en attente oppos\u00e9s. HEDGE<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2020\/08\/NEWLOGO_safetylock4.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/safetylock\/\" title=\"safetylockproprotgezvospositionsenutilisantdesordresen\">SafetyLOCK PRO Prot\u00e9gez vos positions en utilisant des ordres en<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>SAFETYLOCK : S\u00e9curisez vos transactions contre les fortes inversions de march\u00e9\nTrader sur les march\u00e9s financiers comporte des risques \u00e9lev\u00e9s, particuli\u00e8rement&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/safetylock\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"78210\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/swing\/\">Strat\u00e9gie Swing (Pendule). Ouverture automatique de 2 ordres en attente oppos\u00e9s, ordres OCO.<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2008\/12\/NEWLOGO_SWING-45-2019.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/swing\/\" title=\"stratgieswingpenduleouvertureautomatiquede2ordresenattente\">Strat\u00e9gie Swing (Pendule). Ouverture automatique de 2 ordres en attente<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>La strat\u00e9gie Pendule ou Swing implique l&#8217;ouverture s\u00e9quentielle d&#8217;ordres en attente avec une taille de lot augment\u00e9e. Le principe de&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/swing\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"63952\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-media\">\n                <div class=\"ebpg-entry-thumbnail\">\n                    <a class=\"ebpg-post-link-wrapper eb-sr-only\" href=\"https:\/\/expforex.com\/fr\/templates\/\">Mod\u00e8les MQL Open Source. Mod\u00e8le pour cr\u00e9er un Expert Advisor<\/a>\n                    <img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/expforex.com\/wp-content\/uploads\/2023\/12\/Exp-Templates-1.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n                <\/div>\n            <\/div><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/expforex.com\/fr\/templates\/\" title=\"modlesmqlopensourcemodlepourcrerunexpertadvisor\">Mod\u00e8les MQL Open Source. Mod\u00e8le pour cr\u00e9er un Expert Advisor<\/a>\n            <\/h4>\n        <\/header><div class=\"ebpg-entry-content\"><div class=\"ebpg-carousel-post-excerpt\">\n            <p>R\u00e9sum\u00e9\n\n\n\nCr\u00e9er des Conseillers Experts (EAs) pour tester votre strat\u00e9gie en utilisant n&#8217;importe quel indicateur peut en effet \u00eatre simplifi\u00e9 gr\u00e2ce&#8230;<\/p>\n        <\/div><div class=\"ebpg-readmore-btn\">\n            <a href=\"https:\/\/expforex.com\/fr\/templates\/\"> Read More <\/a>\n        <\/div><\/div><\/div><\/div><\/article>            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extra Report Pad &#8211; solution professionnelle pour analyser votre compte de trading<\/p>\n<p>Aujourd&#8217;hui, il est essentiel de trader simultan\u00e9ment plusieurs paires de devises. Mais plus il y a de transactions, plus il est difficile d&#8217;analyser la rentabilit\u00e9 de votre compte. Encore plus difficile d&#8217;analyser les transactions par mois. Et encore plus de calculer les donn\u00e9es statistiques pour chaque transaction s\u00e9par\u00e9ment.<\/p>\n<p>Nous avons trouv\u00e9 une solution : notre panneau peut analyser votre compte et compiler des statistiques avec le maximum de d\u00e9tails possible en temps r\u00e9el.<\/p>\n","protected":false},"author":2,"featured_media":70673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_eb_data_table":"","footnotes":"","_expseo_title":"Extra Report Pad Journal du Trader ou MyFxBook. Professionnel","_expseo_description":"Extra Report Pad est un outil professionnel pour analyser votre compte de trading. Journal du Trader analyse professionnellement votre compte de trading sur des graphiques en direct.","_expseo_canonical":"","_expseo_focus_keyword":"Extra Report Pad","_expseo_robots_noindex":"","_expseo_robots_nofollow":"","_expseo_robots_advanced":"","_expseo_breadcrumb_title":"","_expseo_og_title":"","_expseo_og_description":"","_expseo_og_image":"","_expseo_twitter_title":"","_expseo_twitter_description":"","_expseo_twitter_image":"","_expseo_schema_page_type":"","_expseo_schema_article_type":"","_expseo_schema_product_activator":""},"categories":[7],"tags":[6670,6728,6607,6649,6633,6713,6614,6750,6591,6584,6734,774,2288,6764,6743,6533,6758,6599,6558,2289,6682,344,6550,6621,940,6703,6568,6691,6697,6720,6677,6657,6642,6663,6577],"class_list":["post-70672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","tag-analyse-de-rentabilite","tag-analyse-des-donnees-en-temps-reel","tag-analyse-du-compte-de-negociation","tag-analyse-du-compte-metatrader","tag-analyse-forex-en-temps-reel","tag-analyse-multidevises","tag-analyse-professionnelle-du-marche-des-changes","tag-analyse-statistique-pour-les-traders","tag-bloc-notes-supplementaire","tag-commandes","tag-examen-du-compte-forex","tag-expforex","tag-expforex-fr","tag-gestionnaire-de-compte-forex","tag-indicateurs-de-performance-du-forex","tag-journal","tag-journal-de-bord-du-forex","tag-journal-du-commercant","tag-lanalyse","tag-marche-mql5","tag-moniteur-de-compte-forex","tag-myfxbook","tag-myfxbook-fr","tag-myfxbook-alternative-fr","tag-myfxbook-alternative","tag-outil-danalyse-du-forex","tag-rapport","tag-rapport-de-trading-mt4","tag-rapport-de-trading-mt5","tag-rentabilite-du-commerce-par-mois","tag-statistiques-detaillees-sur-les-echanges","tag-statistiques-sur-le-commerce-du-forex","tag-statistiques-sur-le-forex","tag-suivi-de-la-performance-des-transactions","tag-transactions"],"acf":{"metatrader4":"MT4","metatrader5":"MT5","type":"Meilleur GRATUIT","typebrief":"Rapport professionnel de compte de trading","mt4buy":"15056","mt5buy":"36730","typefreedemo":"FREE","downloadfreedemo":413,"DirectDownloadLink":"https:\/\/expforex.com\/?sdm_process_download=1&download_id=4177","versions":"23.999","version_date":"2023 12 12","postanotherid":"4177","direct5":"mql5buy:\/\/36730.Ind5+Extra+Report+Pad\/","direct4":"mql4buy:\/\/15056.Ind4+Extra+Report+Pad\/","testimonials_list":"","schema_name":"Extra Report Pad","schema_description":"","schema_type":"Utilities","schema_ratingValue":"4.74","schema_ratingCount":"83","schema_highPrice_MT4":"0.00","schema_rentprice_MT4":"0.00","schema_highPrice_MT5":"0.00","schema_rentprice_MT5":"0.00"},"_links":{"self":[{"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/posts\/70672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/comments?post=70672"}],"version-history":[{"count":1,"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/posts\/70672\/revisions"}],"predecessor-version":[{"id":172919,"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/posts\/70672\/revisions\/172919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/media\/70673"}],"wp:attachment":[{"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/media?parent=70672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/categories?post=70672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expforex.com\/fr\/wp-json\/wp\/v2\/tags?post=70672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}